{"id":5878,"date":"2021-01-25T15:12:19","date_gmt":"2021-01-25T15:12:19","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?publicaciones=una-llamada-de-emergencia"},"modified":"2024-03-20T17:44:42","modified_gmt":"2024-03-20T16:44:42","slug":"una-llamada-de-emergencia","status":"publish","type":"publicacion","link":"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/","title":{"rendered":"Una llamada de emergencia"},"content":{"rendered":"<p>Tras una d\u00e9cada en la que la cooperaci\u00f3n internacional ha perdido peso en Espa\u00f1a, este contexto de crisis muestra, hoy m\u00e1s que nunca, el papel que desempe\u00f1a como instrumento para no dejar a nadie atr\u00e1s. La solidaridad entre pa\u00edses, regiones y continentes no es opcional, sino m\u00e1s bien la \u00fanica v\u00eda que tiene el ser humano para afrontar una amenaza global que pone en peligro la vida de cualquier persona.<\/p>\n<p>Esta situaci\u00f3n excepcional pone a prueba esta solidaridad, pero tambi\u00e9n la globalizaci\u00f3n y los marcos internacionales que la gobiernan. Con la nueva Agenda Internacional de Desarrollo como l\u00ednea a seguir, el mundo debe organizarse, protegi\u00e9ndose unos a otros y colaborar, primero, para vencer el virus y, segundo, para garantizar que la brecha de la desigualdad no se vea ampliada.<\/p>\n<p>En este escenario es donde el Gobierno de Espa\u00f1a debe dar un paso adelante y reafirmar su compromiso con la cooperaci\u00f3n internacional en aquellos sectores que se han demostrado cruciales durante la crisis. Se deben poner en el centro de la agenda de la cooperaci\u00f3n espa\u00f1ola los servicios sociales b\u00e1sicos como la sanidad y la educaci\u00f3n.&nbsp;<\/p>\n<p>Desde Entreculturas y la Fundaci\u00f3n ETEA presentamos este documento que analiza la cooperaci\u00f3n de Espa\u00f1a en educaci\u00f3n. En este informe se muestran tantos las inversiones de la \u00faltima d\u00e9cada, como las caracter\u00edsticas de estas, as\u00ed como las diferencias entre Espa\u00f1a y otros pa\u00edses del entorno de la UE.<\/p>\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/01\/recuperarayudaeducacion_ec_enero2021.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">descargar<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tras una d\u00e9cada en la que la cooperaci\u00f3n internacional ha perdido peso en Espa\u00f1a, este contexto de crisis muestra, hoy m\u00e1s que nunca, el papel que desempe\u00f1a como instrumento para no dejar a nadie atr\u00e1s. La solidaridad entre pa\u00edses, regiones y continentes no es opcional, sino m\u00e1s bien la \u00fanica v\u00eda que tiene el ser humano para afrontar una amenaza global que pone en peligro la vida de cualquier persona. Esta situaci\u00f3n excepcional pone a prueba esta solidaridad, pero tambi\u00e9n la globalizaci\u00f3n y los marcos internacionales que la gobiernan. Con la nueva Agenda Internacional de Desarrollo como l\u00ednea a seguir, el mundo debe organizarse, protegi\u00e9ndose unos a otros y colaborar, primero, para vencer el virus y, segundo, para garantizar que la brecha de la desigualdad no se vea ampliada. En este escenario es donde el Gobierno de Espa\u00f1a debe dar un paso adelante y reafirmar su compromiso con la cooperaci\u00f3n [&hellip;]<\/p>\n","protected":false},"featured_media":5472,"template":"","format":[112],"categories":[18],"tags":[185],"cause":[128],"class_list":["post-5878","publicacion","type-publicacion","status-publish","has-post-thumbnail","hentry","category-estudios","tag-entreculturas","cause-educacion","format-estudios-e-informes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Una llamada de emergencia - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una llamada de emergencia\" \/>\n<meta property=\"og:description\" content=\"Tras una d\u00e9cada en la que la cooperaci\u00f3n internacional ha perdido peso en Espa\u00f1a, este contexto de crisis muestra, hoy m\u00e1s que nunca, el papel que desempe\u00f1a como instrumento para no dejar a nadie atr\u00e1s. La solidaridad entre pa\u00edses, regiones y continentes no es opcional, sino m\u00e1s bien la \u00fanica v\u00eda que tiene el ser humano para afrontar una amenaza global que pone en peligro la vida de cualquier persona. Esta situaci\u00f3n excepcional pone a prueba esta solidaridad, pero tambi\u00e9n la globalizaci\u00f3n y los marcos internacionales que la gobiernan. Con la nueva Agenda Internacional de Desarrollo como l\u00ednea a seguir, el mundo debe organizarse, protegi\u00e9ndose unos a otros y colaborar, primero, para vencer el virus y, segundo, para garantizar que la brecha de la desigualdad no se vea ampliada. En este escenario es donde el Gobierno de Espa\u00f1a debe dar un paso adelante y reafirmar su compromiso con la cooperaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T16:44:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/01\/portada-aod.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"706\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/publicacion\\\/una-llamada-de-emergencia\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/publicacion\\\/una-llamada-de-emergencia\\\/\",\"name\":\"Una llamada de emergencia - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/publicacion\\\/una-llamada-de-emergencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/publicacion\\\/una-llamada-de-emergencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/portada-aod.jpg\",\"datePublished\":\"2021-01-25T15:12:19+00:00\",\"dateModified\":\"2024-03-20T16:44:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/publicacion\\\/una-llamada-de-emergencia\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/publicacion\\\/una-llamada-de-emergencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/publicacion\\\/una-llamada-de-emergencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/portada-aod.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/portada-aod.jpg\",\"width\":706,\"height\":1000,\"caption\":\"portada-aod\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/publicacion\\\/una-llamada-de-emergencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publicaciones\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/publicaciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Una llamada de emergencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Una llamada de emergencia - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/","og_locale":"gl_ES","og_type":"article","og_title":"Una llamada de emergencia","og_description":"Tras una d\u00e9cada en la que la cooperaci\u00f3n internacional ha perdido peso en Espa\u00f1a, este contexto de crisis muestra, hoy m\u00e1s que nunca, el papel que desempe\u00f1a como instrumento para no dejar a nadie atr\u00e1s. La solidaridad entre pa\u00edses, regiones y continentes no es opcional, sino m\u00e1s bien la \u00fanica v\u00eda que tiene el ser humano para afrontar una amenaza global que pone en peligro la vida de cualquier persona. Esta situaci\u00f3n excepcional pone a prueba esta solidaridad, pero tambi\u00e9n la globalizaci\u00f3n y los marcos internacionales que la gobiernan. Con la nueva Agenda Internacional de Desarrollo como l\u00ednea a seguir, el mundo debe organizarse, protegi\u00e9ndose unos a otros y colaborar, primero, para vencer el virus y, segundo, para garantizar que la brecha de la desigualdad no se vea ampliada. En este escenario es donde el Gobierno de Espa\u00f1a debe dar un paso adelante y reafirmar su compromiso con la cooperaci\u00f3n [&hellip;]","og_url":"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-03-20T16:44:42+00:00","og_image":[{"width":706,"height":1000,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/01\/portada-aod.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/","url":"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/","name":"Una llamada de emergencia - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/01\/portada-aod.jpg","datePublished":"2021-01-25T15:12:19+00:00","dateModified":"2024-03-20T16:44:42+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/01\/portada-aod.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/01\/portada-aod.jpg","width":706,"height":1000,"caption":"portada-aod"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/gl\/publicacion\/una-llamada-de-emergencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Publicaciones","item":"https:\/\/www.entreculturas.org\/gl\/publicaciones\/"},{"@type":"ListItem","position":3,"name":"Una llamada de emergencia"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/gl\/#website","url":"https:\/\/www.entreculturas.org\/gl\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/gl\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/gl\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/publicacion\/5878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/publicacion"}],"about":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/types\/publicacion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media\/5472"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media?parent=5878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/categories?post=5878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/tags?post=5878"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/cause?post=5878"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/format?post=5878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}