{"id":9680,"date":"2021-12-27T10:55:42","date_gmt":"2021-12-27T09:55:42","guid":{"rendered":"https:\/\/www.entreculturas.org\/publicacion\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/"},"modified":"2024-09-17T13:36:40","modified_gmt":"2024-09-17T11:36:40","slug":"beatriz-isla-voluntaria-en-la-delegacion-de-cantabria","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/","title":{"rendered":"Beatriz Isla &#8211; voluntaria en la delegaci\u00f3n de Cantabria"},"content":{"rendered":"<p style=\"text-align: justify;\">Me llamo Bea, soy voluntaria &nbsp;de Entreculturas en la Delegaci\u00f3n de Cantabria desde su comienzo en 2003 cuando Entreculturas empieza su andadura en esta comunidad. Por aquel entonces se encomienda la tarea de llevar la delegaci\u00f3n a Ceferino Garc\u00eda (sj) que al mismo tiempo era director del Centro Loyola de Santander.&nbsp;En esos momentos a las personas que pertenec\u00edamos a&nbsp;los grupos de fe del Centro Loyola, se nos invit\u00f3&nbsp;a asumir una \u201cmisi\u00f3n\u201d personal participando como voluntarios activos en la delegaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Formar parte de Entreculturas para m\u00ed es una satisfacci\u00f3n y un reto personal.&nbsp;La delegaci\u00f3n comenz\u00f3 su actividad con mucha ilusi\u00f3n y ganas de colaborar con la sociedad c\u00e1ntabra en el conocimiento y resoluci\u00f3n de los problemas que a afectan &nbsp;a los pa\u00edses m\u00e1s empobrecidos para sensibilizarles con esa realidad y fomentar actividades para que el cambio a favor de la justicia fuera posible.&nbsp;Para ello tuvimos que conocer su identidad, y su forma de hacer pues se nos ofrec\u00eda una variedad de actividades: permanencia en la delegaci\u00f3n, relaci\u00f3n con empresas, atenci\u00f3n a los medios de comunicaci\u00f3n social, reparto de material a los centros educativos, ingresos de donativos en el banco, recogida de m\u00f3viles, coordinaci\u00f3n con otras entidades para la SAME, dar cuenta de los gastos de la delegaci\u00f3n, formaci\u00f3n y puesta en com\u00fan para fundamentar y consolidar las razones y motivos de la acci\u00f3n.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Somos conscientes de que nuestro peque\u00f1o aporte, grano de arena, tiene repercusi\u00f3n en aquellos pa\u00edses con los que trabajamos. Nos sentimos enviados a la misi\u00f3n, una misi\u00f3n compartida&nbsp;con los m\u00e1s desfavorecidos, queriendo defender el derecho a la educaci\u00f3n de calidad.&nbsp;A lo largo de estos 18 a\u00f1os la delegaci\u00f3n ha ido evolucionando seg\u00fan las necesidades y situaciones estructurales, sociales y personales que se han ido presentando hasta llegar al momento actual.<\/p>\n<p style=\"text-align: justify;\">Han pasando por la delegaci\u00f3n muchas personas que han dedicado su tiempo a Entreculturas&nbsp;colaborando en aquello que hiciera falta. Entre ellas quiero recordar a nuestra delegada Maripi, recientemente fallecida de forma inesperada por su entrega a la misi\u00f3n compartida. Nos sensibilizaba a todos y todas con la importancia de participar en los actos de la organizaci\u00f3n en la ciudad. Como dec\u00eda ella, hay que darse a conocer, sensibilizar a la gente y as\u00ed seremos capaces de crear un mundo m\u00e1s justo y solidario, creando oportunidades para todos y todas &nbsp;y trabajando&nbsp;por el Reino para amar y servir m\u00e1s a Dios, como dice San Ignacio.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Gracias Maripi por compartir misi\u00f3n, vida y fe con nosotros\u2026 Y tambi\u00e9n quiero dar las gracias a todos\/as los\/as voluntarios\/as de la delegaci\u00f3n por &nbsp;vuestra entrega, tiempo y compromiso. Gracias.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me llamo Bea, soy voluntaria &nbsp;de Entreculturas en la Delegaci\u00f3n de Cantabria desde su comienzo en 2003 cuando Entreculturas empieza su andadura en esta comunidad. Por aquel entonces se encomienda la tarea de llevar la delegaci\u00f3n a Ceferino Garc\u00eda (sj) que al mismo tiempo era director del Centro Loyola de Santander.&nbsp;En esos momentos a las personas que pertenec\u00edamos a&nbsp;los grupos de fe del Centro Loyola, se nos invit\u00f3&nbsp;a asumir una \u201cmisi\u00f3n\u201d personal participando como voluntarios activos en la delegaci\u00f3n. Formar parte de Entreculturas para m\u00ed es una satisfacci\u00f3n y un reto personal.&nbsp;La delegaci\u00f3n comenz\u00f3 su actividad con mucha ilusi\u00f3n y ganas de colaborar con la sociedad c\u00e1ntabra en el conocimiento y resoluci\u00f3n de los problemas que a afectan &nbsp;a los pa\u00edses m\u00e1s empobrecidos para sensibilizarles con esa realidad y fomentar actividades para que el cambio a favor de la justicia fuera posible.&nbsp;Para ello tuvimos que conocer su identidad, y su [&hellip;]<\/p>\n","protected":false},"featured_media":9681,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[191],"country":[],"cause":[],"class_list":["post-9680","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-voluntariado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Beatriz Isla - voluntaria en la delegaci\u00f3n de Cantabria - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beatriz Isla - voluntaria en la delegaci\u00f3n de Cantabria\" \/>\n<meta property=\"og:description\" content=\"Me llamo Bea, soy voluntaria &nbsp;de Entreculturas en la Delegaci\u00f3n de Cantabria desde su comienzo en 2003 cuando Entreculturas empieza su andadura en esta comunidad. Por aquel entonces se encomienda la tarea de llevar la delegaci\u00f3n a Ceferino Garc\u00eda (sj) que al mismo tiempo era director del Centro Loyola de Santander.&nbsp;En esos momentos a las personas que pertenec\u00edamos a&nbsp;los grupos de fe del Centro Loyola, se nos invit\u00f3&nbsp;a asumir una \u201cmisi\u00f3n\u201d personal participando como voluntarios activos en la delegaci\u00f3n. Formar parte de Entreculturas para m\u00ed es una satisfacci\u00f3n y un reto personal.&nbsp;La delegaci\u00f3n comenz\u00f3 su actividad con mucha ilusi\u00f3n y ganas de colaborar con la sociedad c\u00e1ntabra en el conocimiento y resoluci\u00f3n de los problemas que a afectan &nbsp;a los pa\u00edses m\u00e1s empobrecidos para sensibilizarles con esa realidad y fomentar actividades para que el cambio a favor de la justicia fuera posible.&nbsp;Para ello tuvimos que conocer su identidad, y su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T11:36:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2023\/12\/beatriz_isla-2-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"584\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\\\/\",\"name\":\"Beatriz Isla - voluntaria en la delegaci\u00f3n de Cantabria - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/beatriz_isla-2-2.jpg\",\"datePublished\":\"2021-12-27T09:55:42+00:00\",\"dateModified\":\"2024-09-17T11:36:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/beatriz_isla-2-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/beatriz_isla-2-2.jpg\",\"width\":500,\"height\":584},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beatriz Isla &#8211; voluntaria en la delegaci\u00f3n de Cantabria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Beatriz Isla - voluntaria en la delegaci\u00f3n de Cantabria - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/","og_locale":"gl_ES","og_type":"article","og_title":"Beatriz Isla - voluntaria en la delegaci\u00f3n de Cantabria","og_description":"Me llamo Bea, soy voluntaria &nbsp;de Entreculturas en la Delegaci\u00f3n de Cantabria desde su comienzo en 2003 cuando Entreculturas empieza su andadura en esta comunidad. Por aquel entonces se encomienda la tarea de llevar la delegaci\u00f3n a Ceferino Garc\u00eda (sj) que al mismo tiempo era director del Centro Loyola de Santander.&nbsp;En esos momentos a las personas que pertenec\u00edamos a&nbsp;los grupos de fe del Centro Loyola, se nos invit\u00f3&nbsp;a asumir una \u201cmisi\u00f3n\u201d personal participando como voluntarios activos en la delegaci\u00f3n. Formar parte de Entreculturas para m\u00ed es una satisfacci\u00f3n y un reto personal.&nbsp;La delegaci\u00f3n comenz\u00f3 su actividad con mucha ilusi\u00f3n y ganas de colaborar con la sociedad c\u00e1ntabra en el conocimiento y resoluci\u00f3n de los problemas que a afectan &nbsp;a los pa\u00edses m\u00e1s empobrecidos para sensibilizarles con esa realidad y fomentar actividades para que el cambio a favor de la justicia fuera posible.&nbsp;Para ello tuvimos que conocer su identidad, y su [&hellip;]","og_url":"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-09-17T11:36:40+00:00","og_image":[{"width":500,"height":584,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2023\/12\/beatriz_isla-2-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/","url":"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/","name":"Beatriz Isla - voluntaria en la delegaci\u00f3n de Cantabria - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2023\/12\/beatriz_isla-2-2.jpg","datePublished":"2021-12-27T09:55:42+00:00","dateModified":"2024-09-17T11:36:40+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2023\/12\/beatriz_isla-2-2.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2023\/12\/beatriz_isla-2-2.jpg","width":500,"height":584},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/beatriz-isla-voluntaria-en-la-delegacion-de-cantabria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/gl\/noticias\/"},{"@type":"ListItem","position":3,"name":"Beatriz Isla &#8211; voluntaria en la delegaci\u00f3n de Cantabria"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/gl\/#website","url":"https:\/\/www.entreculturas.org\/gl\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/gl\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/gl\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia\/9680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media\/9681"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media?parent=9680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/categories?post=9680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/tags?post=9680"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/country?post=9680"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/cause?post=9680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}