{"id":6552,"date":"2022-05-20T08:35:20","date_gmt":"2022-05-20T08:35:20","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso"},"modified":"2024-02-19T11:37:57","modified_gmt":"2024-02-19T10:37:57","slug":"el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/","title":{"rendered":"\u201cEl circuito  migratorio hacia el norte se ha vuelto cada vez m\u00e1s peligroso\u201d"},"content":{"rendered":"<\/p>\n<p>Soy Julio Villavicencio, soy sacerdote jesuita, Director del Servicio Jesuita a Migrantes (SJM) Argentina y Uruguay. El SJM de Argentina y Uruguay est\u00e1 dividido en \u00e1reas: tenemos el \u00e1rea social, de educaci\u00f3n, de Pastoral, de Incidencia y el \u00e1rea de medios de vida, que es nuestra \u00faltima apertura. Trabajamos para acompa\u00f1ar a las personas migrantes y refugiadas para su integraci\u00f3n, y tambi\u00e9n para la defensa y acceso a los derechos.<\/p>\n<p><span style=\"color:#FF0000\"><strong>Este&nbsp;proyecto se fund\u00f3 en&nbsp;2019&nbsp;a ra\u00edz del flujo venezolano, \u00bfpuedes comentarnos los inicios?<\/strong><\/span><br \/>El SJM&nbsp; en Argentina tiene un antecedente previo en 2005, pero que no llega a ser un Servicio Jesuita a Migrantes con la proporci\u00f3n que tenemos ahora. Oficialmente el SJM en Argentina y Uruguay se abre en el a\u00f1o 2019, un poco producto de la crisis humanitaria venezolana, que genera un gran flujo migratorio en toda Am\u00e9rica Latina, en toda la regi\u00f3n. En ese sentido, esta necesidad y la crisis dieron pie a poder abrir el SJM en Argentina y en Uruguay, pero a medida que fuimos avanzando en la problem\u00e1tica migratoria o acompa\u00f1ando a las personas en este proceso que tambi\u00e9n es de refugio, fuimos descubriendo muchas otras nacionalidades que estaban postergadas hist\u00f3ricamente, y que estamos tambi\u00e9n tratando de acompa\u00f1ar y aprender.<\/p>\n<p><span style=\"color:#FF0000\"><strong>\u00bfCu\u00e1les son los principales pa\u00edses de procedencia que est\u00e1is atendiendo?<\/strong><\/span><br \/>Principalmente Venezuela, y quiz\u00e1s le sigue en segundo lugar Colombia, sobre todo como producto de este recrudecimiento de la violencia dentro del pa\u00eds, que genera tambi\u00e9n una nueva ola de expulsi\u00f3n. Tambi\u00e9n lo que hace que la situaci\u00f3n o el circuito hacia el norte se haya vuelto cada vez m\u00e1s peligroso, y m\u00e1s dif\u00edcil el ingreso y el acceso, provoca ahora muchos flujos migratorios hacia el sur. De ah\u00ed que tambi\u00e9n haya mucha migraci\u00f3n colombiana que est\u00e1 llegando a Argentina y Uruguay.<\/p>\n<p>Entonces, refiri\u00e9ndonos a Argentina yo hablar\u00eda de Venezuela, Colombia, y luego pa\u00edses extra de Mercasur como Hait\u00ed, Rep\u00fablica Dominicana y algunas nacionalidades de \u00c1frica subsahariana. Centr\u00e1ndonos en Uruguay, tambi\u00e9n estamos hablando de mucha presencia de nacionalidad venezolana, pero en segundo lugar entrar\u00eda el flujo migratorio cubano y en tercero el dominicano: esos ser\u00edan m\u00e1s o menos los flujos o las nacionalidades que acompa\u00f1amos en el SJM.<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sjm_argentina.jpeg\" style=\"width: 800px;height: 600px\"><\/p>\n<p><span style=\"color:#FF0000\"><strong>\u00bfC\u00f3mo trabaja el SJM con los flujos migratorios que comentabas inicialmente? Cuando una familia llega al pa\u00eds \u00bfc\u00f3mo os conoce, c\u00f3mo es la acogida..?<\/strong><\/span><br \/>Hay dos grandes tipos de perfil que abordamos. Unos son personas que ya han llegado a la Argentina o a Uruguay y por alguna situaci\u00f3n no han logrado tener un proceso de integraci\u00f3n exitosa, y el otro incluye a caminantes que reci\u00e9n llegan, en situaci\u00f3n de gran vulnerabilidad, incluso algunos solo traen lo puesto.<\/p>\n<p>Los primeros llegan sobre todo por el tema habitacional, tanto en Uruguay como en Argentina. Entonces tenemos que acompa\u00f1arlos en todo un proceso que comienza con lo laboral, con lo habitacional muchas veces. Con respecto a los segundos, estos muchas veces nos escriben antes de llegar al pa\u00eds. Tambi\u00e9n pasa que cuando entran en territorio nacional alguien les indica nuestra direcci\u00f3n, sea en una parroquia o por ejemplo en la terminal de buses, y cuando nos timbran nos encontramos con familias que no tienen a d\u00f3nde ir.<\/p>\n<p><span style=\"color:#FF0000\"><strong>\u00bfCu\u00e1l es el perfil de las personas que llegan? \u00bfSon m\u00e1s familias completas, o m\u00e1s bien personas adultas, menores\u2026 ?<\/strong><\/span><br \/>En el tema del trabajo con la migraci\u00f3n las din\u00e1micas van cambiando muy r\u00e1pido. Por ejemplo, si de repente hay una crisis en un pa\u00eds se va a notar en unos meses con un impacto social, econ\u00f3mico, pol\u00edtico&#8230; Entonces var\u00edan much\u00edsimo los perfiles y las nacionalidades de las personas que van llegando.<br \/>Un ejemplo ser\u00eda la migraci\u00f3n venezolana, que se caracteriz\u00f3 desde m\u00e1s o menos 2018 hasta el 2020 de antes de la pandemia, por ser una migraci\u00f3n con un perfil de j\u00f3venes entre 27 y 35 a\u00f1os con cierto nivel de estudios.<\/p>\n<p><span style=\"color:#FF0000\"><strong>Con respecto a las personas que llegan, \u00bfestas se quedan o vuelven a sus pa\u00edses tras pasar un tiempo?<\/strong><\/span><br \/>Hay de todo. Lo que hemos visto \u00faltimamente es que se ha generado una suerte de circularidad en la poblaci\u00f3n migrante, o en cierta poblaci\u00f3n migrante. Algunos de ellos se instalan, se integran, pues su objetivo ha sido llegar a un lugar y conseguir adaptarse a \u00e9l, para no tener que seguir movi\u00e9ndose.&nbsp;<\/p>\n<p>Pero hay otras familias y personas que han desarrollado una suerte de b\u00fasqueda y no le tienen miedo a trasladarse de un pa\u00eds a otro. Cruzan por donde puedan hacerlo, no solo a trav\u00e9s de lugares regulares, y esa migraci\u00f3n ha hecho una suerte de circularidad donde van bajando, y como no han podido integrarse o han tenido procesos fallidos en otros pa\u00edses siguen buscando. Cuando llegan, como tampoco en un corto plazo logran lo que quieren, vuelven a salir.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"600\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sjm_arg.jpeg\" width=\"800\"><\/p>\n<p><span style=\"color:#FF0000\"><strong>\u00bfDe qu\u00e9 manera ha afectado la pandemia y de qu\u00e9 manera os hab\u00e9is tenido que adaptar a esta realidad en vuestra misi\u00f3n?<\/strong><\/span><br \/>La pandemia fue un golpe dur\u00edsimo para todos, y nosotros lo vivimos con las familias, sobre todo con las que trabajan mayoritariamente con venta ambulante. La crisis sanitaria global implic\u00f3 no tener ingresos, no tener para comer, o no tener para pagar el alquiler. Por ello tuvimos que concentrar mucho nuestra energ\u00eda en lo que es la asistencia humanitaria, dejando m\u00e1s de lado otros muchos servicios, o rebajando la intensidad en ellos y concentrando todas nuestras fuerzas en asistencia humanitaria.<\/p>\n<p>As\u00ed, nuestra principal labor era sobre todo esto, lo b\u00e1sico: entregar alimentos, llevarlos puerta por puerta, lo cual era todo un sistema de recibir por Whatsapp, o por llamadas telef\u00f3nicas, ubicar a las personas, hacer un mapeo y luego generar toda una log\u00edstica para entregar todos estos alimentos, que no a todos pod\u00edan llegar\u2026 No nos alcanzaba para todas las solicitudes que hab\u00eda.<\/p>\n<p><span style=\"color:#FF0000\"><strong>Para concluir, \u00bfcu\u00e1les son vuestros retos en este a\u00f1o?<\/strong><\/span><br \/>Una de las l\u00edneas muy marcadas es la integraci\u00f3n socioecon\u00f3mica, o sea el trabajo. Tenemos el \u00e1rea de medios de vida, \u00e1mbito en el que estamos haciendo mucha fuerza para tratar de vincular a las personas con trabajos formales, as\u00ed como para ayudar a las personas a crear sus propios emprendimientos. Por ejemplo estar\u00eda nuestra l\u00ednea \u201cSoy Refugio\u201d, pensada sobre todo para mujeres que a veces est\u00e1n solas y sin oficio. Se le ense\u00f1a costura y se empieza a elaborar productos bajo la marca \u201cSoy Refugio\u201d . Los talleres los proponemos nosotros, pero los ingresos son para las personas que hacen estos productos, y mantenemos tambi\u00e9n los costos con un porcentaje. Esto enciende la esperanza de que algo se puede hacer, que es lo crucial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevistamos a Julio Villavicencio, Director del Servicio Jesuita a Migrantes (SJM) Argentina y Uruguay. Dos organizaciones que trabajan para acompa\u00f1ar a las personas migrantes y refugiadas para su integraci\u00f3n, y tambi\u00e9n para la defensa y acceso a los derechos.<\/p>\n","protected":false},"featured_media":6550,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[10],"country":[],"cause":[129],"class_list":["post-6552","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-migracion-y-refugio","cause-migracion-y-refugio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u201cEl circuito migratorio hacia el norte se ha vuelto cada vez m\u00e1s peligroso\u201d - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cEl circuito migratorio hacia el norte se ha vuelto cada vez m\u00e1s peligroso\u201d\" \/>\n<meta property=\"og:description\" content=\"Entrevistamos a Julio Villavicencio, Director del Servicio Jesuita a Migrantes (SJM) Argentina y Uruguay. Dos organizaciones que trabajan para acompa\u00f1ar a las personas migrantes y refugiadas para su integraci\u00f3n, y tambi\u00e9n para la defensa y acceso a los derechos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T10:37:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sjm_argentina.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\\\/\",\"name\":\"\u201cEl circuito migratorio hacia el norte se ha vuelto cada vez m\u00e1s peligroso\u201d - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/sjm_argentina.jpeg\",\"datePublished\":\"2022-05-20T08:35:20+00:00\",\"dateModified\":\"2024-02-19T10:37:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/sjm_argentina.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/sjm_argentina.jpeg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u201cEl circuito migratorio hacia el norte se ha vuelto cada vez m\u00e1s peligroso\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u201cEl circuito migratorio hacia el norte se ha vuelto cada vez m\u00e1s peligroso\u201d - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/","og_locale":"gl_ES","og_type":"article","og_title":"\u201cEl circuito migratorio hacia el norte se ha vuelto cada vez m\u00e1s peligroso\u201d","og_description":"Entrevistamos a Julio Villavicencio, Director del Servicio Jesuita a Migrantes (SJM) Argentina y Uruguay. Dos organizaciones que trabajan para acompa\u00f1ar a las personas migrantes y refugiadas para su integraci\u00f3n, y tambi\u00e9n para la defensa y acceso a los derechos.","og_url":"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-19T10:37:57+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sjm_argentina.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/","url":"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/","name":"\u201cEl circuito migratorio hacia el norte se ha vuelto cada vez m\u00e1s peligroso\u201d - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sjm_argentina.jpeg","datePublished":"2022-05-20T08:35:20+00:00","dateModified":"2024-02-19T10:37:57+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sjm_argentina.jpeg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sjm_argentina.jpeg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/el-circuito-migratorio-hacia-el-norte-se-ha-vuelto-cada-vez-mas-peligroso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/gl\/noticias\/"},{"@type":"ListItem","position":3,"name":"\u201cEl circuito migratorio hacia el norte se ha vuelto cada vez m\u00e1s peligroso\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/gl\/#website","url":"https:\/\/www.entreculturas.org\/gl\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/gl\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/gl\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia\/6552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media\/6550"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media?parent=6552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/categories?post=6552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/tags?post=6552"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/country?post=6552"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/cause?post=6552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}