{"id":6388,"date":"2021-12-22T10:16:24","date_gmt":"2021-12-22T10:16:24","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano"},"modified":"2024-02-19T16:27:09","modified_gmt":"2024-02-19T15:27:09","slug":"participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/","title":{"rendered":"ParticipAcci\u00f3n a favor de la cultura de paz en el Pac\u00edfico Colombiano"},"content":{"rendered":"<p><strong>\u201c<em>Para m\u00ed este proyecto es m\u00e1s que una capacitaci\u00f3n, es seguir alimentando mi vida, seguir dot\u00e1ndome de herramientas para transformar otras vidas, as\u00ed como otra gente ha transformado la m\u00eda<\/em>\u201d.&nbsp;<\/strong><\/p>\n<p>El testimonio de Dora In\u00e9s Mosquera, educadora popular en Santiago de Cali (Colombia), nos recuerda el sentido de este caminar colectivo que iniciamos desde Entreculturas junto a Fe y Alegr\u00eda Colombia en el 2019 con el proyecto <strong>ParticipAcci\u00f3n Pac\u00edfico.<\/strong> Una iniciativa que, a d\u00eda de hoy, <strong>ha contado con la participaci\u00f3n de m\u00e1s de 3.000&nbsp;j\u00f3venes y mujeres de Choc\u00f3, Cali y Buenaventura para fomentar una cultura de paz en sus comunidades.<\/strong> Una regi\u00f3n que arrastra una larga historia de conflictos armados y sociales significativos en la que urge proponer otras formas de relaci\u00f3n y convivencia.&nbsp;<\/p>\n<\/p>\n<p><em><span style=\"font-size:10px\">\u00a9 Fe y Alegr\u00eda Colombia<\/span><\/em><\/p>\n<h3><span style=\"color:#FF0000\"><strong>ParticipAcci\u00f3n Pac\u00edfico en los centros educativos<\/strong><\/span><\/h3>\n<p>Estudiantes, docentes, padres y madres de familia fueron los protagonistas de las 11 instituciones educativas p\u00fablicas -6 de ellas rurales- que se involucraron de lleno en el proyecto ParticipAcci\u00f3n Pac\u00edfico. En un inicio, esta iniciativa fue pensada para&nbsp;acompa\u00f1ar y formar a la comunidad de forma presencial. Sin embargo, con la llegada de la pandemia de la Covid-19, el programa se adapt\u00f3 a la no presencialidad sin perder el objetivo de <strong>motivar y propiciar la construcci\u00f3n colectiva de acciones de incidencia para favorecer la convivencia escolar.&nbsp;<\/strong><\/p>\n<p>Las sesiones de formaci\u00f3n han permitido empoderar a j\u00f3venes, docentes y familias para identificar alternativas no violentas, desde el fortalecimiento de las capacidades ciudadanas y para gestionar conflictos. \u201c<em>Compartir los diferentes puntos de vista ante una situaci\u00f3n, permite construir nuevas formas de gestionar los conflictos<\/em>\u201d, afirman los y las j\u00f3venes de s\u00e9ptimo grado de la instituci\u00f3n educativa Humberto Jord\u00e1n Mazuera de Cali.<\/p>\n<p>Con la pandemia, la formaci\u00f3n desde la virtualidad ha sido pensada para <strong>integrar tambi\u00e9n a sus familias, trabajando el compromiso por el cuidado de la vida y la convivencia familiar. <\/strong>Como la actividad \u201cLa Flor del Cuidado Familiar\u201d realizada por el estudiantado del centro educativo Santo Domingo Savio del departamento de Choc\u00f3, orientada al rescate de los valores familiares a conservar o fortalecer en \u00e9poca de pandemia.&nbsp;<\/p>\n<p>Adem\u00e1s, con el apoyo de la Secretar\u00eda de Educaci\u00f3n Departamental del Choc\u00f3, se han acompa\u00f1ado espacios de formaci\u00f3n virtual con docentes orientados a diversificar las estrategias pedag\u00f3gicas en \u00e9poca de pandemia, especialmente, para responder a los desaf\u00edos de la calidad del servicio educativo y la permanencia de los y las estudiantes que en este contexto territorial cobra una gran relevancia dadas las pocas condiciones de conectividad.&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"533\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/formacion_equipo_pp_202.jpg\" width=\"800\"><\/p>\n<p><em><span style=\"font-size: 10px\">\u00a9 Fe y Alegr\u00eda Colombia<\/span><\/em><\/p>\n<h3><span style=\"color:#FF0000\"><strong>ParticipAcci\u00f3n Pac\u00edfico en las comunidades<\/strong><\/span><\/h3>\n<p><strong>En el \u00e1mbito comunitario, se trabaja con colectivos juveniles con afinidades art\u00edsticas y culturales <\/strong>que desean fortalecer su compromiso ciudadano. Desde Entreculturas y Fe y Alegr\u00eda Colombia hemos logrado llegar a ellos a trav\u00e9s de llamadas telef\u00f3nicas, encuentros online y plataformas virtuales.<\/p>\n<p>Esta nueva metodolog\u00eda a distancia ha permitido tambi\u00e9n llevar a cabo nuevas iniciativas como el concurso \u201cArte para Transformar\u201d, donde j\u00f3venes de Cali, Buenaventura y Choc\u00f3 han aprovechado el poder del arte y la cultura para transmitir mensajes de esperanza, humanidad, sororidad y solidaridad a trav\u00e9s de la m\u00fasica, el teatro, la composici\u00f3n literaria, las artes pl\u00e1sticas y la danza.&nbsp;<\/p>\n<p>Otras de las iniciativas que ha logrado tener un gran impacto en las comunidades ha sido la <strong>Convivencia de C\u00edrculos de Mujeres del Pac\u00edfico. <\/strong>Naci\u00f3 en el mes de febrero de la mano de <strong>37 mujeres comprometidas en fomentar valores de equidad de g\u00e9nero, igualdad y empoderamiento de la mujer.<\/strong> Su gran trabajo qued\u00f3 reflejado en acciones de movilizaci\u00f3n social en cada territorio, como las realizadas para conmemorar el 8 de marzo, el D\u00eda Internacional de la Mujer.<\/p>\n<p>El proyecto sigue fortaleciendo la participaci\u00f3n activa y cr\u00edtica de propuestas que posicionen nuevos discursos, pr\u00e1cticas y compromisos para la convivencia escolar, la gesti\u00f3n, tramitaci\u00f3n y transformaci\u00f3n de los conflictos y el trabajo en red entre mujeres y hombres del Pac\u00edfico Colombiano. Un trabajo integral que se ha ido ejecutando gracias al apoyo del Ayuntamiento de Madrid y gracias tambi\u00e9n a cada una de las personas voluntarias y personal trabajador que han hecho posible ParticipAcci\u00f3n Pac\u00edfico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"533\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/convivencia_circulo_mujeres_cali_y_buenaventura_2021a.jpg\" width=\"800\"><\/p>\n<p><em><span style=\"font-size: 10px\">\u00a9 Fe y Alegr\u00eda Colombia<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde Entreculturas, junto a Fe y Alegr\u00eda Colombia, iniciamos en el 2019 el proyecto ParticipAcci\u00f3n Pac\u00edfico. Una iniciativa que, a d\u00eda de hoy, ha comprometido a un total de 2346 j\u00f3venes y mujeres de Choc\u00f3, Cali y Buenaventura a fomentar una cultura de paz en sus comunidades. <\/p>\n","protected":false},"featured_media":6385,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[8],"country":[],"cause":[132],"class_list":["post-6388","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-participacion-y-ciudadania-global","cause-participacion-y-ciudadania-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ParticipAcci\u00f3n a favor de la cultura de paz en el Pac\u00edfico Colombiano - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ParticipAcci\u00f3n a favor de la cultura de paz en el Pac\u00edfico Colombiano\" \/>\n<meta property=\"og:description\" content=\"Desde Entreculturas, junto a Fe y Alegr\u00eda Colombia, iniciamos en el 2019 el proyecto ParticipAcci\u00f3n Pac\u00edfico. Una iniciativa que, a d\u00eda de hoy, ha comprometido a un total de 2346 j\u00f3venes y mujeres de Choc\u00f3, Cali y Buenaventura a fomentar una cultura de paz en sus comunidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T15:27:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/convivencia_circulo_mujeres_cali_y_buenaventura_2021.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\\\/\",\"name\":\"ParticipAcci\u00f3n a favor de la cultura de paz en el Pac\u00edfico Colombiano - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/convivencia_circulo_mujeres_cali_y_buenaventura_2021.jpg\",\"datePublished\":\"2021-12-22T10:16:24+00:00\",\"dateModified\":\"2024-02-19T15:27:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/convivencia_circulo_mujeres_cali_y_buenaventura_2021.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/convivencia_circulo_mujeres_cali_y_buenaventura_2021.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ParticipAcci\u00f3n a favor de la cultura de paz en el Pac\u00edfico Colombiano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ParticipAcci\u00f3n a favor de la cultura de paz en el Pac\u00edfico Colombiano - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/","og_locale":"gl_ES","og_type":"article","og_title":"ParticipAcci\u00f3n a favor de la cultura de paz en el Pac\u00edfico Colombiano","og_description":"Desde Entreculturas, junto a Fe y Alegr\u00eda Colombia, iniciamos en el 2019 el proyecto ParticipAcci\u00f3n Pac\u00edfico. Una iniciativa que, a d\u00eda de hoy, ha comprometido a un total de 2346 j\u00f3venes y mujeres de Choc\u00f3, Cali y Buenaventura a fomentar una cultura de paz en sus comunidades.","og_url":"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-19T15:27:09+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/convivencia_circulo_mujeres_cali_y_buenaventura_2021.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/","url":"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/","name":"ParticipAcci\u00f3n a favor de la cultura de paz en el Pac\u00edfico Colombiano - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/convivencia_circulo_mujeres_cali_y_buenaventura_2021.jpg","datePublished":"2021-12-22T10:16:24+00:00","dateModified":"2024-02-19T15:27:09+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/convivencia_circulo_mujeres_cali_y_buenaventura_2021.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/convivencia_circulo_mujeres_cali_y_buenaventura_2021.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/participaccion-favor-de-la-cultura-de-paz-en-el-pacifico-colombiano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/gl\/noticias\/"},{"@type":"ListItem","position":3,"name":"ParticipAcci\u00f3n a favor de la cultura de paz en el Pac\u00edfico Colombiano"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/gl\/#website","url":"https:\/\/www.entreculturas.org\/gl\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/gl\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/gl\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia\/6388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media\/6385"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media?parent=6388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/categories?post=6388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/tags?post=6388"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/country?post=6388"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/cause?post=6388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}