{"id":6130,"date":"2021-09-07T11:46:35","date_gmt":"2021-09-07T11:46:35","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida"},"modified":"2024-02-19T17:51:41","modified_gmt":"2024-02-19T16:51:41","slug":"nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/","title":{"rendered":"Nuestros voluntarios y voluntarias internacionales de nuevo en salida"},"content":{"rendered":"<p>Desde el programa VOLPA nos sentimos muy ilusionadas. Tras m\u00e1s de un a\u00f1o de par\u00f3n en las salidas de nuestros voluntarios y voluntarias internacionales, todo parece indicar que en los pr\u00f3ximos d\u00edas y semanas se dar\u00e1n <strong>las primeras salidas de VOLPAs<\/strong> a los proyectos y comunidades de Am\u00e9rica Latina y \u00c1frica donde vivir\u00e1n su experiencia de encuentro.<\/p>\n<p>Aunque sabemos que la pandemia no ha tocado a su fin, que sigue con fuerza en muchos lugares del planeta y que la incertidumbre forma parte de la vida, el martes 7 de septiembre celebramos una<strong> jornada de env\u00edo <\/strong>para los siete voluntarios y volutarias que tenemos en pista de salida, m\u00e1s una voluntaria que ya est\u00e1 en terreno.&nbsp;<\/p>\n<ul>\n<li>Willy (Barcelona) -UPENDO, Kenia.&nbsp;<\/li>\n<li>Bea (Sevilla) &#8211; Fe y Alegr\u00eda Congo<\/li>\n<li>Sergio (Sevilla)- SJMR Brasil<\/li>\n<li>Amanda (Sevilla)- Mi Rancho, Bolivia<\/li>\n<li>Anna (Barcelona)- SJR Uganda&nbsp;<\/li>\n<li>In\u00e9s (Valladolid)- Fe y Alegr\u00eda Dominicana<\/li>\n<li>Iria (Madrid)- SJM Chile&nbsp;<\/li>\n<\/ul>\n<p>&nbsp;<br \/>Adem\u00e1s, al grupo que est\u00e1 por salir se sum\u00f3 para la jornada Clara, que desde el pasado mes de julio est\u00e1 colaborando con la Di\u00f3cesis de Migraciones de Nador, Marruecos.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>La jornada empez\u00f3 con la bienvenida de Ram\u00f3n Almansa, director de Entreculturas, que les dirigi\u00f3 unas palabras inspiradoras y claves para la experiencia VOLPA que van a vivir. Ram\u00f3n empez\u00f3 agradeciendo su atrevimiento, perseverancia y el testimonio que est\u00e1n dando desde ya a familiares, amistades y a la gente cercana. <strong>\u201cOs enviamos para servir, para que os transform\u00e9is y nos transform\u00e9is y viv\u00e1is este regalo\u201d<\/strong>, les dijo para enmarcar esta jornada de env\u00edo en la que fueron participando compa\u00f1eros\/as de los departamentos de ciudadan\u00eda, comunicaci\u00f3n y cooperaci\u00f3n de Entreculturas, adem\u00e1s de algunos de sus formadores y formadoras.&nbsp;<br \/>&nbsp;<br \/>Los voluntarios y voluntarias VOLPA son parte de Entreculturas y ese fue uno de los objetivos, que se sintieran parte de una organizaci\u00f3n que les ha acompa\u00f1ado y acompa\u00f1ar\u00e1 tambi\u00e9n ahora en su tiempo en terreno.<br \/>&nbsp;<br \/>Los VOLPAs que participaron en la jornada saldr\u00e1n si todo va bien en pr\u00f3ximas semana. Son voluntarios y voluntarias que han vivido un tiempo largo de espera, lleno de incertidumbre, pero que han mantenido la ilusi\u00f3n y las ganas de vivir y ser parte de esta experiencia VOLPA que en este 2021 cumple <strong>30 a\u00f1os de vida<\/strong> y que como llevamos compartiendo estos meses, transforma vidas. Los siete voluntarios\/as se sumar\u00e1n a proyectos, equipos&nbsp; y comunidades apoyadas por Entreculturas tanto en el<strong> \u00e1mbito educativo como en el migratorio.&nbsp;<\/strong><br \/>&nbsp;<br \/>Con enorme ilusi\u00f3n, nervios, ganas y mucha informaci\u00f3n cerraron la jornada junto al equipo de coordinaci\u00f3n VOLPA que sigue su proceso. Palabras de agradecimiento abrieron la jornada y tambi\u00e9n la cerraron. Es mucho lo vivido y aprendido, y es mucho lo que queda por vivir y aprender en este tiempo en terreno.&nbsp;<\/p>\n<p><span style=\"color:#FF0000\">Si t\u00fa tambi\u00e9n quieres lanzarte al encuentro de otras personas o culturas <a href=\"https:\/\/www.entreculturas.org\/es\/volpa\">entra aqu\u00ed<\/a> e inscr\u00edbete a la pr\u00f3xima edici\u00f3n de VOLPA.<\/span><br \/>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde el programa VOLPA nos sentimos muy ilusionadas. Tras m\u00e1s de un a\u00f1o de par\u00f3n en las salidas de nuestros voluntarios y voluntarias internacionales, todo parece indicar que en los pr\u00f3ximos d\u00edas y semanas se dar\u00e1n las primeras salidas de VOLPAs a los proyectos y comunidades de Am\u00e9rica Latina y \u00c1frica donde vivir\u00e1n su experiencia de encuentro.<\/p>\n","protected":false},"featured_media":6128,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[8],"country":[],"cause":[132],"class_list":["post-6130","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-participacion-y-ciudadania-global","cause-participacion-y-ciudadania-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nuestros voluntarios y voluntarias internacionales de nuevo en salida - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nuestros voluntarios y voluntarias internacionales de nuevo en salida\" \/>\n<meta property=\"og:description\" content=\"Desde el programa VOLPA nos sentimos muy ilusionadas. Tras m\u00e1s de un a\u00f1o de par\u00f3n en las salidas de nuestros voluntarios y voluntarias internacionales, todo parece indicar que en los pr\u00f3ximos d\u00edas y semanas se dar\u00e1n las primeras salidas de VOLPAs a los proyectos y comunidades de Am\u00e9rica Latina y \u00c1frica donde vivir\u00e1n su experiencia de encuentro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T16:51:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/09\/captura_de_pantalla_2021-09-07_a_las_11.29.41.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"455\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\\\/\",\"name\":\"Nuestros voluntarios y voluntarias internacionales de nuevo en salida - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/captura_de_pantalla_2021-09-07_a_las_11.29.41.png\",\"datePublished\":\"2021-09-07T11:46:35+00:00\",\"dateModified\":\"2024-02-19T16:51:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/captura_de_pantalla_2021-09-07_a_las_11.29.41.png\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/captura_de_pantalla_2021-09-07_a_las_11.29.41.png\",\"width\":800,\"height\":455},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nuestros voluntarios y voluntarias internacionales de nuevo en salida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nuestros voluntarios y voluntarias internacionales de nuevo en salida - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/","og_locale":"gl_ES","og_type":"article","og_title":"Nuestros voluntarios y voluntarias internacionales de nuevo en salida","og_description":"Desde el programa VOLPA nos sentimos muy ilusionadas. Tras m\u00e1s de un a\u00f1o de par\u00f3n en las salidas de nuestros voluntarios y voluntarias internacionales, todo parece indicar que en los pr\u00f3ximos d\u00edas y semanas se dar\u00e1n las primeras salidas de VOLPAs a los proyectos y comunidades de Am\u00e9rica Latina y \u00c1frica donde vivir\u00e1n su experiencia de encuentro.","og_url":"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-19T16:51:41+00:00","og_image":[{"width":800,"height":455,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/09\/captura_de_pantalla_2021-09-07_a_las_11.29.41.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/","url":"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/","name":"Nuestros voluntarios y voluntarias internacionales de nuevo en salida - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/09\/captura_de_pantalla_2021-09-07_a_las_11.29.41.png","datePublished":"2021-09-07T11:46:35+00:00","dateModified":"2024-02-19T16:51:41+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/09\/captura_de_pantalla_2021-09-07_a_las_11.29.41.png","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/09\/captura_de_pantalla_2021-09-07_a_las_11.29.41.png","width":800,"height":455},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/nuestros-voluntarios-y-voluntarias-internacionales-de-nuevo-en-salida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/gl\/noticias\/"},{"@type":"ListItem","position":3,"name":"Nuestros voluntarios y voluntarias internacionales de nuevo en salida"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/gl\/#website","url":"https:\/\/www.entreculturas.org\/gl\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/gl\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/gl\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia\/6130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media\/6128"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media?parent=6130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/categories?post=6130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/tags?post=6130"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/country?post=6130"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/cause?post=6130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}