{"id":5996,"date":"2021-07-01T08:27:45","date_gmt":"2021-07-01T08:27:45","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca"},"modified":"2024-02-19T17:35:05","modified_gmt":"2024-02-19T16:35:05","slug":"la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/","title":{"rendered":"La historia de vida de Sydney: &#8220;Me quise traer su corbata para mantenerlo cerca&#8221;"},"content":{"rendered":"<p style=\"text-align: justify\">\u201cPara m\u00ed, migrar signific\u00f3 mucho porque era dejar todo atr\u00e1s: mi familia, mi hermano, que es la persona m\u00e1s importante en mi vida, mi instituto, mi casa, mis amigos\u201d. Estas son las palabras que la joven Sydney Gabriela nos comparte al recordar su tierra, Venezuela, uno de los pa\u00edses con m\u00e1s \u00e9xodo de refugiados de la regi\u00f3n de Am\u00e9rica Latina y el Caribe.<\/p>\n<p>Desde el a\u00f1o 2015, m\u00e1s de 5,4 millones de venezolanos y venezolanas se han visto obligadas a abandonar sus hogares. La violencia y la inseguridad es lo que lleva a las familias a tomar la decisi\u00f3n de migrar, poniendo en riesgo sus vidas durante el desplazamiento y a tener acceso a necesidades b\u00e1sicas como a la educaci\u00f3n, a un hogar, a una alimentaci\u00f3n digna o a la salud.<\/p>\n<p style=\"text-align: justify\">En Espa\u00f1a, los programas de acogida de nuestros compa\u00f1eros y compa\u00f1eras del Servicio Jesuita a Migrantes (SJM), cuya labor apoyamos desde Entreculturas, centra su trabajo en la defensa de los derechos de las personas migrantes y su acogida e integraci\u00f3n. Sus distintas oficinas y espacios son lugares de acompa\u00f1amiento, paz y refugio para aquellas personas que se han visto obligadas a migrar. Eso hace que se sientan acompa\u00f1adas y bienvenidas a la ciudad de acogida, luchando contra numerosas barreras como los tr\u00e1mites burocr\u00e1ticos, la falta de acompa\u00f1amiento social y jur\u00eddico o la dificultad para acceder al mercado laboral.<br \/>La historia de vida de Sydney es especialmente conmovedora. La joven acompa\u00f1ada por SJM en Valencia se vio obligada a abandonar su hogar y no dud\u00f3 ni un segundo en traerse con ella la corbata de su abuelo recientemente fallecido por causas naturales. \u201cMe quise traer su corbata para mantenerlo cerca porque \u00e9l est\u00e1 en el cielo y est\u00e1 protegi\u00e9ndome, me est\u00e1 cuidando y siento que es una protecci\u00f3n para m\u00ed\u201d, nos cuenta Sydney.<\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">Son muchos los recuerdos que quedan a la hora de migrar. Para Sydney, la corbata de su abuelo le recuerda a su familia, al lugar donde naci\u00f3, sus costumbres, sus tradiciones y su cultura. Ahora, desde Valencia, la joven sue\u00f1a alg\u00fan d\u00eda poder llegar a ser \u201cuna gran profesional y demostrarle a mi mam\u00e1, y a aquellas personas que me han juzgado, que s\u00ed he podido\u201d.<\/p>\n<p>Desde SJM, Entreculturas y toda la red de Hospitalidad, seguiremos acompa\u00f1ando a las personas migrantes y refugiadas, caminando junto a ellas, para que encuentren en nuestros proyectos una puerta hacia un futuro mejor para ellas y sus familias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cPara m\u00ed, migrar signific\u00f3 mucho porque era dejar todo atr\u00e1s: mi familia, mi hermano, que es la persona m\u00e1s importante en mi vida, mi instituto, mi casa, mis amigos\u201d. Estas son las palabras que la joven Sydney Gabriela nos comparte al recordar su tierra, Venezuela, uno de los pa\u00edses con m\u00e1s \u00e9xodo de refugiados de la regi\u00f3n de Am\u00e9rica Latina y el Caribe.<\/p>\n","protected":false},"featured_media":5998,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[10],"country":[127],"cause":[129],"class_list":["post-5996","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-migracion-y-refugio","country-venezuela","cause-migracion-y-refugio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La historia de vida de Sydney: &quot;Me quise traer su corbata para mantenerlo cerca&quot; - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La historia de vida de Sydney: &quot;Me quise traer su corbata para mantenerlo cerca&quot;\" \/>\n<meta property=\"og:description\" content=\"\u201cPara m\u00ed, migrar signific\u00f3 mucho porque era dejar todo atr\u00e1s: mi familia, mi hermano, que es la persona m\u00e1s importante en mi vida, mi instituto, mi casa, mis amigos\u201d. Estas son las palabras que la joven Sydney Gabriela nos comparte al recordar su tierra, Venezuela, uno de los pa\u00edses con m\u00e1s \u00e9xodo de refugiados de la regi\u00f3n de Am\u00e9rica Latina y el Caribe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T16:35:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/captura_de_pantalla_2021-07-02_a_las_11.16.51.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\\\/\",\"name\":\"La historia de vida de Sydney: \\\"Me quise traer su corbata para mantenerlo cerca\\\" - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/captura_de_pantalla_2021-07-02_a_las_11.16.51.png\",\"datePublished\":\"2021-07-01T08:27:45+00:00\",\"dateModified\":\"2024-02-19T16:35:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/captura_de_pantalla_2021-07-02_a_las_11.16.51.png\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/captura_de_pantalla_2021-07-02_a_las_11.16.51.png\",\"width\":800,\"height\":492,\"caption\":\"captura_de_pantalla_2021-07-02_a_las_11\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La historia de vida de Sydney: &#8220;Me quise traer su corbata para mantenerlo cerca&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La historia de vida de Sydney: \"Me quise traer su corbata para mantenerlo cerca\" - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/","og_locale":"gl_ES","og_type":"article","og_title":"La historia de vida de Sydney: \"Me quise traer su corbata para mantenerlo cerca\"","og_description":"\u201cPara m\u00ed, migrar signific\u00f3 mucho porque era dejar todo atr\u00e1s: mi familia, mi hermano, que es la persona m\u00e1s importante en mi vida, mi instituto, mi casa, mis amigos\u201d. Estas son las palabras que la joven Sydney Gabriela nos comparte al recordar su tierra, Venezuela, uno de los pa\u00edses con m\u00e1s \u00e9xodo de refugiados de la regi\u00f3n de Am\u00e9rica Latina y el Caribe.","og_url":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-19T16:35:05+00:00","og_image":[{"width":800,"height":492,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/captura_de_pantalla_2021-07-02_a_las_11.16.51.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/","url":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/","name":"La historia de vida de Sydney: \"Me quise traer su corbata para mantenerlo cerca\" - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/captura_de_pantalla_2021-07-02_a_las_11.16.51.png","datePublished":"2021-07-01T08:27:45+00:00","dateModified":"2024-02-19T16:35:05+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/captura_de_pantalla_2021-07-02_a_las_11.16.51.png","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/captura_de_pantalla_2021-07-02_a_las_11.16.51.png","width":800,"height":492,"caption":"captura_de_pantalla_2021-07-02_a_las_11"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-historia-de-vida-de-sydney-me-quise-traer-su-corbata-para-mantenerlo-cerca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/gl\/noticias\/"},{"@type":"ListItem","position":3,"name":"La historia de vida de Sydney: &#8220;Me quise traer su corbata para mantenerlo cerca&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/gl\/#website","url":"https:\/\/www.entreculturas.org\/gl\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/gl\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/gl\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia\/5996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media\/5998"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media?parent=5996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/categories?post=5996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/tags?post=5996"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/country?post=5996"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/cause?post=5996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}