{"id":5849,"date":"2021-05-31T11:04:55","date_gmt":"2021-05-31T11:04:55","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal"},"modified":"2024-02-28T16:42:00","modified_gmt":"2024-02-28T15:42:00","slug":"la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/","title":{"rendered":"La promoci\u00f3n VOLPA 2020\/21 celebra su II Encuentro Estatal"},"content":{"rendered":"<p>El pasado fin de semana celebramos nuestro segundo encuentro Estatal VOLPA del curso 20-21, otra vez de manera virtual. En este encuentro participaron 19 VOLPAs en formaci\u00f3n que siguen el proceso de las delegaciones de Sevilla, Madrid, Burgos y Barcelona.<\/p>\n<p>Durante toda la ma\u00f1ana del s\u00e1bado los participantes disfrutaron del taller <strong>\u201cGesti\u00f3n de conflictos para la experiencia de voluntariado\u201d<\/strong>&nbsp;con nuestro colaborador Sergio Arranz. En este encuentro los voluntarios\/as trabajaron algunas herramientas para la gesti\u00f3n del conflictos, la diferencia entre problemas, conflictos y crisis y sobre todo remarcar la importancia de la comunicaci\u00f3n tanto para la creaci\u00f3n del conflicto como para intentar gestionarlo y resolverlo en los casos que sea posible.&nbsp;<\/p>\n<p>En la segunda jornada, nos centramos en ahondar en el <strong>conocimiento mutuo<\/strong> para sentirse parte de un equipo y una organizaci\u00f3n que les env\u00eda, compartimos las primeras <strong>claves para el encuentro<\/strong> y aterrizamos en los posibles enclaves que acoger\u00e1n a los voluntarios y voluntarias de esta promoci\u00f3n.&nbsp;<\/p>\n<\/p>\n<p>Para ahondar tanto en las claves del encuentro como en los contextos donde est\u00e1n las instituciones que acogen a estas personas voluntarias, <strong>disfrutamos del testimonio de Eva y Carlos que estuvieron en Fe y Alegr\u00eda Ecuador entre 2019 y 2020<\/strong>. Eva y Carlos contaron su experiencia de encuentro con personas maravillosas que tuvieron la suerte de conocer en su barrio de Guayaquil y en la Escuela Hogar de Nazareth y en el Hermano Francisco G\u00e1rate donde desarrollaron su labor. Decenas de nombres fueron apareciendo, y con cada uno de ellos una emoci\u00f3n&#8230;Carlos y Eva compartieron como su experiencia de luces y sombras les ha transformado y ayudado a aprender, a desarrollar la paciencia, lidiar con la incertidumbre, aprender a confiar, vivir sin expectativa, estar viviendo lo que toca vivir&#8230;manejar la frustraci\u00f3n. <strong>\u201cHe aprendido de mi, de lo que soy, de mi relaci\u00f3n con las personas\u2026nadie esperaba nada de mi, solo que estuviera\u201d,<\/strong> dice Eva.&nbsp;<\/p>\n<p>Al final de la segunda jornada y con \u00e1nimo de evaluar y afianzar aprendizajes, salieron palabras como<strong> ilusi\u00f3n, paciencia, v\u00e9rtigo, desaprender, comunicaci\u00f3n<\/strong> e ideas fuerza como la importancia del encuentro, aterrizando sue\u00f1os y removiendo vocaci\u00f3n o no tener miedo al conflicto sino conseguir energ\u00eda para gestionarlo y construir.&nbsp;<\/p>\n<p>Poco a poco el proceso formativo va llegando a su final y como vemos los nervios y las ganas van ganando fuerza. Todo un regalo poder seguir acompa\u00f1ando esta experiencia de cambio personal y social 30 a\u00f1os despu\u00e9s.<\/p>\n<p><span style=\"color:#FF0000\"><strong>#30a\u00f1osVOLPA<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado fin de semana celebramos nuestro segundo encuentro Estatal VOLPA del curso 20-21, otra vez de manera virtual. En este encuentro participaron 19 VOLPAs en formaci\u00f3n que siguen el proceso de las delegaciones de Sevilla, Madrid, Burgos y Barcelona. Poco a poco el proceso formativo va llegando a su final y como vemos los nervios y las ganas van ganando fuerza. Todo un regalo poder seguir acompa\u00f1ando esta experiencia de cambio personal y social 30 a\u00f1os despu\u00e9s.<\/p>\n","protected":false},"featured_media":5848,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[8],"country":[],"cause":[132],"class_list":["post-5849","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-participacion-y-ciudadania-global","cause-participacion-y-ciudadania-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La promoci\u00f3n VOLPA 2020\/21 celebra su II Encuentro Estatal - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La promoci\u00f3n VOLPA 2020\/21 celebra su II Encuentro Estatal\" \/>\n<meta property=\"og:description\" content=\"El pasado fin de semana celebramos nuestro segundo encuentro Estatal VOLPA del curso 20-21, otra vez de manera virtual. En este encuentro participaron 19 VOLPAs en formaci\u00f3n que siguen el proceso de las delegaciones de Sevilla, Madrid, Burgos y Barcelona. Poco a poco el proceso formativo va llegando a su final y como vemos los nervios y las ganas van ganando fuerza. Todo un regalo poder seguir acompa\u00f1ando esta experiencia de cambio personal y social 30 a\u00f1os despu\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T15:42:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/05\/captura_de_pantalla_2021-05-31_a_las_13.03.25.png\" \/>\n\t<meta property=\"og:image:width\" content=\"843\" \/>\n\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\\\/\",\"name\":\"La promoci\u00f3n VOLPA 2020\\\/21 celebra su II Encuentro Estatal - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/captura_de_pantalla_2021-05-31_a_las_13.03.25.png\",\"datePublished\":\"2021-05-31T11:04:55+00:00\",\"dateModified\":\"2024-02-28T15:42:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/captura_de_pantalla_2021-05-31_a_las_13.03.25.png\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/captura_de_pantalla_2021-05-31_a_las_13.03.25.png\",\"width\":843,\"height\":457},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La promoci\u00f3n VOLPA 2020\\\/21 celebra su II Encuentro Estatal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La promoci\u00f3n VOLPA 2020\/21 celebra su II Encuentro Estatal - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/","og_locale":"gl_ES","og_type":"article","og_title":"La promoci\u00f3n VOLPA 2020\/21 celebra su II Encuentro Estatal","og_description":"El pasado fin de semana celebramos nuestro segundo encuentro Estatal VOLPA del curso 20-21, otra vez de manera virtual. En este encuentro participaron 19 VOLPAs en formaci\u00f3n que siguen el proceso de las delegaciones de Sevilla, Madrid, Burgos y Barcelona. Poco a poco el proceso formativo va llegando a su final y como vemos los nervios y las ganas van ganando fuerza. Todo un regalo poder seguir acompa\u00f1ando esta experiencia de cambio personal y social 30 a\u00f1os despu\u00e9s.","og_url":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-28T15:42:00+00:00","og_image":[{"width":843,"height":457,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/05\/captura_de_pantalla_2021-05-31_a_las_13.03.25.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/","url":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/","name":"La promoci\u00f3n VOLPA 2020\/21 celebra su II Encuentro Estatal - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/05\/captura_de_pantalla_2021-05-31_a_las_13.03.25.png","datePublished":"2021-05-31T11:04:55+00:00","dateModified":"2024-02-28T15:42:00+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/05\/captura_de_pantalla_2021-05-31_a_las_13.03.25.png","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/05\/captura_de_pantalla_2021-05-31_a_las_13.03.25.png","width":843,"height":457},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/la-promocion-volpa-202021-celebra-su-ii-encuentro-estatal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/gl\/noticias\/"},{"@type":"ListItem","position":3,"name":"La promoci\u00f3n VOLPA 2020\/21 celebra su II Encuentro Estatal"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/gl\/#website","url":"https:\/\/www.entreculturas.org\/gl\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/gl\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/gl\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia\/5849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media\/5848"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media?parent=5849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/categories?post=5849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/tags?post=5849"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/country?post=5849"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/cause?post=5849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}