{"id":5712,"date":"2021-04-21T09:03:42","date_gmt":"2021-04-21T09:03:42","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger"},"modified":"2024-02-28T17:10:11","modified_gmt":"2024-02-28T16:10:11","slug":"voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/","title":{"rendered":"Voluntarios de BBVA y Entreculturas forman a docentes sobre ciberseguridad para proteger a ni\u00f1os en riesgo de exclusi\u00f3n"},"content":{"rendered":"<p><em><span style=\"font-size:10px\">Foto: Fe y Alegr\u00eda Uruguay<\/span><\/em><\/p>\n<p><strong>Durante los meses de enero y febrero, voluntarias y voluntarios de BBVA, especialistas en ciberseguridad, han realizado sesiones formativas a profesores\/as de la red de colegios con la que Entreculturas trabaja en Espa\u00f1a y de las diferentes escuelas de Fe y Alegr\u00eda en Latinoam\u00e9rica.<\/strong><\/p>\n<p>Los talleres, organizados durante cuatro semanas, han abordado los principales problemas&nbsp; a los que se enfrentan los profesores en el uso de internet y de las Tecnolog\u00edas de la Informaci\u00f3n y Comunicaci\u00f3n (TIC), as\u00ed como los riesgos que la nueva era digital puede suponer a los menores. La formaci\u00f3n se complet\u00f3 con diversos \u2018workshops\u2019 en los que se trataron cuestiones como la realizaci\u00f3n de clases online seguras o la prevenci\u00f3n de ciberataques, entre otros.<br \/>&nbsp;<br \/>Asimismo, los profesionales de ciberseguridad de BBVA se enfocaron en el papel que desempe\u00f1an las redes sociales en el d\u00eda a d\u00eda de los estudiantes y la importancia que juega la privacidad, as\u00ed como la seguridad y el buen uso de la informaci\u00f3n, a trav\u00e9s de los&nbsp; dispositivos m\u00f3viles.<br \/>&nbsp;<br \/>Las sesiones de formaci\u00f3n tambi\u00e9n dedicaron un tiempo a la huella digital y al establecimiento de buenas pr\u00e1cticas para que, tanto los profesores como las familias, puedan hacer un uso seguro de la tecnolog\u00eda en el \u00e1mbito de sus relaciones dentro del centro escolar.<br \/>&nbsp;<br \/>Al tratarse de talleres online, no s\u00f3lo participaron profesores de centros educativos espa\u00f1oles, sino que tambi\u00e9n pudieron formar parte del evento docentes de las escuelas de Fe y Alegr\u00eda de distintos pa\u00edses de Latinoam\u00e9rica, lo que sin duda, enriqueci\u00f3 a\u00fan m\u00e1s las sesiones de formaci\u00f3n, al poder compartir visiones y experiencias muy distintas.<br \/>&nbsp;<br \/>\u201c<em>Queremos agradecer, una a\u00f1o m\u00e1s, el nivel de compromiso y dedicaci\u00f3n que los Voluntarios de BBVA han tenido, abordando los \u2018workshops\u2019 de forma din\u00e1mica y creando un programa formativo tan completo. Colaboraciones como esta recuerdan la importancia de generar sinergias entre el sector privado y el tercer sector, creando una experiencia conjunta y enriqueciendo la alianza integral existente entre ambas entidades. Una relaci\u00f3n que demuestra el papel fundamental que juega la RSC y el resultado positivo que se da cuando se act\u00faa transversalmente en los distintos \u00e1mbitos de gesti\u00f3n de la empresa<\/em>\u201d, ha subrayado Esperanza Vivanco, Responsable de RSC en Entreculturas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"720\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/04\/fe_y_alegria_guatemala_-_entreculturas.jpg\" width=\"1080\"><em><span style=\"font-size: 10px\">Foto: Fe y Alegr\u00eda Guatemala<\/span><\/em><\/p>\n<p><span style=\"color:#FF0000\"><strong>La relaci\u00f3n entre BBVA y Entreculturas<\/strong><\/span><br \/>&nbsp;<br \/>BBVA y Entreculturas llevan colaborando juntos m\u00e1s de quince a\u00f1os a trav\u00e9s de numerosas iniciativas que consolidan la estrecha relaci\u00f3n de ambas entidades. En el a\u00f1o 2006, BBVA pon\u00eda en marcha la iniciativa Euro solidario, por la que los empleados donan un euro al mes de su n\u00f3mina, con el objetivo de contribuir a prevenir la exclusi\u00f3n social de los adolescentes en Espa\u00f1a. Desde entonces, m\u00e1s de 3.000 empleados de BBVA en Espa\u00f1a colaboran con esta iniciativa.<br \/>&nbsp;<br \/>Esta alianza muestra el nivel de compromiso de la entidad financiera con la educaci\u00f3n de colectivos vulnerables. De este modo, los voluntarios y voluntarias de BBVA ponen sus capacidades y su profesionalidad al servicio de Entreculturas y as\u00ed generar un impacto positivo en los diferentes&nbsp; proyectos que llevamos a cabo en Espa\u00f1a y Latinoam\u00e9rica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los meses de enero y febrero, Voluntarios de BBVA, especialistas en ciberseguridad, han realizado sesiones formativas a profesores de la red de colegios con la que trabajamos en Espa\u00f1a y de las diferentes escuelas de Fe y Alegr\u00eda en Latinoam\u00e9rica.<\/p>\n","protected":false},"featured_media":5710,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[196],"country":[],"cause":[128],"class_list":["post-5712","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-rsc","cause-educacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Voluntarios de BBVA y Entreculturas forman a docentes sobre ciberseguridad para proteger a ni\u00f1os en riesgo de exclusi\u00f3n - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Voluntarios de BBVA y Entreculturas forman a docentes sobre ciberseguridad para proteger a ni\u00f1os en riesgo de exclusi\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Durante los meses de enero y febrero, Voluntarios de BBVA, especialistas en ciberseguridad, han realizado sesiones formativas a profesores de la red de colegios con la que trabajamos en Espa\u00f1a y de las diferentes escuelas de Fe y Alegr\u00eda en Latinoam\u00e9rica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T16:10:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/04\/fe_y_alegria_uruguay_-_entreculturas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\\\/\",\"name\":\"Voluntarios de BBVA y Entreculturas forman a docentes sobre ciberseguridad para proteger a ni\u00f1os en riesgo de exclusi\u00f3n - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/fe_y_alegria_uruguay_-_entreculturas.jpg\",\"datePublished\":\"2021-04-21T09:03:42+00:00\",\"dateModified\":\"2024-02-28T16:10:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/fe_y_alegria_uruguay_-_entreculturas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/fe_y_alegria_uruguay_-_entreculturas.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Voluntarios de BBVA y Entreculturas forman a docentes sobre ciberseguridad para proteger a ni\u00f1os en riesgo de exclusi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Voluntarios de BBVA y Entreculturas forman a docentes sobre ciberseguridad para proteger a ni\u00f1os en riesgo de exclusi\u00f3n - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/","og_locale":"gl_ES","og_type":"article","og_title":"Voluntarios de BBVA y Entreculturas forman a docentes sobre ciberseguridad para proteger a ni\u00f1os en riesgo de exclusi\u00f3n","og_description":"Durante los meses de enero y febrero, Voluntarios de BBVA, especialistas en ciberseguridad, han realizado sesiones formativas a profesores de la red de colegios con la que trabajamos en Espa\u00f1a y de las diferentes escuelas de Fe y Alegr\u00eda en Latinoam\u00e9rica.","og_url":"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-28T16:10:11+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/04\/fe_y_alegria_uruguay_-_entreculturas.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/","url":"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/","name":"Voluntarios de BBVA y Entreculturas forman a docentes sobre ciberseguridad para proteger a ni\u00f1os en riesgo de exclusi\u00f3n - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/04\/fe_y_alegria_uruguay_-_entreculturas.jpg","datePublished":"2021-04-21T09:03:42+00:00","dateModified":"2024-02-28T16:10:11+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/04\/fe_y_alegria_uruguay_-_entreculturas.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/04\/fe_y_alegria_uruguay_-_entreculturas.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/voluntarios-de-bbva-y-entreculturas-forman-docentes-sobre-ciberseguridad-para-proteger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/gl\/noticias\/"},{"@type":"ListItem","position":3,"name":"Voluntarios de BBVA y Entreculturas forman a docentes sobre ciberseguridad para proteger a ni\u00f1os en riesgo de exclusi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/gl\/#website","url":"https:\/\/www.entreculturas.org\/gl\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/gl\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/gl\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia\/5712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media\/5710"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media?parent=5712"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/categories?post=5712"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/tags?post=5712"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/country?post=5712"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/cause?post=5712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}