{"id":5110,"date":"2020-09-14T07:50:14","date_gmt":"2020-09-14T07:50:14","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=encuentro-volpa-somos-proceso-y-somos-proyecto"},"modified":"2024-03-06T17:56:28","modified_gmt":"2024-03-06T16:56:28","slug":"volpa-somos-proceso-y-somos-proyecto","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/","title":{"rendered":"Encuentro VOLPA: somos proceso y somos proyecto"},"content":{"rendered":"<p>A estas alturas del a\u00f1o los VOLPA que se encuentran en formaci\u00f3n ya tendr\u00edan destino para vivir su experiencia de voluntariado internacional. A estas alturas del a\u00f1o del COVID-19 las 20 personas que est\u00e1n form\u00e1ndose no saben a\u00fan ni destino ni cuando lo sabr\u00e1n, es el a\u00f1o de gestionar la incertidumbre y los miedos que surgen cuando no se sabe.<\/p>\n<p>El pasado s\u00e1bado los equipos VOLPA de Alboan y de Entreculturas tuvimos un <strong>espacio formativo e informativo con los 34 VOLPA<\/strong> de ambas instituciones que o bien est\u00e1n form\u00e1ndose, o bien fueron de las personas que no pudieron llegar a viajar o tuvieron que regresar una vez decretado el estado de alarma. Todos ellos y ellas, juntos a sus formadores, formadoras y acompa\u00f1antes, compartimos una ma\u00f1ana de s\u00e1bado en la que se <strong>nos invit\u00f3 a vivir este tiempo de incertidumbre con confianza y consciencia<\/strong> para nuestra toma de decisiones: seguir o no seguir en el proceso.&nbsp;<br \/>&nbsp;<\/p>\n<\/p>\n<p>La ma\u00f1ana parti\u00f3 con una bienvenida a las 50 personas presentes de distintos puntos de Espa\u00f1a. V\u00edctor, del equipo de formadores de Granada tomo la temperatura a los VOLPA sobre c\u00f3mo segu\u00edan de conectados con el proyecto VOLPA tras el verano e inmersos en la duda de d\u00f3nde y cu\u00e1ndo podr\u00e1n viajar. <strong>El 78% coment\u00f3 que VOLPA sigue estando entre sus prioridades y el 20% que el proyecto VOLPA le produce incertidumbre.&nbsp;<\/strong><\/p>\n<p>Para poder vivir este tiempo con mayor consciencia, Alfonso L\u00f3pez-Fando, psic\u00f3logo y formador VOLPA a nivel estatal, comparti\u00f3 3 sentencias o verdades que \u00e9l vive de manera clara: <strong>nadie sabe; la duda alimenta el miedo y el miedo alimenta la duda; y el miedo se domestica<\/strong>. Con estas tres sentencias quiso invitar a los VOLPA a que se pregunten cu\u00e1l es el lugar que dan al miedo en este momento de incertidumbre que vivimos en el que no hay claridad sobre el itinerario de su proceso VOLPA como apuesta vital, y les invit\u00f3 a que no sea el miedo quien tome decisiones por ellos, ya que el miedo es el enemigo de la libertad.<\/p>\n<p>Alfonso les invit\u00f3 a <strong>que nadie renuncie a un sue\u00f1o en la vida por el miedo<\/strong> y para ello hay que tomar conciencia del presente, preguntarse una vez m\u00e1s para qu\u00e9 quieres vivir y que la llamada es a integrar nuestra parte racional, emocional y de valores en la toma de decisiones.&nbsp;<\/p>\n<p>Tras la charla inspiradora de Alfonso fue el turno de contar cu\u00e1l es la situaci\u00f3n de las instituciones locales y proyectos donde los VOLPA suelen integrarse para que pudieran tomar consciencia de la situaci\u00f3n. Para ellos contamos con el testimonio de <strong>Marta Soto, que es VOLPA con el SJM en Chile<\/strong> y que cont\u00f3 c\u00f3mo su experiencia de voluntariado est\u00e1 siendo muy distinta a la que pens\u00f3 por el esfuerzo de adaptaci\u00f3n tan grande que la pandemia ha conllevado con gran parte de su tiempo teletrabajando. <strong>Christian Ubilla, director regional de Fe y Alegr\u00eda en Guayaquil<\/strong> acerc\u00f3 a los presentes la situaci\u00f3n dif\u00edcil en la que se encuentra el pa\u00eds, pero sobre todo las familias y el alumnado de Fe y Alegr\u00eda que no cuenta con buenas condiciones de conectividad. Con todo Christian invit\u00f3 a los VOLPA a mantener la esperanza y seguir trabajando por una misi\u00f3n que merece la pena.<br \/>&nbsp;<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/captura_de_pantalla_2020-09-14_a_las_9.42.23.png\" style=\"width: 800px;height: 416px\"><\/p>\n<p>Este bloque lo cerr\u00f3 <strong>Leire Morquecho, coordinadora del \u00e1rea de cooperaci\u00f3n de ALBOAN<\/strong> que, a trav\u00e9s de las causas justas que comparten Alboan y Entreculturas (derecho a la educaci\u00f3n; vida digna en movilidad; justicia socioambiental; Ciudadan\u00eda Global y G\u00e9nero), nos dio unas pinceladas sobre el impacto del COVID en las instituciones con las que trabajamos en Am\u00e9rica Latina y \u00c1frica en la vida de la gente. Esta pandemia solo ha hecho profundizar y visibilizar la realidad de desigualdad y violencia que ya exist\u00eda, pero tambi\u00e9n ha tra\u00eddo dosis de creatividad y llamada a lo comunitario para salir de esta situaci\u00f3n.<\/p>\n<p>El encuentro cerr\u00f3 con avisos y pr\u00f3ximos pasos en los que se anunciaron intenciones m\u00e1s que certezas, ya que a\u00fan no contamos con claridad en el proceso VOLPA de esta generaci\u00f3n 2019\/20, y en la evaluaci\u00f3n final fue esta generaci\u00f3n la que <strong>expres\u00f3 gratitud por el encuentro y conclusiones como hay ampliar la mirada, \u00e1brete a la experiencia, no renunciar o somos proceso y somos proyecto. Seguimos\u2026&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado s\u00e1bado los equipos VOLPA de Alboan y de Entreculturas tuvimos un espacio formativo e informativo con los 34 VOLPA de ambas instituciones que o bien est\u00e1n form\u00e1ndose, o bien fueron de las personas que no pudieron llegar a viajar o tuvieron que regresar una vez decretado el estado de alarma. <\/p>\n","protected":false},"featured_media":5108,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[8],"country":[],"cause":[132],"class_list":["post-5110","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-participacion-y-ciudadania-global","cause-participacion-y-ciudadania-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Encuentro VOLPA: somos proceso y somos proyecto - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Encuentro VOLPA: somos proceso y somos proyecto\" \/>\n<meta property=\"og:description\" content=\"El pasado s\u00e1bado los equipos VOLPA de Alboan y de Entreculturas tuvimos un espacio formativo e informativo con los 34 VOLPA de ambas instituciones que o bien est\u00e1n form\u00e1ndose, o bien fueron de las personas que no pudieron llegar a viajar o tuvieron que regresar una vez decretado el estado de alarma.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T16:56:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/pasted_image_0.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/volpa-somos-proceso-y-somos-proyecto\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/volpa-somos-proceso-y-somos-proyecto\\\/\",\"name\":\"Encuentro VOLPA: somos proceso y somos proyecto - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/volpa-somos-proceso-y-somos-proyecto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/volpa-somos-proceso-y-somos-proyecto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/pasted_image_0.png\",\"datePublished\":\"2020-09-14T07:50:14+00:00\",\"dateModified\":\"2024-03-06T16:56:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/volpa-somos-proceso-y-somos-proyecto\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/volpa-somos-proceso-y-somos-proyecto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/volpa-somos-proceso-y-somos-proyecto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/pasted_image_0.png\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/pasted_image_0.png\",\"width\":1000,\"height\":562},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticia\\\/volpa-somos-proceso-y-somos-proyecto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Encuentro VOLPA: somos proceso y somos proyecto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Encuentro VOLPA: somos proceso y somos proyecto - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/","og_locale":"gl_ES","og_type":"article","og_title":"Encuentro VOLPA: somos proceso y somos proyecto","og_description":"El pasado s\u00e1bado los equipos VOLPA de Alboan y de Entreculturas tuvimos un espacio formativo e informativo con los 34 VOLPA de ambas instituciones que o bien est\u00e1n form\u00e1ndose, o bien fueron de las personas que no pudieron llegar a viajar o tuvieron que regresar una vez decretado el estado de alarma.","og_url":"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-03-06T16:56:28+00:00","og_image":[{"width":1000,"height":562,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/pasted_image_0.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/","url":"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/","name":"Encuentro VOLPA: somos proceso y somos proyecto - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/pasted_image_0.png","datePublished":"2020-09-14T07:50:14+00:00","dateModified":"2024-03-06T16:56:28+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/pasted_image_0.png","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/pasted_image_0.png","width":1000,"height":562},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/gl\/noticia\/volpa-somos-proceso-y-somos-proyecto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/gl\/noticias\/"},{"@type":"ListItem","position":3,"name":"Encuentro VOLPA: somos proceso y somos proyecto"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/gl\/#website","url":"https:\/\/www.entreculturas.org\/gl\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/gl\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/gl\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia\/5110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media\/5108"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media?parent=5110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/categories?post=5110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/tags?post=5110"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/country?post=5110"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/cause?post=5110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}