{"id":10282,"date":"2022-12-11T15:54:34","date_gmt":"2022-12-11T14:54:34","guid":{"rendered":"https:\/\/www.entreculturas.org\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/"},"modified":"2024-03-12T09:18:31","modified_gmt":"2024-03-12T08:18:31","slug":"promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena","status":"publish","type":"ficha","link":"https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/","title":{"rendered":"Promoci\u00f3n de la educaci\u00f3n inicial para el desarrollo integral de la ni\u00f1ez salvadore\u00f1a"},"content":{"rendered":"<p>Promover el ejercicio efectivo del derecho a una educaci\u00f3n inicial de calidad, a trav\u00e9s de dos estrategias: fortalecimiento de los servicios existentes y ampliaci\u00f3n de su cobertura. El<br \/>\nproyecto cont\u00f3 con tres componentes: i) Capacitaci\u00f3n docente ii) Programa C\u00edrculos de familia iii) Alianzas estrat\u00e9gicas con actores locales para el beneficio del proyecto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Promover el ejercicio efectivo del derecho a una educaci\u00f3n inicial de calidad, a trav\u00e9s de dos estrategias: fortalecimiento de los servicios existentes y ampliaci\u00f3n de su cobertura. El proyecto cont\u00f3 con tres componentes: i) Capacitaci\u00f3n docente ii) Programa C\u00edrculos de familia iii) Alianzas estrat\u00e9gicas con actores locales para el beneficio del proyecto.<\/p>\n","protected":false},"featured_media":20552,"template":"","country":[322],"cause":[128],"link-pdf":[411],"anio":[403],"class_list":["post-10282","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","country-el-salvador","cause-educacion","link-pdf-https-drive-google-com-file-d-1bt3aets_krguk0sx6jlu5qvzj6umlula-viewuspsharing","anio-403"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Promoci\u00f3n de la educaci\u00f3n inicial para el desarrollo integral de la ni\u00f1ez salvadore\u00f1a - Entreculturas<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"gl_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Promoci\u00f3n de la educaci\u00f3n inicial para el desarrollo integral de la ni\u00f1ez salvadore\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Promover el ejercicio efectivo del derecho a una educaci\u00f3n inicial de calidad, a trav\u00e9s de dos estrategias: fortalecimiento de los servicios existentes y ampliaci\u00f3n de su cobertura. El proyecto cont\u00f3 con tres componentes: i) Capacitaci\u00f3n docente ii) Programa C\u00edrculos de familia iii) Alianzas estrat\u00e9gicas con actores locales para el beneficio del proyecto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-12T08:18:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png\" \/>\n\t<meta property=\"og:image:width\" content=\"585\" \/>\n\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/ficha\\\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/ficha\\\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\\\/\",\"name\":\"Promoci\u00f3n de la educaci\u00f3n inicial para el desarrollo integral de la ni\u00f1ez salvadore\u00f1a - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/ficha\\\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/ficha\\\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/placeholder04.png\",\"datePublished\":\"2022-12-11T14:54:34+00:00\",\"dateModified\":\"2024-03-12T08:18:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/ficha\\\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\\\/#breadcrumb\"},\"inLanguage\":\"gl-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/ficha\\\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/ficha\\\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/placeholder04.png\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/placeholder04.png\",\"width\":585,\"height\":699,\"caption\":\"corazon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/ficha\\\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Promoci\u00f3n de la educaci\u00f3n inicial para el desarrollo integral de la ni\u00f1ez salvadore\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"gl-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"gl-ES\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/gl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Promoci\u00f3n de la educaci\u00f3n inicial para el desarrollo integral de la ni\u00f1ez salvadore\u00f1a - Entreculturas","robots":{"index":"noindex","follow":"follow"},"og_locale":"gl_ES","og_type":"article","og_title":"Promoci\u00f3n de la educaci\u00f3n inicial para el desarrollo integral de la ni\u00f1ez salvadore\u00f1a","og_description":"Promover el ejercicio efectivo del derecho a una educaci\u00f3n inicial de calidad, a trav\u00e9s de dos estrategias: fortalecimiento de los servicios existentes y ampliaci\u00f3n de su cobertura. El proyecto cont\u00f3 con tres componentes: i) Capacitaci\u00f3n docente ii) Programa C\u00edrculos de familia iii) Alianzas estrat\u00e9gicas con actores locales para el beneficio del proyecto.","og_url":"https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-03-12T08:18:31+00:00","og_image":[{"width":585,"height":699,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/","url":"https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/","name":"Promoci\u00f3n de la educaci\u00f3n inicial para el desarrollo integral de la ni\u00f1ez salvadore\u00f1a - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/gl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","datePublished":"2022-12-11T14:54:34+00:00","dateModified":"2024-03-12T08:18:31+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/#breadcrumb"},"inLanguage":"gl-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/"]}]},{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","width":585,"height":699,"caption":"corazon"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/gl\/ficha\/promocion-de-la-educacion-inicial-para-el-desarrollo-integral-de-la-ninez-salvadorena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/gl\/"},{"@type":"ListItem","position":2,"name":"Promoci\u00f3n de la educaci\u00f3n inicial para el desarrollo integral de la ni\u00f1ez salvadore\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/gl\/#website","url":"https:\/\/www.entreculturas.org\/gl\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/gl\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/gl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"gl-ES"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/gl\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/gl\/","logo":{"@type":"ImageObject","inLanguage":"gl-ES","@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/gl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/ficha\/10282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/types\/ficha"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media\/20552"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/media?parent=10282"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/country?post=10282"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/cause?post=10282"},{"taxonomy":"link-pdf","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/link-pdf?post=10282"},{"taxonomy":"anio","embeddable":true,"href":"https:\/\/www.entreculturas.org\/gl\/wp-json\/wp\/v2\/anio?post=10282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}