{"id":6318,"date":"2021-12-09T09:55:11","date_gmt":"2021-12-09T09:55:11","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=esta-navidad-nos-trae-un-salto-la-esperanza"},"modified":"2023-12-18T10:31:27","modified_gmt":"2023-12-18T09:31:27","slug":"esta-navidad-nos-trae-un-salto-la-esperanza","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/","title":{"rendered":"Esta Navidad nos trae un salto a la esperanza"},"content":{"rendered":"<\/p>\n<p>Con nuestra campa\u00f1a #GraciasPorEsteSalto, este a\u00f1o queremos dar las gracias a cada ni\u00f1o, a cada ni\u00f1a, por sus saltos de alegr\u00eda. Por saltar obst\u00e1culos tan dif\u00edciles como la pandemia, acceder a la educaci\u00f3n siendo ni\u00f1a o vivir en situaci\u00f3n de refugio.<\/p>\n<p>Su felicidad espont\u00e1nea nos hace sentir y saber que la educaci\u00f3n est\u00e1 llegando all\u00ed donde m\u00e1s se necesita, de la mano de Fe y Alegr\u00eda, JRS y el resto de nuestras organizaciones socias.<\/p>\n<p>Os compartimos todos los elementos y las propuestas de esta campa\u00f1a, con la que rendimos homenaje a la infancia y con la que queremos tambi\u00e9n agradecer a todas las personas que apoyan la labor de Entreculturas e impulsan tantos saltos de esperanza y nuevas formas de vida.<\/p>\n<p>&nbsp;<\/p>\n<p><span><strong><span style=\"font-size: 16px\">ELEMENTOS DE LA CAMPA\u00d1A<\/span><\/strong><\/span><\/p>\n<table align=\"center\" border=\"0\" cellpadding=\"8\" cellspacing=\"0\" style=\"width: 800px\">\n<tbody>\n<tr>\n<td style=\"vertical-align: top;width: 230px\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/1-bis.jpg\" style=\"width: 200px;height: 138px\"><\/td>\n<td style=\"vertical-align: top;width: 530px\">\n<p><strong>GRACIAS POR ESTE SALTO<\/strong><br \/>En la web de la campa\u00f1a, <a href=\"https:\/\/navidad.entreculturas.org\/\" target=\"_blank\" rel=\"noopener\">navidad.entreculturas.org<\/a>, podemos encontrar toda la informaci\u00f3n y los recursos de la campa\u00f1a y nos acercamos a nuestros proyectos con infancia en tres realidades diferentes: L\u00edbano, Guatemala y Malaui.<\/p>\n<p>&nbsp;<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td>&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/2-bis.jpg\" style=\"width: 200px;height: 128px\"><\/td>\n<td style=\"vertical-align: top;width: 530px\">\n<p><strong>UN SALTO DE ILUSI\u00d3N POR VOLVER AL COLE<\/strong><br \/>En el <a href=\"https:\/\/youtu.be\/M2B6B_eDcxs\" target=\"_blank\" rel=\"noopener\">spot de la campa\u00f1a<\/a> y en el <a href=\"https:\/\/www.youtube.com\/watch?time_continue=1&amp;v=Q79YOO7JRTI&amp;feature=emb_title\" target=\"_blank\" rel=\"noopener\">v\u00eddeo de proyectos<\/a> nos sumamos a la alegr\u00eda espont\u00e1nea de los ni\u00f1os y ni\u00f1as con los que trabajamos y que han querido compartir su salto con nosotros y nosotras desde pa\u00edses como Honduras, Kenia, Malaui, Chad o Guatemala.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td>&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/4.jpg\" style=\"width: 176px;height: 250px\"><\/td>\n<td style=\"vertical-align: top\">\n<p><strong>GRACIAS A CADA NI\u00d1O Y A CADA NI\u00d1A<\/strong><br \/>A trav\u00e9s de la <a href=\"https:\/\/navidad.entreculturas.org\/library\/pdf\/unidad_didactica_2021.pdf\" target=\"_blank\" rel=\"noopener\">unidad did\u00e1ctica<\/a> de la campa\u00f1a, que podemos trabajar tanto en las aulas como con nuestras familias y entorno cercano, invitamos a peques y a adolescentes a reconocer los motivos que nos hacen estar felices, a compartirlos con los dem\u00e1s y a defender el juego y la educaci\u00f3n como derechos de todos los ni\u00f1os y ni\u00f1as del mundo.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td>&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td style=\"vertical-align: top\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/5.jpg\" style=\"width: 177px;height: 250px\"><\/td>\n<td style=\"vertical-align: top\">\n<p><strong>Y GRACIAS TAMBI\u00c9N A TI&#8230;<\/strong><br \/>En nuestra <a href=\"https:\/\/www.entreculturas.org\/informate\/publicaciones\/revista-trimestral\" target=\"_blank\" rel=\"noopener\">revista trimestral n\u00ba 84<\/a>, adem\u00e1s de recoger las noticias, entrevistas y testimonios m\u00e1s destacados, dedicamos una mirada especial a la realidad de la infancia en diferentes pa\u00edses en nuestros reportajes en profundidad.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td>&nbsp;<\/td>\n<td>&nbsp;<\/td>\n<\/tr>\n<tr>\n<td style=\"vertical-align: top\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/sites\/default\/files\/mails\/Navidad\/2019\/7.jpg\" style=\"width: 200px;height: 114px\"><\/td>\n<td style=\"vertical-align: top\">\n<p><strong>#GRACIASPORESTESALTO<\/strong><br \/>Entre todos y todas hacemos que las campa\u00f1as lleguen a m\u00e1s personas a trav\u00e9s de las redes sociales. En este <a href=\"https:\/\/docs.google.com\/document\/d\/1xDN5_dPIkhFQbEPnBpF346BHSidb4BSlTbQcTftK6ew\/edit?usp=sharing\" target=\"_blank\" rel=\"noopener\">documento<\/a> encontramos propuestas de contenidos y, en <a href=\"https:\/\/drive.google.com\/drive\/folders\/1UNVSxAyvROezX6Ma-lXD8wvO7pXRy96-?usp=sharing\" target=\"_blank\" rel=\"noopener\">esta carpeta<\/a>, las im\u00e1genes y cabeceras de la campa\u00f1a.<br \/>Finalmente, en <a href=\"https:\/\/docs.google.com\/document\/d\/1lfjuOHSo1WSrH7KZFPBi6Gz67e-B1j1mlsOlKrP0Tjg\/edit?usp=sharing\" target=\"_blank\" rel=\"noopener\">este documento<\/a> encontramos tambi\u00e9n la propuesta de mensaje para mover la campa\u00f1a en Whatsapp, otro de los canales a trav\u00e9s de los que podemos hacer llegar nuestro mensaje a\u00fan m\u00e1s lejos.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"vertical-align: top\">&nbsp;<\/td>\n<td style=\"vertical-align: top\">&nbsp;<\/td>\n<\/tr>\n<tr>\n<td style=\"vertical-align: top\">&nbsp;<\/td>\n<td style=\"vertical-align: top\">&nbsp;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Con nuestra campa\u00f1a #GraciasPorEsteSalto, este a\u00f1o queremos dar las gracias a cada ni\u00f1o, a cada ni\u00f1a, por sus saltos de alegr\u00eda. Por saltar obst\u00e1culos tan dif\u00edciles como la pandemia, acceder a la educaci\u00f3n siendo ni\u00f1a o vivir en situaci\u00f3n de refugio. Su felicidad espont\u00e1nea nos hace sentir y saber que la educaci\u00f3n est\u00e1 llegando all\u00ed donde m\u00e1s se necesita, de la mano de Fe y Alegr\u00eda, JRS y el resto de nuestras organizaciones socias.<\/p>\n","protected":false},"featured_media":6323,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[185],"country":[],"cause":[],"class_list":["post-6318","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-entreculturas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Esta Navidad nos trae un salto a la esperanza - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Esta Navidad nos trae un salto a la esperanza\" \/>\n<meta property=\"og:description\" content=\"Con nuestra campa\u00f1a #GraciasPorEsteSalto, este a\u00f1o queremos dar las gracias a cada ni\u00f1o, a cada ni\u00f1a, por sus saltos de alegr\u00eda. Por saltar obst\u00e1culos tan dif\u00edciles como la pandemia, acceder a la educaci\u00f3n siendo ni\u00f1a o vivir en situaci\u00f3n de refugio. Su felicidad espont\u00e1nea nos hace sentir y saber que la educaci\u00f3n est\u00e1 llegando all\u00ed donde m\u00e1s se necesita, de la mano de Fe y Alegr\u00eda, JRS y el resto de nuestras organizaciones socias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-18T09:31:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/gracias_por_este_salto_instagram_1080x1080.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/esta-navidad-nos-trae-un-salto-la-esperanza\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/esta-navidad-nos-trae-un-salto-la-esperanza\\\/\",\"name\":\"Esta Navidad nos trae un salto a la esperanza - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/esta-navidad-nos-trae-un-salto-la-esperanza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/esta-navidad-nos-trae-un-salto-la-esperanza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/gracias_por_este_salto_instagram_1080x1080.jpg\",\"datePublished\":\"2021-12-09T09:55:11+00:00\",\"dateModified\":\"2023-12-18T09:31:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/esta-navidad-nos-trae-un-salto-la-esperanza\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/esta-navidad-nos-trae-un-salto-la-esperanza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/esta-navidad-nos-trae-un-salto-la-esperanza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/gracias_por_este_salto_instagram_1080x1080.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/gracias_por_este_salto_instagram_1080x1080.jpg\",\"width\":800,\"height\":800,\"caption\":\"gracias_por_este_salto_instagram_1080x1080\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/esta-navidad-nos-trae-un-salto-la-esperanza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Esta Navidad nos trae un salto a la esperanza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Esta Navidad nos trae un salto a la esperanza - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/","og_locale":"fr_FR","og_type":"article","og_title":"Esta Navidad nos trae un salto a la esperanza","og_description":"Con nuestra campa\u00f1a #GraciasPorEsteSalto, este a\u00f1o queremos dar las gracias a cada ni\u00f1o, a cada ni\u00f1a, por sus saltos de alegr\u00eda. Por saltar obst\u00e1culos tan dif\u00edciles como la pandemia, acceder a la educaci\u00f3n siendo ni\u00f1a o vivir en situaci\u00f3n de refugio. Su felicidad espont\u00e1nea nos hace sentir y saber que la educaci\u00f3n est\u00e1 llegando all\u00ed donde m\u00e1s se necesita, de la mano de Fe y Alegr\u00eda, JRS y el resto de nuestras organizaciones socias.","og_url":"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2023-12-18T09:31:27+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/gracias_por_este_salto_instagram_1080x1080.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/","url":"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/","name":"Esta Navidad nos trae un salto a la esperanza - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/gracias_por_este_salto_instagram_1080x1080.jpg","datePublished":"2021-12-09T09:55:11+00:00","dateModified":"2023-12-18T09:31:27+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/gracias_por_este_salto_instagram_1080x1080.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/12\/gracias_por_este_salto_instagram_1080x1080.jpg","width":800,"height":800,"caption":"gracias_por_este_salto_instagram_1080x1080"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/esta-navidad-nos-trae-un-salto-la-esperanza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/fr\/noticias\/"},{"@type":"ListItem","position":3,"name":"Esta Navidad nos trae un salto a la esperanza"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/fr\/#website","url":"https:\/\/www.entreculturas.org\/fr\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/fr\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/fr\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia\/6318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media\/6323"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media?parent=6318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/categories?post=6318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/tags?post=6318"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/country?post=6318"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/cause?post=6318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}