{"id":5986,"date":"2021-06-28T09:58:18","date_gmt":"2021-06-28T09:58:18","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla"},"modified":"2024-07-29T12:50:21","modified_gmt":"2024-07-29T10:50:21","slug":"reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/","title":{"rendered":"Reconocen al centro SAFA Patronato Vereda con la Medalla de Oro de la Ciudad de Sevilla 2021"},"content":{"rendered":"\n<p>El centro educativo <strong>SAFA Patronato Vereda recibi\u00f3 el pasado 30 de mayo la Medalla de Oro de la Ciudad de Sevilla 2021<\/strong>. Este reconocimiento coincide con el 50 aniversario de su creaci\u00f3n en el barrio de Valdezorras, en Sevilla.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>El centro educativo destaca por su labor din\u00e1mica y comprometida con la realidad social de su entorno m\u00e1s cercano y con las distintas realidades de nuestro planeta, con especial atenci\u00f3n a la educaci\u00f3n medioambiental y la solidaridad. <strong>El centro desarrolla una destacada labor socia<\/strong>l y ha funcionado durante todo el curso como un catalizador de ayudas para aquellas familias que presentaban distintas necesidades.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Desde Entreculturas hemos podido colaborar con la reducci\u00f3n de la brecha digital en el centro educativo<\/strong> siendo mediadores de ayudas para financiar dispositivos digitales (tablets) y conexiones a la red para que el alumnado de distintas familias del centro educativo pudiese seguir su educaci\u00f3n desde casa durante la \u00e9poca de confinamiento y durante este curso escolar.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Por otro lado, se destaca la labor social y solidaria del centro educativo a trav\u00e9s de su grupo de la Red Solidaria de J\u00f3venes (RSJ), que <strong>cada a\u00f1o suma m\u00e1s de 50 estudiantes de este centro educativo<\/strong>. La RSJ de este centro lleva a\u00f1os trabajando, form\u00e1ndose y reflexionando para realizar acciones solidarias y fomentar el desarrollo de valores y actitudes solidarias en el centro educativo.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>El alumnado ha experimentado que el cambio social es posible<\/strong>, mejorando su desarrollo cognitivo, emocional, moral y social, y adquiere capacidades b\u00e1sicas para el ejercicio de una ciudadan\u00eda global. Este reconocimiento del Ayuntamiento de Sevilla es un est\u00edmulo para toda la comunidad educativa del colegio SAFA Patronato Vereda en su labor de educar \u201chombres y mujeres para los dem\u00e1s\u201d.<\/p>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>En <strong>1 hora, 2 minutos y 20 segundos del v\u00eddeo<\/strong> de la gala de entrega de Medallas de Oro de la Ciudad de Sevilla 2021, pod\u00e9is encontrar la entrega al centro educativo SAFA Patronato Vereda.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Medallas de Sevilla 2021\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/H_CoG3sDXcI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El centro educativo SAFA Patronato Vereda recibi\u00f3 el pasado 30 de mayo la Medalla de Oro de la Ciudad de Sevilla 2021. Este reconocimiento coincide con el 50 aniversario de su creaci\u00f3n en el barrio de Valdezorras, en Sevilla.<\/p>\n","protected":false},"featured_media":5985,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[289],"country":[],"cause":[128],"class_list":["post-5986","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-educacion","cause-educacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reconocen al centro SAFA Patronato Vereda con la Medalla de Oro de la Ciudad de Sevilla 2021 - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reconocen al centro SAFA Patronato Vereda con la Medalla de Oro de la Ciudad de Sevilla 2021\" \/>\n<meta property=\"og:description\" content=\"El centro educativo SAFA Patronato Vereda recibi\u00f3 el pasado 30 de mayo la Medalla de Oro de la Ciudad de Sevilla 2021. Este reconocimiento coincide con el 50 aniversario de su creaci\u00f3n en el barrio de Valdezorras, en Sevilla.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-29T10:50:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/06\/noticia_safa_patronato_vereda.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\\\/\",\"name\":\"Reconocen al centro SAFA Patronato Vereda con la Medalla de Oro de la Ciudad de Sevilla 2021 - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/noticia_safa_patronato_vereda.jpg\",\"datePublished\":\"2021-06-28T09:58:18+00:00\",\"dateModified\":\"2024-07-29T10:50:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/noticia_safa_patronato_vereda.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/noticia_safa_patronato_vereda.jpg\",\"width\":880,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reconocen al centro SAFA Patronato Vereda con la Medalla de Oro de la Ciudad de Sevilla 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reconocen al centro SAFA Patronato Vereda con la Medalla de Oro de la Ciudad de Sevilla 2021 - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/","og_locale":"fr_FR","og_type":"article","og_title":"Reconocen al centro SAFA Patronato Vereda con la Medalla de Oro de la Ciudad de Sevilla 2021","og_description":"El centro educativo SAFA Patronato Vereda recibi\u00f3 el pasado 30 de mayo la Medalla de Oro de la Ciudad de Sevilla 2021. Este reconocimiento coincide con el 50 aniversario de su creaci\u00f3n en el barrio de Valdezorras, en Sevilla.","og_url":"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-07-29T10:50:21+00:00","og_image":[{"width":880,"height":640,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/06\/noticia_safa_patronato_vereda.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/","url":"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/","name":"Reconocen al centro SAFA Patronato Vereda con la Medalla de Oro de la Ciudad de Sevilla 2021 - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/06\/noticia_safa_patronato_vereda.jpg","datePublished":"2021-06-28T09:58:18+00:00","dateModified":"2024-07-29T10:50:21+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/06\/noticia_safa_patronato_vereda.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/06\/noticia_safa_patronato_vereda.jpg","width":880,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/reconocen-al-centro-safa-patronato-vereda-con-la-medalla-de-oro-de-la-ciudad-de-sevilla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/fr\/noticias\/"},{"@type":"ListItem","position":3,"name":"Reconocen al centro SAFA Patronato Vereda con la Medalla de Oro de la Ciudad de Sevilla 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/fr\/#website","url":"https:\/\/www.entreculturas.org\/fr\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/fr\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/fr\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia\/5986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media\/5985"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media?parent=5986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/categories?post=5986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/tags?post=5986"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/country?post=5986"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/cause?post=5986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}