{"id":5812,"date":"2021-05-18T14:46:52","date_gmt":"2021-05-18T14:46:52","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de"},"modified":"2024-02-28T16:43:51","modified_gmt":"2024-02-28T15:43:51","slug":"miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/","title":{"rendered":"Miradas que Migran lanza su 5\u00aa edici\u00f3n con unas Jornadas interactivas en la construcci\u00f3n de narrativas de acogida"},"content":{"rendered":"<p style=\"text-align: justify\">Este 2021 celebramos la <strong>5\u00aa edici\u00f3n del proyecto de Aprendizaje-Servicio \u00abMiradas que Migran\u00bb,<\/strong> que acompa\u00f1amos desde hace 5 a\u00f1os en el equipo de Educaci\u00f3n de Entreculturas junto al alumnado y profesorado del Grado en Dise\u00f1o, en la Facultad de Bellas Artes de la Universidad Complutense de Madrid. <strong>Han participado este a\u00f1o 275 alumnas y alumnos<\/strong> de asignaturas diferentes del Grado en Dise\u00f1o, durante un curso universitario que como todas y todos sabemos, ha sido especialmente desafiante.<\/p>\n<p style=\"text-align: justify\">Es en respuesta a las crecientes desigualdades y desaf\u00edos globales que estamos viviendo en el mundo, que el alumnado de Miradas que Migran se ha acercado este a\u00f1o a las realidades de l<strong>as migraciones forzosas en el mundo con una mirada concreta en el contexto de la Covid-19 y la crisis clim\u00e1tica<\/strong>, factores que est\u00e1n multiplicando las dificultades vividas por las personas migrantes y refugiadas. A finales del 2018 eran m\u00e1s de 79,5 millones de personas desplazadas forzosamente en el mundo (ACNUR, 2020), y se prev\u00e9 que el n\u00famero de personas siga aumentando con la pandemia. \u00bfC\u00f3mo podemos entonces incidir nosotras y nosotros, desde las Universidades, centros educativos, movimientos sociales y la ciudadan\u00eda en general, para garantizar que los derechos inalienables de las personas migrantes y refugiadas se cumplan, y los discursos de odio se transformen en una respuesta de acogida inaplazable?<\/p>\n<p style=\"text-align: justify\">Conversaremos sobre \u00e9sta y muchas otras preguntas en las pr\u00f3ximas <strong>Jornadas de Miradas que Migran: Innovaci\u00f3n, ApS y Sostenibilidad<\/strong>, que organizamos junto al Grado en Dise\u00f1o de la Facultad de Bellas Artes de la UCM la pr\u00f3xima semana del 24-28 de mayo. Entre los eventos destacados que tendr\u00e1n lugar durante la semana, os queremos hacer <u><strong>una invitaci\u00f3n especial<\/strong><\/u> a la <strong>\u00abMesa de Experiencias: Miradas que migran y construyen acogida\u00bb el mi\u00e9rcoles 26 de mayo<\/strong>, un di\u00e1logo virtual y participativo abierto al p\u00fablico entre experiencias de personas que est\u00e1n construyendo acogida, defendiendo derechos y transformando narrativas en torno a las migraciones forzosas. En la Mesa de Experiencias <strong>tendremos la suerte de contar con intervenciones de diferentes miradas del mundo<\/strong>, \u00a1no os lo perd\u00e1is!<\/p>\n<p style=\"text-align: justify\">Pod\u00e9is inscribiros en el siguiente <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSexBmin5I9nfujEfZ9Y5qFV9bNjL1JYDCr5MwUuLw7RzTUugA\/viewform\">ENLACE DE INSCRIPCI\u00d3N<\/a><strong>,<\/strong> y descubrir a las y los ponentes invitados.<\/p>\n<p style=\"text-align: justify\">La Mesa de Experiencias tendr\u00e1 <strong>dos sesiones el mi\u00e9rcoles 26 de mayo 2021<\/strong>:<\/p>\n<p style=\"text-align: justify\"><u>SESI\u00d3N MA\u00d1ANA: 12:00-13:30h (hora peninsular Espa\u00f1a)<\/u><\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" alt=\"noticia2\" src=\"https:\/\/www.entreculturas.org\/files\/imagenes09\/eBol_feb09\/Flechita.jpg\" style=\", Arial, Tahoma, sans-serif;font-size: 15px;text-align: justify;float: left\" width=\"25\"><strong>Mariana Morales<\/strong>. Cooperaci\u00f3n \u2013 Departamento \u00c1frica y Asia, Entreculturas.<\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" alt=\"noticia2\" src=\"https:\/\/www.entreculturas.org\/files\/imagenes09\/eBol_feb09\/Flechita.jpg\" style=\", Arial, Tahoma, sans-serif;font-size: 15px;text-align: justify;float: left\" width=\"25\"><strong>Iv\u00e1n Forero<\/strong>. Refugiado colombiano, historiador y soci\u00f3logo, defensor de los derechos humanos.<\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" alt=\"noticia2\" src=\"https:\/\/www.entreculturas.org\/files\/imagenes09\/eBol_feb09\/Flechita.jpg\" style=\", Arial, Tahoma, sans-serif;font-size: 15px;text-align: justify;float: left\" width=\"25\"><strong>Alumnado y profesorado<\/strong>, Grado en Dise\u00f1o UCM. Proyecto ApS Miradas que Migran.<\/p>\n<p style=\"text-align: justify\"><u>SESI\u00d3N TARDE: 18:30-20:00h (hora peninsular Espa\u00f1a)<\/u><\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" alt=\"noticia2\" src=\"https:\/\/www.entreculturas.org\/files\/imagenes09\/eBol_feb09\/Flechita.jpg\" style=\", Arial, Tahoma, sans-serif;font-size: 15px;text-align: justify;float: left\" width=\"25\"><strong>Ang\u00e9lica Zuluaga.<\/strong> Psic\u00f3loga, \u00c1rea Mujer, SJM Valencia.<\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" alt=\"noticia2\" src=\"https:\/\/www.entreculturas.org\/files\/imagenes09\/eBol_feb09\/Flechita.jpg\" style=\", Arial, Tahoma, sans-serif;font-size: 15px;text-align: justify;float: left\" width=\"25\">&nbsp;<strong>Viviane Ogou Corbi.<\/strong> Estudiante de Seguridad Internacional, Fundadora de Puerta de \u00c1frica y Delegada Juvenil en el Consejo de Europa.<\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" alt=\"noticia2\" src=\"https:\/\/www.entreculturas.org\/files\/imagenes09\/eBol_feb09\/Flechita.jpg\" style=\", Arial, Tahoma, sans-serif;font-size: 15px;text-align: justify;float: left\" width=\"25\"><strong>Alumnado y profesorado,<\/strong> Grado en Dise\u00f1o UCM. Proyecto ApS Miradas que Migran.<\/p>\n<p style=\"text-align: justify\">Las Jornadas MqM: Innovaci\u00f3n, ApS y Sostenibilidad tambi\u00e9n acoger\u00e1n durante toda la semana del 24-28 otras actividades, entre ellas <strong>el acceso a la exposici\u00f3n virtual del trabajo realizado por el alumnado del Grado en Dise\u00f1o<\/strong>, elaborada por el alumnado y profesorado participante de esta quinta edici\u00f3n de Miradas que Migran. La exposici\u00f3n invita a descubrir <strong>carteles de comunicaci\u00f3n, narraciones transmedia e instalaciones de dise\u00f1o&nbsp;de 7 asignaturas<\/strong> diferentes del Grado en Dise\u00f1o, que sensibilizan en torno a los desaf\u00edos y las realidades de las migraciones forzosas en el mundo, e inciden en la construcci\u00f3n ciudadana de una cultura de acogida real, efectiva e inaplazable.<\/p>\n<p style=\"text-align: center\"><strong>\u00a1OS ESPERAMOS!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 2021 celebramos la 5\u00aa edici\u00f3n del proyecto de Aprendizaje-Servicio \u00abMiradas que Migran\u00bb, que acompa\u00f1amos desde hace 5 a\u00f1os en el equipo de Educaci\u00f3n de Entreculturas junto al alumnado y profesorado del Grado en Dise\u00f1o, en la Facultad de Bellas Artes de la Universidad Complutense de Madrid. Han participado este a\u00f1o 275 alumnas y alumnos de asignaturas diferentes del Grado en Dise\u00f1o, durante un curso universitario que como todas y todos sabemos, ha sido especialmente desafiante.<\/p>\n","protected":false},"featured_media":5811,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[10],"country":[],"cause":[129],"class_list":["post-5812","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-migracion-y-refugio","cause-migracion-y-refugio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Miradas que Migran lanza su 5\u00aa edici\u00f3n con unas Jornadas interactivas en la construcci\u00f3n de narrativas de acogida - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miradas que Migran lanza su 5\u00aa edici\u00f3n con unas Jornadas interactivas en la construcci\u00f3n de narrativas de acogida\" \/>\n<meta property=\"og:description\" content=\"Este 2021 celebramos la 5\u00aa edici\u00f3n del proyecto de Aprendizaje-Servicio \u00abMiradas que Migran\u00bb, que acompa\u00f1amos desde hace 5 a\u00f1os en el equipo de Educaci\u00f3n de Entreculturas junto al alumnado y profesorado del Grado en Dise\u00f1o, en la Facultad de Bellas Artes de la Universidad Complutense de Madrid. Han participado este a\u00f1o 275 alumnas y alumnos de asignaturas diferentes del Grado en Dise\u00f1o, durante un curso universitario que como todas y todos sabemos, ha sido especialmente desafiante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T15:43:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/05\/encabezado_cartelmqm2021_-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1515\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\\\/\",\"name\":\"Miradas que Migran lanza su 5\u00aa edici\u00f3n con unas Jornadas interactivas en la construcci\u00f3n de narrativas de acogida - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/encabezado_cartelmqm2021_-.jpg\",\"datePublished\":\"2021-05-18T14:46:52+00:00\",\"dateModified\":\"2024-02-28T15:43:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/encabezado_cartelmqm2021_-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/encabezado_cartelmqm2021_-.jpg\",\"width\":1920,\"height\":1515},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Miradas que Migran lanza su 5\u00aa edici\u00f3n con unas Jornadas interactivas en la construcci\u00f3n de narrativas de acogida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Miradas que Migran lanza su 5\u00aa edici\u00f3n con unas Jornadas interactivas en la construcci\u00f3n de narrativas de acogida - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/","og_locale":"fr_FR","og_type":"article","og_title":"Miradas que Migran lanza su 5\u00aa edici\u00f3n con unas Jornadas interactivas en la construcci\u00f3n de narrativas de acogida","og_description":"Este 2021 celebramos la 5\u00aa edici\u00f3n del proyecto de Aprendizaje-Servicio \u00abMiradas que Migran\u00bb, que acompa\u00f1amos desde hace 5 a\u00f1os en el equipo de Educaci\u00f3n de Entreculturas junto al alumnado y profesorado del Grado en Dise\u00f1o, en la Facultad de Bellas Artes de la Universidad Complutense de Madrid. Han participado este a\u00f1o 275 alumnas y alumnos de asignaturas diferentes del Grado en Dise\u00f1o, durante un curso universitario que como todas y todos sabemos, ha sido especialmente desafiante.","og_url":"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-28T15:43:51+00:00","og_image":[{"width":1920,"height":1515,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/05\/encabezado_cartelmqm2021_-.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/","url":"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/","name":"Miradas que Migran lanza su 5\u00aa edici\u00f3n con unas Jornadas interactivas en la construcci\u00f3n de narrativas de acogida - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/05\/encabezado_cartelmqm2021_-.jpg","datePublished":"2021-05-18T14:46:52+00:00","dateModified":"2024-02-28T15:43:51+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/05\/encabezado_cartelmqm2021_-.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/05\/encabezado_cartelmqm2021_-.jpg","width":1920,"height":1515},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/miradas-que-migran-lanza-su-5a-edicion-con-unas-jornadas-interactivas-en-la-construccion-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/fr\/noticias\/"},{"@type":"ListItem","position":3,"name":"Miradas que Migran lanza su 5\u00aa edici\u00f3n con unas Jornadas interactivas en la construcci\u00f3n de narrativas de acogida"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/fr\/#website","url":"https:\/\/www.entreculturas.org\/fr\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/fr\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/fr\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia\/5812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media\/5811"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media?parent=5812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/categories?post=5812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/tags?post=5812"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/country?post=5812"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/cause?post=5812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}