{"id":5318,"date":"2020-11-30T09:38:19","date_gmt":"2020-11-30T09:38:19","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=la-accion-por-el-clima-no-puede-esperar"},"modified":"2024-03-06T17:48:58","modified_gmt":"2024-03-06T16:48:58","slug":"la-accion-por-el-clima-no-puede-esperar","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/","title":{"rendered":"La acci\u00f3n por el clima no puede esperar"},"content":{"rendered":"<p>La 26\u00aa cumbre clim\u00e1tica de la ONU, conocida como COP26, iba a tener lugar en Glasgow del 9 al 19 de noviembre de este a\u00f1o. Sin embargo, debido a la pandemia de Covid-19, los organizadores decidieron posponer el evento, que finalmente tendr\u00e1 lugar del 1 al 12 de noviembre de 2021.&nbsp;A pesar del aplazamiento no hay dudas de que ser\u00e1 un hito decisivo para el futuro de nuestro planeta.&nbsp;<\/p>\n<p>Alboan y Entreculturas llevamos varios a\u00f1os siguiendo con atenci\u00f3n este proceso desde nuestro&nbsp;<strong>compromiso con la ecolog\u00eda integral y el cuidado de la Casa Com\u00fan<\/strong>, que se enmarca en la causa com\u00fan que ambas organizaciones mantienemos&nbsp;por la justicia socioambiental. Durante la COP25, la pasada cumbre clim\u00e1tica que se celebr\u00f3 en Madrid entre el 2 y el 13 de diciembre de 2019, nuestras delegaciones&nbsp;&nbsp;pudieron constatar la <strong>enorme atenci\u00f3n medi\u00e1tica<\/strong> que este evento despierta a nivel mundial, as\u00ed como la <strong>capacidad de movilizaci\u00f3n<\/strong> que genera entre las generaciones m\u00e1s j\u00f3venes.&nbsp;<\/p>\n<\/p>\n<p>Aquel encuentro termin\u00f3 con cierta sensaci\u00f3n de frustraci\u00f3n por la falta de avances y determinaci\u00f3n en la lucha contra el cambio clim\u00e1tico. Desde entonces las miradas han estado puestas en la COP26, que deber\u00eda celebrarse este a\u00f1o, puesto que los Estados Partes en el cumplimiento del Acuerdo de Par\u00eds se comprometieron a renovar sus Contribuciones Determinadas a nivel Nacional (NDCs, en ingl\u00e9s), que son b\u00e1sicamente los planes que define cada pa\u00eds para reducir las emisiones de gases de efecto invernadero y adaptarse a los efectos del cambio clim\u00e1tico.&nbsp;<\/p>\n<p>Por ese motivo, aprovechando la fecha simb\u00f3lica del 9 de noviembre que deber\u00eda haber dado inicio a dicha reuni\u00f3n, la Red Xavier, que engloba a las organizaciones y misiones jesuitas de cooperaci\u00f3n internacional, junto con la Conferencia Jesuita de \u00c1frica y Madagascar, han enviado una <strong>carta a varios l\u00edderes pol\u00edticos<\/strong>: Boris Johnson, presidente del Reino Unido, pa\u00eds que coorganizar\u00e1 la pr\u00f3xima COP26; la canciller \u00c1ngela Merkel, Presidenta del Consejo de la Uni\u00f3n Europea; \u00darsula von der Leyen, Presidenta de la Comisi\u00f3n Europea; y Cyril Ramaphosa, presidente de la Uni\u00f3n Africana.&nbsp;<\/p>\n<p>En la misiva enviada, firmada por Frank Janin SJ, presidente de la Red Xavier, y por Agbonkhianmeghe E. Orobator SJ, presidente de la Conferencia Jesuita de \u00c1frica y Madagascar, los jesuitas enfatizan varios <strong>puntos sobre la lucha contra el cambio clim\u00e1tico y la pobreza en \u00c1frica.<\/strong> La actual crisis y los desaf\u00edos que plantea la lucha contra el coronavirus, as\u00ed como el necesario aplazamiento de la COP26, no deben desviar nuestra atenci\u00f3n de la crisis clim\u00e1tica. La respuesta a la crisis clim\u00e1tica no puede esperar y por eso piden a los l\u00edderes de la Uni\u00f3n Europea y la Uni\u00f3n Africana no perder de vista que:&nbsp;&nbsp;<\/p>\n<ul>\n<li>Aunque la Covid-19 supone un problema muy serio, el cambio clim\u00e1tico contin\u00faa y no disminuye. Necesitamos una <strong>transformaci\u00f3n social y ecol\u00f3gica<\/strong> para afrontar las m\u00faltiples crisis de nuestro tiempo. No es suficiente con destinar billones de d\u00f3lares y euros a la lucha contra el coronavirus, es necesario gastarlo de manera que en vistas del cambio clim\u00e1tico, mitiguemos el problema y nos adaptemos a \u00e9l.<\/li>\n<li><strong>\u00c1frica sufre<\/strong> m\u00e1s (o quiz\u00e1 el que m\u00e1s) la Covid-19, <strong>ya que sus problemas de deuda y pobreza ya existentes se han exacerbado con la pandemia<\/strong>. Un escenario que tan solo hace que las consecuencias del cambio clim\u00e1tico y otras plagas debido a la contaminaci\u00f3n y el uso excesivo de recursos naturales sean m\u00e1s agresivas con el continente.<\/li>\n<li><strong>Europa<\/strong>, como uno de los mayores contaminadores de la historia, <strong>debe cumplir con los compromisos asumidos<\/strong> en el Acuerdo de Par\u00eds y en R\u00edo 1992. Directamente con la trasferencia o inversi\u00f3n de dinero y tecnolog\u00eda, o indirectamente ayudando a \u00c1frica a mejorar en los Sistemas de Gesti\u00f3n de Riesgos (DRM, en ingl\u00e9s) y a luchar contra los Flujos Financieros Il\u00edcitos.<\/li>\n<li><strong>El tiempo se acaba<\/strong> y las Contribuciones Previstas y Determinadas a Nivel Nacional (NDCs, en ingl\u00e9s), que encarnan los esfuerzos de cada pa\u00eds para reducir las emisiones nacionales y adaptarse a los efectos del cambio clim\u00e1tico, deben ser formuladas no mirando hacia los datos de 1990, sino hacia el presupuesto de CO2 global que queda antes de que se cruce el umbral de 1.5\/2 grados.<\/li>\n<li>Es posible buscar <strong>sinergias entre los intereses de Europa y \u00c1frica<\/strong>. Por ejemplo, ayudar a \u00c1frica a superar la industria f\u00f3sil es m\u00e1s eficaz para combatir el cambio clim\u00e1tico que \u201chacer trampa\u201d exportando industria sucia a pa\u00edses pobres, puliendo as\u00ed las estad\u00edsticas europeas mientras desplazamos el problema de la contaminaci\u00f3n a otro sitio.<\/li>\n<li>Por lo tanto, dados los problemas en el proceso de la COP patrocinado por las Naciones Unidas, los Jesuitas abogan por a<strong>celerar una cooperaci\u00f3n mejorada entre la UE y \u00c1frica.<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La 26\u00aa cumbre clim\u00e1tica de la ONU, conocida como COP26, iba a tener lugar en Glasgow del 9 al 19 de noviembre de este a\u00f1o. Sin embargo, debido a la pandemia de Covid-19, los organizadores decidieron posponer el evento, que finalmente tendr\u00e1 lugar del 1 al 12 de noviembre de 2021.&nbsp;A pesar del aplazamiento no hay dudas de que ser\u00e1 un hito decisivo para el futuro de nuestro planeta.&nbsp; Alboan y Entreculturas llevamos varios a\u00f1os siguiendo con atenci\u00f3n este proceso desde nuestro&nbsp;compromiso con la ecolog\u00eda integral y el cuidado de la Casa Com\u00fan, que se enmarca en la causa com\u00fan que ambas organizaciones mantienemos&nbsp;por la justicia socioambiental. Durante la COP25, la pasada cumbre clim\u00e1tica que se celebr\u00f3 en Madrid entre el 2 y el 13 de diciembre de 2019, nuestras delegaciones&nbsp;&nbsp;pudieron constatar la enorme atenci\u00f3n medi\u00e1tica que este evento despierta a nivel mundial, as\u00ed como la capacidad de movilizaci\u00f3n que [&hellip;]<\/p>\n","protected":false},"featured_media":3703,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[256],"country":[],"cause":[131],"class_list":["post-5318","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-justicia-socioambiental","cause-justicia-medioambiental"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La acci\u00f3n por el clima no puede esperar - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La acci\u00f3n por el clima no puede esperar\" \/>\n<meta property=\"og:description\" content=\"La 26\u00aa cumbre clim\u00e1tica de la ONU, conocida como COP26, iba a tener lugar en Glasgow del 9 al 19 de noviembre de este a\u00f1o. Sin embargo, debido a la pandemia de Covid-19, los organizadores decidieron posponer el evento, que finalmente tendr\u00e1 lugar del 1 al 12 de noviembre de 2021.&nbsp;A pesar del aplazamiento no hay dudas de que ser\u00e1 un hito decisivo para el futuro de nuestro planeta.&nbsp; Alboan y Entreculturas llevamos varios a\u00f1os siguiendo con atenci\u00f3n este proceso desde nuestro&nbsp;compromiso con la ecolog\u00eda integral y el cuidado de la Casa Com\u00fan, que se enmarca en la causa com\u00fan que ambas organizaciones mantienemos&nbsp;por la justicia socioambiental. Durante la COP25, la pasada cumbre clim\u00e1tica que se celebr\u00f3 en Madrid entre el 2 y el 13 de diciembre de 2019, nuestras delegaciones&nbsp;&nbsp;pudieron constatar la enorme atenci\u00f3n medi\u00e1tica que este evento despierta a nivel mundial, as\u00ed como la capacidad de movilizaci\u00f3n que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T16:48:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/09\/madrid-clima2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/la-accion-por-el-clima-no-puede-esperar\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/la-accion-por-el-clima-no-puede-esperar\\\/\",\"name\":\"La acci\u00f3n por el clima no puede esperar - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/la-accion-por-el-clima-no-puede-esperar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/la-accion-por-el-clima-no-puede-esperar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/madrid-clima2.jpg\",\"datePublished\":\"2020-11-30T09:38:19+00:00\",\"dateModified\":\"2024-03-06T16:48:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/la-accion-por-el-clima-no-puede-esperar\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/la-accion-por-el-clima-no-puede-esperar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/la-accion-por-el-clima-no-puede-esperar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/madrid-clima2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/madrid-clima2.jpg\",\"width\":800,\"height\":533,\"caption\":\"madrid-clima2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/la-accion-por-el-clima-no-puede-esperar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La acci\u00f3n por el clima no puede esperar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La acci\u00f3n por el clima no puede esperar - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/","og_locale":"fr_FR","og_type":"article","og_title":"La acci\u00f3n por el clima no puede esperar","og_description":"La 26\u00aa cumbre clim\u00e1tica de la ONU, conocida como COP26, iba a tener lugar en Glasgow del 9 al 19 de noviembre de este a\u00f1o. Sin embargo, debido a la pandemia de Covid-19, los organizadores decidieron posponer el evento, que finalmente tendr\u00e1 lugar del 1 al 12 de noviembre de 2021.&nbsp;A pesar del aplazamiento no hay dudas de que ser\u00e1 un hito decisivo para el futuro de nuestro planeta.&nbsp; Alboan y Entreculturas llevamos varios a\u00f1os siguiendo con atenci\u00f3n este proceso desde nuestro&nbsp;compromiso con la ecolog\u00eda integral y el cuidado de la Casa Com\u00fan, que se enmarca en la causa com\u00fan que ambas organizaciones mantienemos&nbsp;por la justicia socioambiental. Durante la COP25, la pasada cumbre clim\u00e1tica que se celebr\u00f3 en Madrid entre el 2 y el 13 de diciembre de 2019, nuestras delegaciones&nbsp;&nbsp;pudieron constatar la enorme atenci\u00f3n medi\u00e1tica que este evento despierta a nivel mundial, as\u00ed como la capacidad de movilizaci\u00f3n que [&hellip;]","og_url":"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-03-06T16:48:58+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/09\/madrid-clima2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/","url":"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/","name":"La acci\u00f3n por el clima no puede esperar - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/09\/madrid-clima2.jpg","datePublished":"2020-11-30T09:38:19+00:00","dateModified":"2024-03-06T16:48:58+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/09\/madrid-clima2.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/09\/madrid-clima2.jpg","width":800,"height":533,"caption":"madrid-clima2"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/la-accion-por-el-clima-no-puede-esperar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/fr\/noticias\/"},{"@type":"ListItem","position":3,"name":"La acci\u00f3n por el clima no puede esperar"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/fr\/#website","url":"https:\/\/www.entreculturas.org\/fr\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/fr\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/fr\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia\/5318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media\/3703"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media?parent=5318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/categories?post=5318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/tags?post=5318"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/country?post=5318"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/cause?post=5318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}