{"id":4773,"date":"2020-06-12T08:29:15","date_gmt":"2020-06-12T08:29:15","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille"},"modified":"2024-03-06T18:23:36","modified_gmt":"2024-03-06T17:23:36","slug":"inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/","title":{"rendered":"Inauguramos la exposici\u00f3n virtual de La Luz de las Ni\u00f1as: conoce la historia de Kim, Mireille, Sima y Michel Ange"},"content":{"rendered":"<\/p>\n<p>El objetivo de esta nueva exposici\u00f3n virtual es el de poder acercar a un mayor n\u00famero de personas <strong>la realidades de millones de ni\u00f1as en todo el mundo<\/strong>, incluso en situaciones de crisis, como la vivida actualmente a causa del Covid-19. <strong>El cierre de las escuelas<\/strong>, est\u00e1 teniendo un <strong>fuerte impacto en el aumento de la violencia que sufren las ni\u00f1as y las mujeres<\/strong>, por lo que ahora, m\u00e1s que nunca, es importante poder contar con recursos como este para seguir visibilizando esta lacra.&nbsp;<\/p>\n<p>La exposici\u00f3n pone rostro a la realidad que viven <a href=\"https:\/\/www.laluzdelasninas.org\/\" target=\"_blank\" rel=\"noopener\">240 millones de ni\u00f1as en todo el mundo<\/a>. Una muestra que refleja la oscuridad por la que ni\u00f1as y j\u00f3venes atraviesan como consecuencia de pr\u00e1cticas abusivas como el matrimonio forzado, la violencia psicol\u00f3gica, f\u00edsica y sexual, la mutilaci\u00f3n genital, etc. pero que tambi\u00e9n <strong>arroja luz y esperanza, mostrando la lucha de las ni\u00f1as por sus derechos<\/strong>, por lograr un presente digno y un futuro lleno de posibilidades.&nbsp;&nbsp;<\/p>\n<p>Concretamente, la exposici\u00f3n se inspira en la vida de <strong>Kim, Mireille, Sima y Michel Ange<\/strong>, cuatro j\u00f3venes de diferentes partes del mundo pero que comparten una <strong>historia en com\u00fan<\/strong>: la de haberse encontrado, enfrentado y superado barreras por el mero hecho de ser ni\u00f1as.<\/p>\n<p>La historia de lucha de las cuatro j\u00f3venes es la demostraci\u00f3n de que, a pesar de las dificultades, se puede salir adelante. Y es que actualmente Kim sigue estudiando en Guatemala y sue\u00f1a con ser locura de radio; Mireille es doctora en un hospital de Malaui; Sima es activista por los derechos de las mujeres en Chad; y Michel Ange juega al f\u00fatbol y sigue estudiando en Hait\u00ed, y se siente igual que el resto de sus compa\u00f1eros y compa\u00f1eras.<br \/>&nbsp;<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/ninas-exo-fondo-amarillo.jpg\" style=\"width: 800px;height: 546px\"><\/p>\n<p>La exposici\u00f3n, adem\u00e1s, profundiza en <strong>datos y cifras sobre la dimensi\u00f3n de la violencia hacia las ni\u00f1as y j\u00f3venes<\/strong>, poniendo en evidencia que se trata de una de las vulneraciones de los derechos humanos m\u00e1s extendida del mundo y propone actividades para que el alumnado a partir de los 10 a\u00f1os pueda reflexionar acerca de las desigualdades que sufren las ni\u00f1as.\u00bfRecuerdas la exposici\u00f3n de La Luz de las Ni\u00f1as?&nbsp;<\/p>\n<p>La exposici\u00f3n La Luz de las Ni\u00f1as, que ha sido visitada ya por m\u00e1s de 200 alumnas y alumnos en distintos colegios de Espa\u00f1a, se convierte ahora en una&nbsp; exposici\u00f3n virtual.&nbsp;<\/p>\n<p>Te proponemos un viaje virtual por los pa\u00edses en los que Entreculturas promueve escuelas seguras para defender y proteger los derechos de las ni\u00f1as y en el que&nbsp; Kim, Mireille, Michel Anche y Sima te guiar\u00e1n para mostrarte c\u00f3mo la educaci\u00f3n ha transformado sus vidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La exposici\u00f3n virtual La Luz de las Ni\u00f1as pone rostro a la realidad que viven 240 millones de ni\u00f1as en todo el mundo y se se inspira en la vida de Kim, Mireille, Sima y Michel Ange, cuatro j\u00f3venes de diferentes partes del mundo pero que comparten una historia en com\u00fan.<\/p>\n","protected":false},"featured_media":4772,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[293],"country":[],"cause":[130],"class_list":["post-4773","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-genero","cause-genero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Inauguramos la exposici\u00f3n virtual de La Luz de las Ni\u00f1as: conoce la historia de Kim, Mireille, Sima y Michel Ange - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inauguramos la exposici\u00f3n virtual de La Luz de las Ni\u00f1as: conoce la historia de Kim, Mireille, Sima y Michel Ange\" \/>\n<meta property=\"og:description\" content=\"La exposici\u00f3n virtual La Luz de las Ni\u00f1as pone rostro a la realidad que viven 240 millones de ni\u00f1as en todo el mundo y se se inspira en la vida de Kim, Mireille, Sima y Michel Ange, cuatro j\u00f3venes de diferentes partes del mundo pero que comparten una historia en com\u00fan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T17:23:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/ninas-exo-fondo-amarillo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1121\" \/>\n\t<meta property=\"og:image:height\" content=\"765\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\\\/\",\"name\":\"Inauguramos la exposici\u00f3n virtual de La Luz de las Ni\u00f1as: conoce la historia de Kim, Mireille, Sima y Michel Ange - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/ninas-exo-fondo-amarillo.jpg\",\"datePublished\":\"2020-06-12T08:29:15+00:00\",\"dateModified\":\"2024-03-06T17:23:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/ninas-exo-fondo-amarillo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/ninas-exo-fondo-amarillo.jpg\",\"width\":1121,\"height\":765},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Inauguramos la exposici\u00f3n virtual de La Luz de las Ni\u00f1as: conoce la historia de Kim, Mireille, Sima y Michel Ange\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Inauguramos la exposici\u00f3n virtual de La Luz de las Ni\u00f1as: conoce la historia de Kim, Mireille, Sima y Michel Ange - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/","og_locale":"fr_FR","og_type":"article","og_title":"Inauguramos la exposici\u00f3n virtual de La Luz de las Ni\u00f1as: conoce la historia de Kim, Mireille, Sima y Michel Ange","og_description":"La exposici\u00f3n virtual La Luz de las Ni\u00f1as pone rostro a la realidad que viven 240 millones de ni\u00f1as en todo el mundo y se se inspira en la vida de Kim, Mireille, Sima y Michel Ange, cuatro j\u00f3venes de diferentes partes del mundo pero que comparten una historia en com\u00fan.","og_url":"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-03-06T17:23:36+00:00","og_image":[{"width":1121,"height":765,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/ninas-exo-fondo-amarillo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/","url":"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/","name":"Inauguramos la exposici\u00f3n virtual de La Luz de las Ni\u00f1as: conoce la historia de Kim, Mireille, Sima y Michel Ange - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/ninas-exo-fondo-amarillo.jpg","datePublished":"2020-06-12T08:29:15+00:00","dateModified":"2024-03-06T17:23:36+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/ninas-exo-fondo-amarillo.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/ninas-exo-fondo-amarillo.jpg","width":1121,"height":765},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/inauguramos-la-exposicion-virtual-de-la-luz-de-las-ninas-conoce-la-historia-de-kim-mireille\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/fr\/noticias\/"},{"@type":"ListItem","position":3,"name":"Inauguramos la exposici\u00f3n virtual de La Luz de las Ni\u00f1as: conoce la historia de Kim, Mireille, Sima y Michel Ange"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/fr\/#website","url":"https:\/\/www.entreculturas.org\/fr\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/fr\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/fr\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia\/4773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media\/4772"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media?parent=4773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/categories?post=4773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/tags?post=4773"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/country?post=4773"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/cause?post=4773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}