{"id":47248,"date":"2026-04-09T19:12:59","date_gmt":"2026-04-09T17:12:59","guid":{"rendered":"https:\/\/www.entreculturas.org\/?post_type=noticia&#038;p=47248"},"modified":"2026-04-10T14:14:31","modified_gmt":"2026-04-10T12:14:31","slug":"25-aniversario-red-solidaria-jovenes","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/","title":{"rendered":"Entreculturas re\u00fane a j\u00f3venes, a la ministra Sira Rego y al director de la AECID Ant\u00f3n Leis en el 25\u00ba aniversario de la RSJ"},"content":{"rendered":"\n<p><strong>M\u00e1s de 16.000 j\u00f3venes han participado desde 2001 en esta iniciativa que impulsa la participaci\u00f3n social en centros educativos y comunidades<\/strong><\/p>\n\n\n\n<p> Desde Entreculturas hemos celebrado en Madrid <strong>el 25\u00ba aniversario de la Red Solidaria de J\u00f3venes<\/strong> (RSJ), una iniciativa que desde 2001 impulsa la participaci\u00f3n de las juventudes en centros educativos y comunidades. A lo largo de estos a\u00f1os, m\u00e1s de 16.000 j\u00f3venes han formado parte de esta red, generando propuestas colectivas en torno a la educaci\u00f3n, la igualdad y la justicia social .<\/p>\n\n\n\n<p>El encuentro, celebrado en Espacio Rastro, ha reunido a j\u00f3venes, antiguas personas participantes, educadoras y representantes institucionales en un espacio de <strong>di\u00e1logo intergeneracional centrado en el papel de las juventudes<\/strong> en la construcci\u00f3n de sociedades m\u00e1s justas y cohesionadas. Durante la jornada, j\u00f3venes de distintos territorios compartieron sus experiencias de participaci\u00f3n y reflexionaron sobre desaf\u00edos actuales como la desinformaci\u00f3n o la polarizaci\u00f3n, as\u00ed como sobre la necesidad de fortalecer espacios colectivos que permitan una implicaci\u00f3n real en la vida social y pol\u00edtica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-participacion-juvenil-en-el-centro-del-debate-publico\">La participaci\u00f3n juvenil, en el centro del debate p\u00fablico<\/h2>\n\n\n\n<p>En el acto ha participado la <strong>ministra de Juventud e Infancia, Sira Rego<\/strong>, quien ha subrayado que \u201cescuchar a las juventudes no puede ser un gesto simb\u00f3lico ni un tr\u00e1mite, sino incorporar esa mirada en la toma de decisiones p\u00fablicas\u201d. En este sentido, ha se\u00f1alado que es necesario \u201ccrear canales estables, accesibles y dotados de recursos para que la participaci\u00f3n de los y las j\u00f3venes sea real\u201d, recordando adem\u00e1s que la futura Ley de Juventud ha sido elaborada con la participaci\u00f3n de miles de j\u00f3venes de todo el pa\u00eds.<\/p>\n\n\n\n<p>Por su parte, <strong>Ant\u00f3n Leis, director de la Agencia Espa\u00f1ola de Cooperaci\u00f3n Internacional para el Desarrollo (AECID)<\/strong>, ha destacado el valor de estos espacios para conectar la participaci\u00f3n juvenil con los desaf\u00edos globales desde la cooperaci\u00f3n internacional, se\u00f1alando que \u201cRedes como la RSJ son el vivero donde se cultiva esa nueva generaci\u00f3n de cooperantes, de funcionariado, de activistas, de periodistas y de responsables pol\u00edticos que entienden la solidaridad como respuesta contempor\u00e1nea a crisis muy complejas\u201d.<\/p>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-container-core-group-is-layout-cc019cf6 wp-block-group-is-layout-constrained\" style=\"margin-bottom:var(--wp--preset--spacing--70);padding-right:20px;padding-left:20px\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-e524df8a wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover hover-fondo-video\" style=\"min-height:334px;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" class=\"wp-block-cover__image-background wp-image-47330 size-large\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/DSC_0333-1024x683.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/DSC_0333-1024x683.jpg 1024w, https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/DSC_0333-300x200.jpg 300w, https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/DSC_0333-768x512.jpg 768w, https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/DSC_0333.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#6e707c\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover is-light hover-fondo-video\" style=\"min-height:334px;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" class=\"wp-block-cover__image-background wp-image-47331 size-large\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/DSC_0276-1024x683.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/DSC_0276-1024x683.jpg 1024w, https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/DSC_0276-300x200.jpg 300w, https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/DSC_0276-768x512.jpg 768w, https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/DSC_0276.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#7c8d92\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cover hover-fondo-video\" style=\"min-height:334px;aspect-ratio:unset;\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" class=\"wp-block-cover__image-background wp-image-47332 size-large\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/Copia-de-DSC_0134-1024x683.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/Copia-de-DSC_0134-1024x683.jpg 1024w, https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/Copia-de-DSC_0134-300x200.jpg 300w, https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/Copia-de-DSC_0134-768x512.jpg 768w, https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/Copia-de-DSC_0134.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#7e7b85\"><\/span><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-block-cover-is-layout-constrained\">\n<p class=\"has-text-align-center has-large-font-size\"><\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-espacios-que-hacen-posible-la-participacion\">Espacios que hacen posible la participaci\u00f3n<\/h2>\n\n\n\n<p>La jornada ha contado tambi\u00e9n con la intervenci\u00f3n de j\u00f3venes participantes en la red. Luana Rodr\u00edguez, de Andaluc\u00eda, ha compartido su experiencia se\u00f1alando que \u201cvivimos en un mundo con muchas desigualdades y <strong>estar aqu\u00ed me hace sentir que, aunque sea desde lo peque\u00f1o, puedo hacer algo<\/strong>. Tambi\u00e9n me motiva mucho el hecho de sentir que mi voz cuenta. No siempre tenemos espacios donde los j\u00f3venes podamos opinar de verdad, proponer ideas o cuestionar cosas, y aqu\u00ed s\u00ed pasa\u201d.<\/p>\n\n\n\n<p>Desde Entreculturas, <strong>Ram\u00f3n Almansa, director ejecutivo, ha puesto el foco en la importancia de la construcci\u00f3n colectiva<\/strong>: \u201cEn un mundo globalizado, tenemos dos opciones: Construir muros o crear RED. Por mucho que nos traten de convencer de lo contrario, los y las j\u00f3venes hoy aqu\u00ed presentes apuestan por lo segundo. Una RED basada en la confianza, el respeto y el amor global.\u201d<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-una-red-que-sigue-creciendo\">Una red que sigue creciendo<\/h2>\n\n\n\n<p>Este 25\u00ba aniversario pone en valor la necesidad de <strong>sostener en el tiempo espacios que permitan a las juventudes implicarse activamente<\/strong> en la transformaci\u00f3n de sus entornos. En un contexto marcado por la desinformaci\u00f3n y la polarizaci\u00f3n, desde Entreculturas subrayamos la importancia de reforzar procesos colectivos que fomenten el pensamiento cr\u00edtico y la construcci\u00f3n de respuestas compartidas.<\/p>\n\n\n\n<p>El aniversario se enmarca adem\u00e1s en una agenda m\u00e1s amplia de encuentros que culminar\u00e1 con el <strong>X Encuentro Global de la Red Solidaria de J\u00f3venes<\/strong>, en el que participar\u00e1n m\u00e1s de 150 j\u00f3venes de distintos pa\u00edses para compartir experiencias y fortalecer redes de participaci\u00f3n a nivel internacional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 16.000 j\u00f3venes han participado desde 2001 en esta iniciativa que impulsa la participaci\u00f3n social en centros educativos y comunidades Desde Entreculturas hemos celebrado en Madrid el 25\u00ba aniversario de la Red Solidaria de J\u00f3venes (RSJ), una iniciativa que desde 2001 impulsa la participaci\u00f3n de las juventudes en centros educativos y comunidades. A lo largo de estos a\u00f1os, m\u00e1s de 16.000 j\u00f3venes han formado parte de esta red, generando propuestas colectivas en torno a la educaci\u00f3n, la igualdad y la justicia social . El encuentro, celebrado en Espacio Rastro, ha reunido a j\u00f3venes, antiguas personas participantes, educadoras y representantes institucionales en un espacio de di\u00e1logo intergeneracional centrado en el papel de las juventudes en la construcci\u00f3n de sociedades m\u00e1s justas y cohesionadas. Durante la jornada, j\u00f3venes de distintos territorios compartieron sus experiencias de participaci\u00f3n y reflexionaron sobre desaf\u00edos actuales como la desinformaci\u00f3n o la polarizaci\u00f3n, as\u00ed como sobre la [&hellip;]<\/p>\n","protected":false},"featured_media":47250,"template":"","meta":{"_acf_changed":false},"categories":[7],"tags":[8],"country":[120],"cause":[132],"class_list":["post-47248","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-participacion-y-ciudadania-global","country-espana","cause-participacion-y-ciudadania-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>25\u00ba aniversario de la RSJ: J\u00f3venes y la ministra Riego en Madrid<\/title>\n<meta name=\"description\" content=\"Celebramos el 25\u00ba aniversario de la Red Solidaria de J\u00f3venes con un evento con j\u00f3venes y la ministra de Juventud, Sira Riego.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entreculturas re\u00fane a j\u00f3venes, a la ministra Sira Rego y al director de la AECID Ant\u00f3n Leis en el 25\u00ba aniversario de la RSJ\" \/>\n<meta property=\"og:description\" content=\"Celebramos el 25\u00ba aniversario de la Red Solidaria de J\u00f3venes con un evento con j\u00f3venes y la ministra de Juventud, Sira Riego.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-10T12:14:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/Menos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/25-aniversario-red-solidaria-jovenes\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/25-aniversario-red-solidaria-jovenes\\\/\",\"name\":\"25\u00ba aniversario de la RSJ: J\u00f3venes y la ministra Riego en Madrid\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/25-aniversario-red-solidaria-jovenes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/25-aniversario-red-solidaria-jovenes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Menos.jpg\",\"datePublished\":\"2026-04-09T17:12:59+00:00\",\"dateModified\":\"2026-04-10T12:14:31+00:00\",\"description\":\"Celebramos el 25\u00ba aniversario de la Red Solidaria de J\u00f3venes con un evento con j\u00f3venes y la ministra de Juventud, Sira Riego.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/25-aniversario-red-solidaria-jovenes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/25-aniversario-red-solidaria-jovenes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/25-aniversario-red-solidaria-jovenes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Menos.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Menos.jpg\",\"width\":800,\"height\":533,\"caption\":\"Acto 25\u00ba Aniversario\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/25-aniversario-red-solidaria-jovenes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Entreculturas re\u00fane a j\u00f3venes, a la ministra Sira Rego y al director de la AECID Ant\u00f3n Leis en el 25\u00ba aniversario de la RSJ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"25\u00ba aniversario de la RSJ: J\u00f3venes y la ministra Riego en Madrid","description":"Celebramos el 25\u00ba aniversario de la Red Solidaria de J\u00f3venes con un evento con j\u00f3venes y la ministra de Juventud, Sira Riego.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/","og_locale":"fr_FR","og_type":"article","og_title":"Entreculturas re\u00fane a j\u00f3venes, a la ministra Sira Rego y al director de la AECID Ant\u00f3n Leis en el 25\u00ba aniversario de la RSJ","og_description":"Celebramos el 25\u00ba aniversario de la Red Solidaria de J\u00f3venes con un evento con j\u00f3venes y la ministra de Juventud, Sira Riego.","og_url":"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2026-04-10T12:14:31+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/Menos.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/","url":"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/","name":"25\u00ba aniversario de la RSJ: J\u00f3venes y la ministra Riego en Madrid","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/Menos.jpg","datePublished":"2026-04-09T17:12:59+00:00","dateModified":"2026-04-10T12:14:31+00:00","description":"Celebramos el 25\u00ba aniversario de la Red Solidaria de J\u00f3venes con un evento con j\u00f3venes y la ministra de Juventud, Sira Riego.","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/Menos.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/04\/Menos.jpg","width":800,"height":533,"caption":"Acto 25\u00ba Aniversario"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/25-aniversario-red-solidaria-jovenes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/fr\/noticias\/"},{"@type":"ListItem","position":3,"name":"Entreculturas re\u00fane a j\u00f3venes, a la ministra Sira Rego y al director de la AECID Ant\u00f3n Leis en el 25\u00ba aniversario de la RSJ"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/fr\/#website","url":"https:\/\/www.entreculturas.org\/fr\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/fr\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/fr\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia\/47248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media\/47250"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media?parent=47248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/categories?post=47248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/tags?post=47248"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/country?post=47248"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/cause?post=47248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}