{"id":2768,"date":"2019-02-26T10:13:23","date_gmt":"2019-02-26T10:13:23","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=ser-madre-desplazada-en-la-frontera-colombo-venezolana"},"modified":"2024-02-09T12:44:19","modified_gmt":"2024-02-09T11:44:19","slug":"ser-madre-desplazada-en-la-frontera-colombo-venezolana","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/","title":{"rendered":"Ser madre desplazada en la frontera colombo-venezolana"},"content":{"rendered":"<p><strong><em>Cuando llegamos, no ten\u00edamos cama, colch\u00f3n. Yo dorm\u00ed mis primeros 5 meses del embarazo en el suelo, en el piso; el espacio era muy chiquito y ten\u00edamos que dormir ah\u00ed todos juntos, al lado del otro, y ah\u00ed mismo estaba la cocina, el ba\u00f1o, bueno, ah\u00ed medio dividimos la cosa. Estuve 5 meses ah\u00ed de los 8 que tengo de embarazo.<\/em><\/strong><\/p>\n<p>Son las palabras de una de las mujeres que atiende el&nbsp; Servicio Jesuita a Refugiados (JRS) en Norte de Santander, departamento colombiano que linda con Venezuela, a trav\u00e9s de nuestro programa \u00ab\u00a0En las Fronteras de Colombia\u00a0\u00bb, una zona cuya realidad migratoria contiene muchos elementos claves para comprender lo que, en realidad, es una <strong>profunda crisis humanitaria con distintas fuentes<\/strong>. Por un lado la crisis bebe, desde el a\u00f1o 2017, del inicio de la implementaci\u00f3n de los Acuerdos de Paz entre el Gobierno Nacional de Colombia y las FARC-EP, en <strong>un pa\u00eds polarizado donde la violencia va tomando nuevas formas pero no se reduce<\/strong>. Y por otro, bebe del recrudecimiento de la situaci\u00f3n pol\u00edtica y econ\u00f3mica en Venezuela, que est\u00e1 generando que un gran n\u00famero de personas se encuentren en situaci\u00f3n de extrema <strong>vulnerabilidad y riesgo social<\/strong>, tanto dentro como fuera de las fronteras.<br \/>&nbsp;<\/p>\n<p>La frontera es puente de uni\u00f3n, pero progresivamente se ha convertido en un espacio en el que se vulneran los derechos de las personas desplazadas y, tambi\u00e9n, los de la poblaci\u00f3n de acogida, que vive en una situaci\u00f3n de desprotecci\u00f3n profunda. <strong>Las mujeres son las principales v\u00edctimas de esta situaci\u00f3n<\/strong>, porque son forzadas a huir o desplazarse a lugares donde no hay alternativas productivas para ellas, ni oportunidades de acceso a la educaci\u00f3n para sus hijos. De ellas, las mujeres gestantes y lactantes que han migrado se encuentran en una situaci\u00f3n de especial vulnerabilidad: desprotegidas por su situaci\u00f3n de irregularidad y sin la posibilidad de acceder a los servicios que cubren necesidades b\u00e1sicas.&nbsp;<\/p>\n<p>\u201cEsto ha cambiado mi vida, pues ha sido dif\u00edcil dejar lo poco que tenemos y llegar a la deriva y embarazada\u00a0\u00bb, explica otra de las mujeres atendidas por el Servicio Jesuita a Refugiados (JRS) en Norte de Santander. \u00ab\u00a0Aunque vinimos con la mente preparada para pasar por lo que tengamos que pasar&#8230; porque aqu\u00ed hay m\u00e1s posibilidades que en Venezuela\u201d.<\/p>\n<p>Muchas de las mujeres que se atienden&nbsp;en la zona huyen del miedo y la violencia de su lugar de origen, de la violencia de g\u00e9nero que la mayor\u00eda sufre, y viven un estr\u00e9s emocional por la desintegraci\u00f3n familiar y el cambio de roles durante el desplazamiento. Son mujeres que han puesto a prueba su&nbsp; <strong>capacidad de resiliencia<\/strong>, buscando salir adelante a pesar de las diversas adversidades que han encontrado en su camino, poniendo en riesgo su integridad y la de sus familias. A esta situaci\u00f3n, se suman los distintos problemas de salud que afectan a las mujeres embarazadas y lactantes y a sus hijos.&nbsp;<\/p>\n<p>JRS les presta atenci\u00f3n desde un acercamiento hospitalario y de acogida, ofreci\u00e9ndoles asesor\u00eda jur\u00eddica para exigir sus derechos, acompa\u00f1amiento en procesos psicosociales, asistencia humanitaria, acceso a controles prenatales y acceso a ciertos tipos de medicamentos.&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"533\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/noticia-colombia1.jpg\" width=\"800\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la frontera de Colombia con Venezuela, apoyamos la intervenci\u00f3n del JRS que presta atenci\u00f3n hospitalaria y de acogida, asesor\u00eda jur\u00eddica, acompa\u00f1amiento en procesos psicosociales, asistencia humanitaria, acceso a controles prenatales y acceso a medicamentos a la poblaci\u00f3n desplazada.<\/p>\n","protected":false},"featured_media":2764,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[10],"country":[140,127],"cause":[129],"class_list":["post-2768","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-migracion-y-refugio","country-colombia","country-venezuela","cause-migracion-y-refugio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ser madre desplazada en la frontera colombo-venezolana - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ser madre desplazada en la frontera colombo-venezolana\" \/>\n<meta property=\"og:description\" content=\"En la frontera de Colombia con Venezuela, apoyamos la intervenci\u00f3n del JRS que presta atenci\u00f3n hospitalaria y de acogida, asesor\u00eda jur\u00eddica, acompa\u00f1amiento en procesos psicosociales, asistencia humanitaria, acceso a controles prenatales y acceso a medicamentos a la poblaci\u00f3n desplazada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T11:44:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/noticia-colombia2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\\\/\",\"name\":\"Ser madre desplazada en la frontera colombo-venezolana - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/noticia-colombia2.jpg\",\"datePublished\":\"2019-02-26T10:13:23+00:00\",\"dateModified\":\"2024-02-09T11:44:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/noticia-colombia2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/noticia-colombia2.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ser madre desplazada en la frontera colombo-venezolana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ser madre desplazada en la frontera colombo-venezolana - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/","og_locale":"fr_FR","og_type":"article","og_title":"Ser madre desplazada en la frontera colombo-venezolana","og_description":"En la frontera de Colombia con Venezuela, apoyamos la intervenci\u00f3n del JRS que presta atenci\u00f3n hospitalaria y de acogida, asesor\u00eda jur\u00eddica, acompa\u00f1amiento en procesos psicosociales, asistencia humanitaria, acceso a controles prenatales y acceso a medicamentos a la poblaci\u00f3n desplazada.","og_url":"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-09T11:44:19+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/noticia-colombia2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/","url":"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/","name":"Ser madre desplazada en la frontera colombo-venezolana - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/noticia-colombia2.jpg","datePublished":"2019-02-26T10:13:23+00:00","dateModified":"2024-02-09T11:44:19+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/noticia-colombia2.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/noticia-colombia2.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/ser-madre-desplazada-en-la-frontera-colombo-venezolana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/fr\/noticias\/"},{"@type":"ListItem","position":3,"name":"Ser madre desplazada en la frontera colombo-venezolana"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/fr\/#website","url":"https:\/\/www.entreculturas.org\/fr\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/fr\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/fr\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia\/2768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media\/2764"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media?parent=2768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/categories?post=2768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/tags?post=2768"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/country?post=2768"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/cause?post=2768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}