{"id":2721,"date":"2019-02-09T23:00:00","date_gmt":"2019-02-09T23:00:00","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas"},"modified":"2024-02-09T11:44:21","modified_gmt":"2024-02-09T10:44:21","slug":"3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/","title":{"rendered":"3.500 personas han corrido en Madrid contra la violencia hacia las ni\u00f1as"},"content":{"rendered":"<p>Hoy hemos celebrado en Madrid la VIII edici\u00f3n de la Carrera Solidaria \u201cCorre por una causa, corre por la educaci\u00f3n\u201d. A las 9:30 horas en la Casa de Campo de Madrid cerca 3.500 personas han corrido para visibilizar las desigualdades que sufren las ni\u00f1as.<\/p>\n<p>Es la octava edici\u00f3n de esta carrera que en los a\u00f1os anteriores reuni\u00f3 a m\u00e1s de <strong>16.200 participantes<\/strong> y que tiene como objetivo <strong>sensibilizar a la poblaci\u00f3n espa\u00f1ola sobre la importancia de que todas las personas puedan tener una educaci\u00f3n de calidad y un presente y futuro digno<\/strong>. Cada a\u00f1o, los fondos recaudados con las inscripciones y las empresas colaboradoras se destinan a un proyecto educativo de Entreculturas en un pa\u00eds de Am\u00e9rica Latina o de \u00c1frica.<\/p>\n<p>A trav\u00e9s del circuito de carreras solidarias \u201cCorre por una Causa\u201d, en esta edici\u00f3n recaudamos fondos para visibilizar las desigualdades que sufren las ni\u00f1as, protegerlas frente a la violencia, valorar su capacidad para elegir su futuro e incidir para transformar las causas de la injusticia hacia ellas. Seg\u00fan Raquel Mart\u00edn, nuestra Directora de Comunicaci\u00f3n y Desarrollo Institucional, \u201cqueremos que brille su luz. Las ni\u00f1as tienen derecho a una infancia en igualdad de oportunidades, libre de miedos, de amenazas y agresiones. La educaci\u00f3n puede defenderlas, proteger sus derechos, transformar sus vidas\u201d.&nbsp;<\/p>\n<p>Hoy en d\u00eda l<strong>a violencia niega el derecho a la educaci\u00f3n a millones de ni\u00f1as de todo el mundo<\/strong>: contin\u00faa siendo una de las violaciones m\u00e1s persistentes, sistem\u00e1ticas y generalizadas de los derechos humanos. No hablamos de an\u00e9cdotas: 240 millones de ni\u00f1as ven amenazada su vida por la violencia, m\u00e1s de 200 millones de ni\u00f1as en el mundo han sufrido mutilaci\u00f3n genital. Cada a\u00f1o 12 millones de ni\u00f1as son casadas antes de cumplir los 18. M\u00e1s de 150 millones sufren violencia sexual. Y 34,2 millones de ni\u00f1as y mujeres son refugiadas o desplazadas. La mayor\u00eda de ni\u00f1as en el mundo se ven obligadas a realizar tareas del hogar como cocinar, ir a buscar le\u00f1a, agua o quedarse al cargo de sus hermanos peque\u00f1os. Estas formas de violencia hacia las ni\u00f1as provocan en ellas graves secuelas psicol\u00f3gicas, f\u00edsicas y sociales que las marcan para siempre, y las aleja de la escuela, de su infancia y de sus oportunidades.&nbsp;<\/p>\n<p>Este a\u00f1o los fondos recaudados ir\u00e1n destinados al programa <a href=\"https:\/\/www.laluzdelasninas.org\" target=\"_blank\" rel=\"noopener\">\u201cLa Luz de las ni\u00f1as\u201d<\/a> que desde 2012 y en 15 pa\u00edses se ha<strong> atendido a 32.747 ni\u00f1as<\/strong>. Actualmente, en 2019, est\u00e1n participando en el Programa 12.700 ni\u00f1as de 11 pa\u00edses (RD Congo, Rep\u00fablica Centroafricana, Sud\u00e1n del Sur, Chad, Kenia, Guatemala, Nicaragua, Hait\u00ed, El Salvador, Honduras, Per\u00fa).<\/p>\n<p>En tres l\u00edneas de acci\u00f3n:<\/p>\n<ul>\n<li>Fomentando su acceso y la permanencia escolar,<\/li>\n<li>Previniendo, detectando, atendiendo y denunciando la violencia contra las ni\u00f1as<\/li>\n<li>Ofreciendo rehabilitaci\u00f3n psicol\u00f3gica y social a las ni\u00f1as v\u00edctimas de violencia, mejorando su autoestima y realizando actividades de formaci\u00f3n e integraci\u00f3n.<\/li>\n<\/ul>\n<p>Adem\u00e1s, \u201cCorre por una Causa\u201d cuenta con la colaboraci\u00f3n de Liferay, Mapfre, Deloitte y Melod\u00eda FM como empresas patrocinadoras que dan su apoyo a este evento deportivo y solidario con las ni\u00f1as que m\u00e1s lo necesitan. Asimismo, m\u00e1s de 200 colaboradores apoyan el circuito de carreras solidarias a trav\u00e9s de compra de dorsales, cesi\u00f3n de producto y voluntariado corporativo.&nbsp; Por \u00faltimo, cada a\u00f1o se incorporan m\u00e1s de 100 colegios, institutos y universidades que participan en esta iniciativa en el marco de sus actividades deportivas y solidarias. Aquellos interesados en participar en las carreras solidarias de Entreculturas pueden elegir su ciudad e inscribirse a trav\u00e9s de la web: <a href=\"https:\/\/www.correporunacausa.org\/\" target=\"_blank\" rel=\"noopener\">correporunacasusa.org<\/a>.<\/p>\n<p>Adem\u00e1s todos los participantes tendr\u00e1n una promoci\u00f3n Especial con el Parque Atracciones para todas las personas participantes: 50% descuento para corredor y 3 acompa\u00f1antes, v\u00e1lido para s\u00e1bados y domingos de Febrero y Marzo de 2019.<\/p>\n<p><a href=\"https:\/\/www.flickr.com\/photos\/entreculturas\/albums\/72157706572303005\" target=\"_blank\" rel=\"noopener\"><span style=\"color:#ff0101\"><strong>ACCEDE A LA FOTOGALER\u00cdA.<\/strong><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy hemos celebrado en Madrid la VIII edici\u00f3n de la Carrera Solidaria \u201cCorre por una causa, corre por la educaci\u00f3n\u201d.  Cerca 3.500 personas han corrido para visibilizar las desigualdades que sufren las ni\u00f1as y apoyar nuestro programa La Luz de las Ni\u00f1as, en el que desde 2012 y en 15 pa\u00edses se ha atendido a 32.747 ni\u00f1as.<\/p>\n","protected":false},"featured_media":2720,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[293],"country":[120],"cause":[130],"class_list":["post-2721","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-genero","country-espana","cause-genero"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>3.500 personas han corrido en Madrid contra la violencia hacia las ni\u00f1as - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3.500 personas han corrido en Madrid contra la violencia hacia las ni\u00f1as\" \/>\n<meta property=\"og:description\" content=\"Hoy hemos celebrado en Madrid la VIII edici\u00f3n de la Carrera Solidaria \u201cCorre por una causa, corre por la educaci\u00f3n\u201d. Cerca 3.500 personas han corrido para visibilizar las desigualdades que sufren las ni\u00f1as y apoyar nuestro programa La Luz de las Ni\u00f1as, en el que desde 2012 y en 15 pa\u00edses se ha atendido a 32.747 ni\u00f1as.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T10:44:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/carrera-madraid-baja.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"526\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\\\/\",\"name\":\"3.500 personas han corrido en Madrid contra la violencia hacia las ni\u00f1as - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/carrera-madraid-baja.jpg\",\"datePublished\":\"2019-02-09T23:00:00+00:00\",\"dateModified\":\"2024-02-09T10:44:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/carrera-madraid-baja.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/carrera-madraid-baja.jpg\",\"width\":800,\"height\":526},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticia\\\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"3.500 personas han corrido en Madrid contra la violencia hacia las ni\u00f1as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"3.500 personas han corrido en Madrid contra la violencia hacia las ni\u00f1as - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/","og_locale":"fr_FR","og_type":"article","og_title":"3.500 personas han corrido en Madrid contra la violencia hacia las ni\u00f1as","og_description":"Hoy hemos celebrado en Madrid la VIII edici\u00f3n de la Carrera Solidaria \u201cCorre por una causa, corre por la educaci\u00f3n\u201d. Cerca 3.500 personas han corrido para visibilizar las desigualdades que sufren las ni\u00f1as y apoyar nuestro programa La Luz de las Ni\u00f1as, en el que desde 2012 y en 15 pa\u00edses se ha atendido a 32.747 ni\u00f1as.","og_url":"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-09T10:44:21+00:00","og_image":[{"width":800,"height":526,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/carrera-madraid-baja.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/","url":"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/","name":"3.500 personas han corrido en Madrid contra la violencia hacia las ni\u00f1as - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/carrera-madraid-baja.jpg","datePublished":"2019-02-09T23:00:00+00:00","dateModified":"2024-02-09T10:44:21+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/carrera-madraid-baja.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/02\/carrera-madraid-baja.jpg","width":800,"height":526},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/fr\/noticia\/3500-personas-han-corrido-en-madrid-contra-la-violencia-hacia-las-ninas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/fr\/noticias\/"},{"@type":"ListItem","position":3,"name":"3.500 personas han corrido en Madrid contra la violencia hacia las ni\u00f1as"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/fr\/#website","url":"https:\/\/www.entreculturas.org\/fr\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/fr\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/fr\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia\/2721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media\/2720"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media?parent=2721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/categories?post=2721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/tags?post=2721"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/country?post=2721"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/cause?post=2721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}