{"id":23723,"date":"2024-04-10T14:28:12","date_gmt":"2024-04-10T12:28:12","guid":{"rendered":"https:\/\/www.entreculturas.org\/?post_type=ficha&#038;p=23723"},"modified":"2024-04-10T14:33:12","modified_gmt":"2024-04-10T12:33:12","slug":"ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid","status":"publish","type":"ficha","link":"https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/","title":{"rendered":"Ni\u00f1as, ni\u00f1os y adolescentes de 7 comunidades vulnerables de El Salvador ejercen su derecho a una educaci\u00f3n de calidad con equidad de g\u00e9nero en respuesta a la emergencia educativa generado por el COVID-19"},"content":{"rendered":"\n<p>Fortalecer las capacidades para abordar las desigualdades educativas generadas por la pandemia es esencial. Contar con mecanismos de protecci\u00f3n escolar para estudiantes en condiciones de mayor vulnerabilidad es crucial, ya que les permitir\u00eda desarrollarse integralmente.<br>Asimismo, es necesario que las familias cuenten con las condiciones adecuadas para acompa\u00f1ar el proceso educativo de sus hijos e hijas<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fortalecer las capacidades para abordar las desigualdades educativas generadas por la pandemia es esencial. Contar con mecanismos de protecci\u00f3n escolar para estudiantes en condiciones de mayor vulnerabilidad es crucial, ya que les permitir\u00eda desarrollarse integralmente.Asimismo, es necesario que las familias cuenten con las condiciones adecuadas para acompa\u00f1ar el proceso educativo de sus hijos e hijas<\/p>\n","protected":false},"featured_media":20552,"template":"","country":[322],"cause":[],"link-pdf":[],"anio":[],"class_list":["post-23723","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","country-el-salvador"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ni\u00f1as, ni\u00f1os y adolescentes de 7 comunidades vulnerables de El Salvador ejercen su derecho a una educaci\u00f3n de calidad con equidad de g\u00e9nero en respuesta a la emergencia educativa generado por el COVID-19 - Entreculturas<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ni\u00f1as, ni\u00f1os y adolescentes de 7 comunidades vulnerables de El Salvador ejercen su derecho a una educaci\u00f3n de calidad con equidad de g\u00e9nero en respuesta a la emergencia educativa generado por el COVID-19\" \/>\n<meta property=\"og:description\" content=\"Fortalecer las capacidades para abordar las desigualdades educativas generadas por la pandemia es esencial. Contar con mecanismos de protecci\u00f3n escolar para estudiantes en condiciones de mayor vulnerabilidad es crucial, ya que les permitir\u00eda desarrollarse integralmente.Asimismo, es necesario que las familias cuenten con las condiciones adecuadas para acompa\u00f1ar el proceso educativo de sus hijos e hijas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-10T12:33:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png\" \/>\n\t<meta property=\"og:image:width\" content=\"585\" \/>\n\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/ficha\\\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/ficha\\\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\\\/\",\"name\":\"Ni\u00f1as, ni\u00f1os y adolescentes de 7 comunidades vulnerables de El Salvador ejercen su derecho a una educaci\u00f3n de calidad con equidad de g\u00e9nero en respuesta a la emergencia educativa generado por el COVID-19 - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/ficha\\\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/ficha\\\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/placeholder04.png\",\"datePublished\":\"2024-04-10T12:28:12+00:00\",\"dateModified\":\"2024-04-10T12:33:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/ficha\\\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/ficha\\\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/ficha\\\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/placeholder04.png\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/placeholder04.png\",\"width\":585,\"height\":699,\"caption\":\"corazon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/ficha\\\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ni\u00f1as, ni\u00f1os y adolescentes de 7 comunidades vulnerables de El Salvador ejercen su derecho a una educaci\u00f3n de calidad con equidad de g\u00e9nero en respuesta a la emergencia educativa generado por el COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ni\u00f1as, ni\u00f1os y adolescentes de 7 comunidades vulnerables de El Salvador ejercen su derecho a una educaci\u00f3n de calidad con equidad de g\u00e9nero en respuesta a la emergencia educativa generado por el COVID-19 - Entreculturas","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Ni\u00f1as, ni\u00f1os y adolescentes de 7 comunidades vulnerables de El Salvador ejercen su derecho a una educaci\u00f3n de calidad con equidad de g\u00e9nero en respuesta a la emergencia educativa generado por el COVID-19","og_description":"Fortalecer las capacidades para abordar las desigualdades educativas generadas por la pandemia es esencial. Contar con mecanismos de protecci\u00f3n escolar para estudiantes en condiciones de mayor vulnerabilidad es crucial, ya que les permitir\u00eda desarrollarse integralmente.Asimismo, es necesario que las familias cuenten con las condiciones adecuadas para acompa\u00f1ar el proceso educativo de sus hijos e hijas","og_url":"https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-04-10T12:33:12+00:00","og_image":[{"width":585,"height":699,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/","url":"https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/","name":"Ni\u00f1as, ni\u00f1os y adolescentes de 7 comunidades vulnerables de El Salvador ejercen su derecho a una educaci\u00f3n de calidad con equidad de g\u00e9nero en respuesta a la emergencia educativa generado por el COVID-19 - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","datePublished":"2024-04-10T12:28:12+00:00","dateModified":"2024-04-10T12:33:12+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","width":585,"height":699,"caption":"corazon"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/fr\/ficha\/ninas-ninos-y-adolescentes-de-7-comunidades-vulnerables-de-el-salvador-ejercen-su-derecho-a-una-educacion-de-calidad-con-equidad-de-genero-en-respuesta-a-la-emergencia-educativa-generado-por-el-covid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Ni\u00f1as, ni\u00f1os y adolescentes de 7 comunidades vulnerables de El Salvador ejercen su derecho a una educaci\u00f3n de calidad con equidad de g\u00e9nero en respuesta a la emergencia educativa generado por el COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/fr\/#website","url":"https:\/\/www.entreculturas.org\/fr\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/fr\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/fr\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/ficha\/23723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/types\/ficha"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media\/20552"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/media?parent=23723"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/country?post=23723"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/cause?post=23723"},{"taxonomy":"link-pdf","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/link-pdf?post=23723"},{"taxonomy":"anio","embeddable":true,"href":"https:\/\/www.entreculturas.org\/fr\/wp-json\/wp\/v2\/anio?post=23723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}