{"id":5436,"date":"2019-09-25T15:12:36","date_gmt":"2019-09-25T15:12:36","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?publicaciones=informe-anual-entreculturas-2018"},"modified":"2024-08-06T11:03:22","modified_gmt":"2024-08-06T09:03:22","slug":"informe-anual-entreculturas-2018","status":"publish","type":"publicacion","link":"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/","title":{"rendered":"Informe Anual Entreculturas 2018"},"content":{"rendered":"<p>En 2018, apoyamos el derecho a la educaci\u00f3n, la dignidad y la justicia a trav\u00e9s de\u00a0159 proyectos, atendiendo a\u00a0184.269 en 37 pa\u00edses.\u00a0<\/p>\n<p>El Congreso Internacional de Fe y Alegr\u00eda, las palabras de Arturo Sosa en su discurso de apertura, el no conformarnos y pensar siempre en c\u00f3mo hacer las cosas mejor, plantearnos constantemente d\u00f3nde est\u00e1 la urgencia, qui\u00e9n es la prioridad, acompa\u00f1ar a quienes huyen, hacernos parte de las caravanas de migrantes, del sufrir de la gente en Venezuela, en Honduras, en El Salvador, Nicaragua o Colombia&#8230;<\/p>\n<p>El ponernos de lado de aquellos a quienes se aparta, de los colectivos cuyos derechos se vulneran especialmente, de los pueblos ind\u00edgenas, de las mujeres, de las ni\u00f1as&#8230; y encontrar en su lucha una luz, como la de Kim, como la de Ronaldine, que nos siga inspirando y nos demuestre que vale la pena combatir las amenazas y el miedo. Todo esto es, en grandes pinceladas, lo que podr\u00eda definir nuestra labor durante 2018.\u00a0<\/p>\n<p>GRACIAS POR SER PARTE DE ELLO.<\/p>\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/08\/InformeAnual2018.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">descargar<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En 2018, apoyamos el derecho a la educaci\u00f3n, la dignidad y la justicia a trav\u00e9s de\u00a0159 proyectos, atendiendo a\u00a0184.269 en 37 pa\u00edses.\u00a0 El Congreso Internacional de Fe y Alegr\u00eda, las palabras de Arturo Sosa en su discurso de apertura, el no conformarnos y pensar siempre en c\u00f3mo hacer las cosas mejor, plantearnos constantemente d\u00f3nde est\u00e1 la urgencia, qui\u00e9n es la prioridad, acompa\u00f1ar a quienes huyen, hacernos parte de las caravanas de migrantes, del sufrir de la gente en Venezuela, en Honduras, en El Salvador, Nicaragua o Colombia&#8230; El ponernos de lado de aquellos a quienes se aparta, de los colectivos cuyos derechos se vulneran especialmente, de los pueblos ind\u00edgenas, de las mujeres, de las ni\u00f1as&#8230; y encontrar en su lucha una luz, como la de Kim, como la de Ronaldine, que nos siga inspirando y nos demuestre que vale la pena combatir las amenazas y el miedo. Todo esto es, [&hellip;]<\/p>\n","protected":false},"featured_media":5437,"template":"","format":[114],"categories":[16],"tags":[185],"cause":[128,131,129,132],"class_list":["post-5436","publicacion","type-publicacion","status-publish","has-post-thumbnail","hentry","category-memorias","tag-entreculturas","cause-educacion","cause-justicia-medioambiental","cause-migracion-y-refugio","cause-participacion-y-ciudadania-global","format-memorias-anuales"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Informe Anual Entreculturas 2018 - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informe Anual Entreculturas 2018\" \/>\n<meta property=\"og:description\" content=\"En 2018, apoyamos el derecho a la educaci\u00f3n, la dignidad y la justicia a trav\u00e9s de\u00a0159 proyectos, atendiendo a\u00a0184.269 en 37 pa\u00edses.\u00a0 El Congreso Internacional de Fe y Alegr\u00eda, las palabras de Arturo Sosa en su discurso de apertura, el no conformarnos y pensar siempre en c\u00f3mo hacer las cosas mejor, plantearnos constantemente d\u00f3nde est\u00e1 la urgencia, qui\u00e9n es la prioridad, acompa\u00f1ar a quienes huyen, hacernos parte de las caravanas de migrantes, del sufrir de la gente en Venezuela, en Honduras, en El Salvador, Nicaragua o Colombia&#8230; El ponernos de lado de aquellos a quienes se aparta, de los colectivos cuyos derechos se vulneran especialmente, de los pueblos ind\u00edgenas, de las mujeres, de las ni\u00f1as&#8230; y encontrar en su lucha una luz, como la de Kim, como la de Ronaldine, que nos siga inspirando y nos demuestre que vale la pena combatir las amenazas y el miedo. Todo esto es, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-06T09:03:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/09\/captura_de_pantalla_2019-09-25_a_las_14.21.00.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1172\" \/>\n\t<meta property=\"og:image:height\" content=\"823\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/publicacion\\\/informe-anual-entreculturas-2018\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/publicacion\\\/informe-anual-entreculturas-2018\\\/\",\"name\":\"Informe Anual Entreculturas 2018 - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/publicacion\\\/informe-anual-entreculturas-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/publicacion\\\/informe-anual-entreculturas-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/captura_de_pantalla_2019-09-25_a_las_14.21.00.png\",\"datePublished\":\"2019-09-25T15:12:36+00:00\",\"dateModified\":\"2024-08-06T09:03:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/publicacion\\\/informe-anual-entreculturas-2018\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/publicacion\\\/informe-anual-entreculturas-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/publicacion\\\/informe-anual-entreculturas-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/captura_de_pantalla_2019-09-25_a_las_14.21.00.png\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/captura_de_pantalla_2019-09-25_a_las_14.21.00.png\",\"width\":1172,\"height\":823,\"caption\":\"captura_de_pantalla_2019-09-25_a_las_14\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/publicacion\\\/informe-anual-entreculturas-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Publicaciones\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/publicaciones\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Informe Anual Entreculturas 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Informe Anual Entreculturas 2018 - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/","og_locale":"en_US","og_type":"article","og_title":"Informe Anual Entreculturas 2018","og_description":"En 2018, apoyamos el derecho a la educaci\u00f3n, la dignidad y la justicia a trav\u00e9s de\u00a0159 proyectos, atendiendo a\u00a0184.269 en 37 pa\u00edses.\u00a0 El Congreso Internacional de Fe y Alegr\u00eda, las palabras de Arturo Sosa en su discurso de apertura, el no conformarnos y pensar siempre en c\u00f3mo hacer las cosas mejor, plantearnos constantemente d\u00f3nde est\u00e1 la urgencia, qui\u00e9n es la prioridad, acompa\u00f1ar a quienes huyen, hacernos parte de las caravanas de migrantes, del sufrir de la gente en Venezuela, en Honduras, en El Salvador, Nicaragua o Colombia&#8230; El ponernos de lado de aquellos a quienes se aparta, de los colectivos cuyos derechos se vulneran especialmente, de los pueblos ind\u00edgenas, de las mujeres, de las ni\u00f1as&#8230; y encontrar en su lucha una luz, como la de Kim, como la de Ronaldine, que nos siga inspirando y nos demuestre que vale la pena combatir las amenazas y el miedo. Todo esto es, [&hellip;]","og_url":"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-08-06T09:03:22+00:00","og_image":[{"width":1172,"height":823,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/09\/captura_de_pantalla_2019-09-25_a_las_14.21.00.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/","url":"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/","name":"Informe Anual Entreculturas 2018 - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/09\/captura_de_pantalla_2019-09-25_a_las_14.21.00.png","datePublished":"2019-09-25T15:12:36+00:00","dateModified":"2024-08-06T09:03:22+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/09\/captura_de_pantalla_2019-09-25_a_las_14.21.00.png","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2019\/09\/captura_de_pantalla_2019-09-25_a_las_14.21.00.png","width":1172,"height":823,"caption":"captura_de_pantalla_2019-09-25_a_las_14"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/en\/publicacion\/informe-anual-entreculturas-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/en\/"},{"@type":"ListItem","position":2,"name":"Publicaciones","item":"https:\/\/www.entreculturas.org\/en\/publicaciones\/"},{"@type":"ListItem","position":3,"name":"Informe Anual Entreculturas 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/en\/#website","url":"https:\/\/www.entreculturas.org\/en\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/en\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/en\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/publicacion\/5436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/publicacion"}],"about":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/types\/publicacion"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media\/5437"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media?parent=5436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/categories?post=5436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/tags?post=5436"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/cause?post=5436"},{"taxonomy":"format","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/format?post=5436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}