{"id":46201,"date":"2026-02-11T14:42:08","date_gmt":"2026-02-11T13:42:08","guid":{"rendered":"https:\/\/www.entreculturas.org\/?post_type=podcast&#038;p=46201"},"modified":"2026-02-11T14:49:07","modified_gmt":"2026-02-11T13:49:07","slug":"julia-navarro-podcast-ong-regularizacion-migrante","status":"publish","type":"podcast","link":"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/","title":{"rendered":"Julia Navarro conversa con Nico Castellano: \u201cLas personas migrantes no son pobrecitos, son personas con derechos\u201d"},"content":{"rendered":"\n<p>Esta semana en el podcast de <em><a href=\"https:\/\/www.entreculturas.org\/podcast\/\">Voces por una Causa<\/a><\/em>, <strong>la escritora Julia Navarro conversa con Nico Castellano, periodista de la <a href=\"https:\/\/cadenaser.com\/\">Cadena SER<\/a><\/strong> y una de las voces m\u00e1s reconocidas en Espa\u00f1a en la cobertura informativa sobre migraciones y derechos humanos. Con \u00e9l, Julia Navarro nos acerca a la situaci\u00f3n actual de las migraciones en Espa\u00f1a, al debate p\u00fablico en torno a la reciente regularizaci\u00f3n extraordinaria de personas migrantes y a las pol\u00edticas migratorias restrictivas impulsadas por el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) en Estados Unidos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-de-que-hablan-julia-navarro-y-nico-castellano\"><strong>\u00bfDe qu\u00e9 hablan Julia Navarro y Nico Castellano?<\/strong><\/h3>\n\n\n\n<p>En este episodio, Nico Castellano analiza el contexto social y pol\u00edtico en el que se sit\u00faa <strong>el debate migratorio en Espa\u00f1a y el impacto de la polarizaci\u00f3n <\/strong>en la opini\u00f3n p\u00fablica. El periodista alerta de que el ruido pol\u00edtico y medi\u00e1tico est\u00e1 teniendo consecuencias directas en la convivencia democr\u00e1tica, ya que, como explica, \u201cest\u00e1 rompiendo los m\u00ednimos de la empat\u00eda, deshumanizando a los migrantes y a todos aquellos que no piensan como ellos\u201d.<\/p>\n\n\n\n<p>Durante la conversaci\u00f3n, Nico se detiene en la recientemente aprobada regularizaci\u00f3n extraordinaria de personas migrantes y defiende que se trata de una medida necesaria desde un enfoque de derechos, ya que <strong>\u201cno puede haber personas de segunda categor\u00eda\u201d,<\/strong> y a\u00f1ade que la regularizaci\u00f3n o normalizaci\u00f3n administrativa de estas personas es una consecuencia directa de haber dejado durante a\u00f1os a miles de personas fuera del sistema.<\/p>\n\n\n\n<p>Julia Navarro y Nico Castellano tambi\u00e9n abordan las <strong>pol\u00edticas migratorias en Estados Unidos y el papel del ICE<\/strong>. Nico es contundente al describir estas actuaciones y advierte de la gravedad de lo que est\u00e1 ocurriendo: \u201cEst\u00e1n cometiendo vulneraciones de derecho, salvajes, criminales\u201d, se\u00f1ala, alertando tambi\u00e9n del impacto del miedo y el rechazo en personas que ya forman parte de la sociedad, incluidas segundas y terceras generaciones.<\/p>\n\n\n\n<p><strong>\u00bfQu\u00e9 es \u2018Voces por una Causa\u2019 con Julia Navarro?<\/strong><\/p>\n\n\n\n<p>Presentado por la escritora y periodista Julia Navarro, <a href=\"https:\/\/www.entreculturas.org\/podcast\/\"><strong>\u2018Voces por una causa\u2019<\/strong><\/a><strong> es el podcast semanal de la ONG Entreculturas<\/strong> que explora cuestiones sociales, medioambientales y culturales a trav\u00e9s de testimonios en primera persona. Los programas se emiten todos los jueves en nuestro canal de <a href=\"https:\/\/www.youtube.com\/c\/EntreculturasOrg915902672\">Youtube<\/a>, en <a href=\"https:\/\/open.spotify.com\/show\/6dS5JsqnsWrnHL1gwead1A\">Spotify<\/a>, en <a href=\"https:\/\/www.ivoox.com\/perfil-entreculturas_a8_listener_28185270_1.html\">Ivoox<\/a>, y en <a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/entreculturas-voces-por-una-causa\/id1621485462\">Apple Podcast<\/a>.<\/p>\n\n\n\n<iframe data-testid=\"embed-iframe\" style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed\/episode\/2qaGFlU8rGAp15Qv8lvTzV?utm_source=generator\" width=\"100%\" height=\"352\" frameBorder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>Esta semana en el podcast de Voces por una Causa, la escritora Julia Navarro conversa con Nico Castellano, periodista de la Cadena SER y una de las voces m\u00e1s reconocidas en Espa\u00f1a en la cobertura informativa sobre migraciones y derechos humanos. Con \u00e9l, Julia Navarro nos acerca a la situaci\u00f3n actual de las migraciones en Espa\u00f1a, al debate p\u00fablico en torno a la reciente regularizaci\u00f3n extraordinaria de personas migrantes y a las pol\u00edticas migratorias restrictivas impulsadas por el Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE) en Estados Unidos. \u00bfDe qu\u00e9 hablan Julia Navarro y Nico Castellano? En este episodio, Nico Castellano analiza el contexto social y pol\u00edtico en el que se sit\u00faa el debate migratorio en Espa\u00f1a y el impacto de la polarizaci\u00f3n en la opini\u00f3n p\u00fablica. El periodista alerta de que el ruido pol\u00edtico y medi\u00e1tico est\u00e1 teniendo consecuencias directas en la convivencia democr\u00e1tica, ya que, como explica, [&hellip;]<\/p>\n","protected":false},"featured_media":46209,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[],"class_list":["post-46201","podcast","type-podcast","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Julia Navarro conversa con Nico Castellano sobre migraci\u00f3n<\/title>\n<meta name=\"description\" content=\"Julia Navarro conversa con Nico Castellano sobre la situaci\u00f3n actual de las migraciones en Espa\u00f1a y en el mundo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Julia Navarro conversa con Nico Castellano: \u201cLas personas migrantes no son pobrecitos, son personas con derechos\u201d\" \/>\n<meta property=\"og:description\" content=\"Julia Navarro conversa con Nico Castellano sobre la situaci\u00f3n actual de las migraciones en Espa\u00f1a y en el mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:49:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/02\/Somos-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/podcast\\\/julia-navarro-podcast-ong-regularizacion-migrante\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/podcast\\\/julia-navarro-podcast-ong-regularizacion-migrante\\\/\",\"name\":\"Julia Navarro conversa con Nico Castellano sobre migraci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/podcast\\\/julia-navarro-podcast-ong-regularizacion-migrante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/podcast\\\/julia-navarro-podcast-ong-regularizacion-migrante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Somos-1.jpg\",\"datePublished\":\"2026-02-11T13:42:08+00:00\",\"dateModified\":\"2026-02-11T13:49:07+00:00\",\"description\":\"Julia Navarro conversa con Nico Castellano sobre la situaci\u00f3n actual de las migraciones en Espa\u00f1a y en el mundo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/podcast\\\/julia-navarro-podcast-ong-regularizacion-migrante\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/podcast\\\/julia-navarro-podcast-ong-regularizacion-migrante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/podcast\\\/julia-navarro-podcast-ong-regularizacion-migrante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Somos-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/Somos-1.jpg\",\"width\":800,\"height\":533,\"caption\":\"Julia Navarro y Nico Castellano hablando sobre migraci\u00f3n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/podcast\\\/julia-navarro-podcast-ong-regularizacion-migrante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast Julia Navarro\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/podcasts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Julia Navarro conversa con Nico Castellano: \u201cLas personas migrantes no son pobrecitos, son personas con derechos\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Julia Navarro conversa con Nico Castellano sobre migraci\u00f3n","description":"Julia Navarro conversa con Nico Castellano sobre la situaci\u00f3n actual de las migraciones en Espa\u00f1a y en el mundo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/","og_locale":"en_US","og_type":"article","og_title":"Julia Navarro conversa con Nico Castellano: \u201cLas personas migrantes no son pobrecitos, son personas con derechos\u201d","og_description":"Julia Navarro conversa con Nico Castellano sobre la situaci\u00f3n actual de las migraciones en Espa\u00f1a y en el mundo.","og_url":"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2026-02-11T13:49:07+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/02\/Somos-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/","url":"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/","name":"Julia Navarro conversa con Nico Castellano sobre migraci\u00f3n","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/02\/Somos-1.jpg","datePublished":"2026-02-11T13:42:08+00:00","dateModified":"2026-02-11T13:49:07+00:00","description":"Julia Navarro conversa con Nico Castellano sobre la situaci\u00f3n actual de las migraciones en Espa\u00f1a y en el mundo.","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/02\/Somos-1.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/02\/Somos-1.jpg","width":800,"height":533,"caption":"Julia Navarro y Nico Castellano hablando sobre migraci\u00f3n"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/en\/podcast\/julia-navarro-podcast-ong-regularizacion-migrante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/en\/"},{"@type":"ListItem","position":2,"name":"Podcast Julia Navarro","item":"https:\/\/www.entreculturas.org\/en\/podcasts\/"},{"@type":"ListItem","position":3,"name":"Julia Navarro conversa con Nico Castellano: \u201cLas personas migrantes no son pobrecitos, son personas con derechos\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/en\/#website","url":"https:\/\/www.entreculturas.org\/en\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/en\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/en\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/podcast\/46201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/types\/podcast"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media\/46209"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media?parent=46201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/categories?post=46201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/tags?post=46201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}