{"id":9688,"date":"2022-04-01T10:04:43","date_gmt":"2022-04-01T08:04:43","guid":{"rendered":"https:\/\/www.entreculturas.org\/publicacion\/beatriz-zapata-volpa-en-rd-congo\/"},"modified":"2024-09-17T13:34:50","modified_gmt":"2024-09-17T11:34:50","slug":"beatriz-zapata-volpa-en-rd-congo","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/","title":{"rendered":"Beatriz Zapata &#8211; VOLPA en R.D. Congo"},"content":{"rendered":"<p>Ella es Beatriz Zapata, tiene 27 a\u00f1os. Trabaja&nbsp;como tutora y maestra de franc\u00e9s, termin\u00f3&nbsp;el M\u00e1ster de Educaci\u00f3n para el Desarrollo el a\u00f1o pasado, en Sevilla. Junto al profesor que le tutoriz\u00f3 el Trabajo de Fin de M\u00e1ster, y siguiendo con esa investigaci\u00f3n, avanzar\u00e1n&nbsp;en un Doctorado en el \u00e1mbito de sociolog\u00eda de la educaci\u00f3n.&nbsp;&nbsp;<\/p>\n<p>Como afirma la propia Beatriz, &#8220;no solemos ser tan diferentes al fin y al cabo, como a casi todo el mundo, me gusta compartir mi tiempo, pasarlo con las personas que quiero y conocer a otras nuevas, leer, el cine, dibujar, escribir, hacer deportes de riesgo (escalada, buceo, snowboard&#8230;), viajar (pero no &#8220;hacer turismo&#8221;) y aprender casi cualquier cosa nueva que tenga que ver con las ciencias humanas&#8221;.<\/p>\n<p><strong>\u00bfConoc\u00edas el trabajo de Entreculturas? \u00bfC\u00f3mo llegaste a conocer Entreculturas?<\/strong><\/p>\n<p>En 2015 conoc\u00ed, a trav\u00e9s del bolet\u00edn de noticias de mi universidad, el curso \u201cAc\u00e9rcate al Sur\u201d, hoy llamado \u201cFronteras\u201d. En los caminos que tomamos siempre solemos encontrar personas significativas a las que poder agradecer. A m\u00ed, en esta parte del viaje, me gusta presentar a Stefi, una antigua voluntaria de EC que encontr\u00e9 por casualidad en la facultad de educaci\u00f3n; fue ella quien finalmente me anim\u00f3 a hacerlo.&nbsp;<\/p>\n<p>Me gust\u00f3 tanto el curso, no solo el contenido sino la metodolog\u00eda, los discursos l\u00f3gicos basados en ideas simples y potentes como el respeto, la coherencia, la cooperaci\u00f3n horizontal\u2026 que me qued\u00e9 como voluntaria. He aprendido mucho en estos a\u00f1os gracias a las distintas formaciones, personas, encuentros institucionales, reuniones de ciudadan\u00eda\u2026 y finalmente a la formaci\u00f3n VOLPA.&nbsp;<\/p>\n<p><strong>\u00bfC\u00f3mo conociste VOLPA?<\/strong><\/p>\n<p>Una vez dentro de la ONG es imposible no conocer VOLPA. Aparte de las \u201cnoches de t\u00e9\u201d, siempre hab\u00eda alguien en las reuniones que \u201chab\u00eda sido\u201d VOLPA, que acababa de volver o que estaba haciendo la formaci\u00f3n. Desde el primer momento me sent\u00ed totalmente atra\u00edda por el programa y las historias que escuchaba, los aprendizajes y encuentros. Y hoy, a\u00f1os despu\u00e9s, me encuentro respondiendo estas preguntas desde mi enclave VOLPA.&nbsp;<\/p>\n<p><strong>\u00bfEs tu primera experiencia de Voluntariado Internacional?<\/strong><\/p>\n<p>S\u00ed, pero no de voluntariado. El programa te exige haber realizado voluntariado local. En Sevilla he estado en voluntariados muy diversos, he trabajado casi siempre con la infancia aunque tambi\u00e9n estuve en una protectora de animales. Cuando empiezas a conocer el mundo es imposible no hacerlo desde un posicionamiento hol\u00edstico. Sin embargo, es la igualdad de g\u00e9nero y especialmente, la infancia vulnerable, los colectivos por los que me siento poderosamente interpelada. Soy maestra, por lo que es deformaci\u00f3n profesional. Empec\u00e9 en Crecer con Futuro, una ONG con un equipo de personas maravillosas, que alimentaron mi compromiso social.&nbsp;<\/p>\n<p>Aunque VOLPA es diferente a cualquier otro tipo de voluntariado que haya hecho e incluso a la concepci\u00f3n que ten\u00eda del voluntariado. Es una inmersi\u00f3n total, no sabes d\u00f3nde empieza y termina el voluntariado y donde lo hace tu vida. No es una actividad a la que vas los martes por la tarde y luego vuelves a casa. No \u201cvas\u201d al voluntariado, est\u00e1s en \u00e9l, lo est\u00e1s viviendo. Por tanto, no es solo \u201chacer\u201d, sino \u201cser y estar, haciendo\u201d.&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 significaron para ti los meses de formaci\u00f3n previa?<\/strong><\/p>\n<p>Los meses previos fueron esenciales y siempre he apreciado la calidad de la formaci\u00f3n y del equipo al completo. Antes de venir ya lo sent\u00eda as\u00ed pero lo he comprobado al venir a terreno. Me siento muy afortunada tambi\u00e9n por haber conocido al grupo de mujeres que conforman esta promoci\u00f3n VOLPA, las que est\u00e1n y las que partieron por otros caminos, pero compartiendo un objetivo social com\u00fan. Sin duda el proceso no tendr\u00eda sentido si no fuera en grupo.&nbsp;<\/p>\n<p>El COVID nos oblig\u00f3 a iniciar y continuar una buena parte de la formaci\u00f3n de forma online. Nos perdimos f\u00edsicamente todos los encuentros, regionales y nacionales. Pero aun as\u00ed, con la participaci\u00f3n del grupo y la implicaci\u00f3n de las formadoras, conseguimos no perder el sentido. Por eso creo que tuvo tanto impacto el primer encuentro presencial de fin de semana en Huelva, que justo coincidi\u00f3 con la toma de decisi\u00f3n. Sin duda lo recuerdo como el momento m\u00e1s especial de toda la formaci\u00f3n.&nbsp;<\/p>\n<p>Lo que vemos en los meses previos se materializa aqu\u00ed, en terreno. En nuestro caso, las formadoras y formador (Roc\u00edo, Mila y Fernando) llevan a\u00f1os acompa\u00f1ando Volpas o lo han sido en primera persona, conocen miles de historias\u2026 Eso hace que conozcan muy bien los miedos, situaciones, choques o conflictos que suelen darse; aunque por supuesto, cada experiencia es \u00fanica y no hay formaci\u00f3n que te de las claves para una experiencia perfecta y sin errores. Aun as\u00ed, me encanta descubrirme en situaciones que nos advert\u00edan que podr\u00edan ocurrir, mientras yo pensaba: \u201cbueno, eso no me va a pasar a m\u00ed\u201d, y finalmente, por supuesto que s\u00ed\u2026 s\u00ed que me han pasado. Es un proceso de aprendizaje y humildad continuo.&nbsp;<\/p>\n<p>El acompa\u00f1amiento en la formaci\u00f3n y aqu\u00ed, durante el tiempo de voluntariado en terreno, est\u00e1 siendo muy significativo para m\u00ed. En mi caso, mi acompa\u00f1ante tambi\u00e9n es amigo y siempre encuentra tiempo para pasarse horas charlando o leyendo escritos infinitos, darme feedback, apoyo y herramientas de reflexi\u00f3n.&nbsp;<\/p>\n<p><strong>\u00bfA qu\u00e9 pa\u00eds fuiste destinada? \u00bfCu\u00e1ndo llegaste all\u00ed?<\/strong><\/p>\n<p>Llegu\u00e9 a Kinshasa, capital de la Rep\u00fablica Democr\u00e1tica del Congo (RDC) el 14 de octubre de 2021. En Kinshasa estuve un mes, hasta que llegu\u00e9 a Kikwit, mi ciudad actual de residencia, lo que ahora es mi hogar.&nbsp;<\/p>\n<p>Durante toda la formaci\u00f3n pens\u00e9 que mi destino se encontrar\u00eda, como casi todos los que conoc\u00eda, en Latinoam\u00e9rica. Cuando Fernando, mi acompa\u00f1ante, me hizo pensar en \u00c1frica me ilusion\u00f3 y me removi\u00f3 a la vez por todo el ideario latinoamericano que hab\u00eda construido durante toda la formaci\u00f3n. M\u00e1s tarde, Ana y Sonia me propusieron la RDC como enclave en la entrevista que tuvimos en Sevilla e instintivamente (aunque me dejaron tiempo para meditarlo) dije que s\u00ed. Hoy me siento agradecida por c\u00f3mo se bifurcan los distintos caminos, c\u00f3mo sucede la toma de decisiones, las coincidencias&#8230; que me han tra\u00eddo hasta aqu\u00ed, para conocer a personas que ya forman parte de mi historia de vida y, espero, formar yo parte de las suyas.<\/p>\n<p><strong>\u00bfCon qu\u00e9 instituci\u00f3n est\u00e1s colaborando?<\/strong><\/p>\n<p>Aqu\u00ed trabajo con Foi et Joie RDC. La oficina est\u00e1 en Kinshasa aunque yo vivo en Kikwit, a unos 500km y m\u00e1s de 8h por una dif\u00edcil carretera. El equipo de Kinshasa es excepcional, en la oficina no solo se respira profesionalidad, sino buen rollo y amistad. Esas personas que empezaron siendo desconocidas no tardaron en llamarse amigas. El equipo es muy joven y est\u00e1 lleno de fuerza; traen un aire congol\u00e9s renovador, transformador y local.&nbsp;<\/p>\n<p>Alfred, coordinador de Fe y Alegr\u00eda RDC, junto con Christelle, Ruth, Arvie, Fabrice, Pitshou, Lucie y Matondo, conforman la oficina nacional desde Kinshasa. Pese a ser una oficina joven (tanto por su plantilla como por el tiempo de vida de FyA en RDC), tienen proyectos de educaci\u00f3n para el desarrollo en Kimwenza (Kinshasa), Kikwit, Kisantu y actualmente se est\u00e1n expandiendo a otras zonas \u201cdonde termina el asfalto\u201d.&nbsp;<\/p>\n<p><strong>\u00bfQu\u00e9 es lo particular de este voluntariado y del proyecto que est\u00e1s realizando? \u00bfCu\u00e1l es tu misi\u00f3n? Describe tu d\u00eda a d\u00eda.<\/strong><\/p>\n<p>Si esperas que te cuente una \u201crutina\u201d semanal, voy a decepcionarte. Y eso es lo particular de mi voluntariado. Fe y Alegr\u00eda est\u00e1 naciendo en RDC y aunque ya han avanzado en muchos proyectos, el voluntariado tambi\u00e9n tiene que tomar forma. Mi tarea principal es la formaci\u00f3n del profesorado de colegios a los que acompa\u00f1a Fe y Alegr\u00eda en Kikwit, as\u00ed como un par de conferencias a adolescentes. Este refuerzo pedag\u00f3gico se realiza en fin de semana, uno o dos al mes, lo cual me deja bastante tiempo libre. Y hasta ah\u00ed la misi\u00f3n que me han encomendado. Sin embargo, ocupo mi tiempo con otros proyectos que parece que empiezan a emerger.<\/p>\n<p>Actualmente me re\u00fano con un grupo de mujeres de Kikwit que llevan unos 10 a\u00f1os organizando actividades de g\u00e9nero por el 8M durante todo el mes de marzo.&nbsp; La Red Generaci\u00f3n 21+ ya existe en Kinshasa, pero en Kikwit estamos empezando a despegar. El inicio ha sido muy bueno, confiamos en que consiga consolidarse en el tiempo. Con algunas profesoras realmente potentes de los colegios, queremos aunar, en una \u201cgu\u00eda did\u00e1ctica\u201d, los aspectos metodol\u00f3gicos, de contenido y ayudas pedag\u00f3gicas b\u00e1sicas para aquellos docentes con m\u00e1s dificultades.<\/p>\n<p>Es ahora cuando realmente estoy empezando a rodar y se est\u00e1n gestando proyectos que pueden salir o no, pero que queremos intentar: un programa de radio de cuentacuentos con posterior debate docente, cine-f\u00f3rums en uno de los institutos jesuitas, unas jornadas de teatro lideradas por Ginho, encargado de la radio y experto en organizar actividades culturales.&nbsp;<\/p>\n<p>Lo importante de todos estos proyectos es que la iniciativa surge y el liderazgo reside en personas locales con ganas de continuarlos a medio-largo plazo. Siempre me encuentro en un segundo o tercer plano, apoyando donde me necesiten y proponiendo ideas que pasan por sus filtros. No solo para que los proyectos gocen de autonom\u00eda local sino porque me rodeo de equipos profesionales y comprometidos de los que me permito aprender.&nbsp;&nbsp;<\/p>\n<p>Aprovecho siempre que puedo para visitar los colegios (especialmente el de infantil), recibir clases de kikongo del P\u00e8re Mate o acompa\u00f1arlo en su trabajo en el huerto, leer o escribir.<\/p>\n<p>Reducir la velocidad, parar, es realmente algo a interiorizar. La vida aqu\u00ed se saborea, va m\u00e1s despacio y casi todo gira en torno a las relaciones sociales. Una de las cosas m\u00e1s importante que estoy aprendiendo es la importancia de estar presente. Se espera de los dem\u00e1s un simple mensaje de texto (\u201cBonjour, \u00e7a va?\u201d), una llamada o una visita que se celebra con una generosa hospitalidad, sonrisas y una c\u00e1lida acogida. Y por supuesto algo de comer y beber, que no falten los cacahuetes, pl\u00e1tanos o el \u201cfuf\u00fa\u201d.&nbsp;&nbsp;<\/p>\n<p>No tengo d\u00eda a d\u00eda, cada d\u00eda es diferente y parecido. Todas las comidas son a la misma hora, es el momento de encuentro con los curas de la comunidad, que se hacen llamar \u201cmis t\u00edos\u201d. A veces es dif\u00edcil gestionar la falta de horarios y tareas prestablecidas, pero eso me obliga a tener una continua actitud de reflexi\u00f3n y tener iniciativa. Como dec\u00eda, los encuentros son asiduos, ya sea por una invitaci\u00f3n, porque llegan hu\u00e9spedes a la comunidad o porque surge una conversaci\u00f3n con cualquier persona en la calle.&nbsp;&nbsp;<\/p>\n<p><strong>\u00bfC\u00f3mo fueron las primeras semanas de trabajo?<\/strong><\/p>\n<p>El comienzo del trabajo como tal se ha hecho de rogar. Cuando llegu\u00e9, mi tarea que se da en los colegios, estaba totalmente paralizada por una huelga docente que dur\u00f3 hasta noviembre. Por tanto, el equipo decidi\u00f3 que me quedase en Kinshasa un mes antes de llegar a mi destino, Kikwit. Una vez aqu\u00ed, los colegios segu\u00edan cerrados. Cuando abrieron no sab\u00eda muy bien qu\u00e9 ten\u00eda que hacer, as\u00ed que me dediqu\u00e9 a visitarlos, observar y aprender. Sin darme cuenta empezaron las vacaciones de navidad, pasando alguna que otra malaria por el camino. En diciembre hicimos la primera formaci\u00f3n, previo estudio de intereses, etc. En enero volv\u00ed a Kinshasa dos semanas y es ahora cuando estamos empezando a rodar.&nbsp;<\/p>\n<p>Esa es la magia de VOLPA, que nunca sabes qu\u00e9 te espera, y me gusta tal y como se est\u00e1 desarrollando: aceptando, aprendiendo y respetando los tiempos de adaptaci\u00f3n, seguridad, participaci\u00f3n y, sobre todo, encuentro.<\/p>\n<p>En cualquier caso, las primeras semanas de adaptaci\u00f3n al contexto se dieron de una forma muy natural, propiciadas por las personas que me acogieron. Cuando me preguntan qu\u00e9 opino de la RDC siempre respondo con una palabra: \u201cacogedora\u201d. Es inevitable enamorarse r\u00e1pido.&nbsp;<br \/>&nbsp;<br \/><strong>\u00bfQu\u00e9 es lo que m\u00e1s te ha llamado la atenci\u00f3n en este tiempo?<\/strong><\/p>\n<p>En primer lugar, lo que m\u00e1s me ha llamado la atenci\u00f3n es la calidad humana. Creo que nunca hab\u00eda estado en un lugar donde encontrar a un n\u00famero tan elevado de personas con un car\u00e1cter tan (de nuevo) acogedor. Me fascina la ilusi\u00f3n constante por el encuentro, por conocerse, la facilidad para intercambiar contactos, para compartir, para celebrar, para hablarse con exquisito respeto, para confiar, para partir siempre de una imagen positiva del otro.&nbsp;<\/p>\n<p>En segundo lugar, relacionado con esta cultura del encuentro, no deja de sorprenderme el contraste. Aqu\u00ed comparto solo algunos ejemplos.<\/p>\n<p>Por una parte, contraste entre un car\u00e1cter que huye del conflicto, que cuida las palabras para nunca faltar al respeto, que mima los detalles para los invitados, donde no faltan cacahuetes y sonrisas, que no juzga tan r\u00e1pido; por otra parte, las continuas advertencias de los curas sobre la peligrosidad de Kikwit, el vandalismo callejero, los accidentes, los juicios ligados al g\u00e9nero o la religi\u00f3n, la violencia, una polic\u00eda corrupta\u2026<br \/>&nbsp;<br \/>Contraste entre una poblaci\u00f3n emprendedora, con una juventud s\u00faper potente y formada con ganas de transformar la sociedad, con las mujeres m\u00e1s fuertes que haya conocido, con expertas\/os en temas de primera actualidad, l\u00edderes de las universidades del pa\u00eds, con ni\u00f1os y ni\u00f1as delicadamente respetuosos&#8230; Y entre un sistema educativo y sanitario deficiente, una administraci\u00f3n desastrosa, un estado que ha abandonado a su poblaci\u00f3n, funcionariado que no recibe salarios, casas hechas de barro, demasiado trabajo infantil\u2026<\/p>\n<p>Contraste entre la suciedad, las malas condiciones de higiene, el mal estado de los edificios y entre personas que pasean en este escenario con sus caros trajes de chaqueta, iphones, vestidos, tacones y gafas de sol de marca.&nbsp;<br \/>Contraste entre casas hechas de barro, bamb\u00fa y paja y el gran panel solar que se sit\u00faa en el tejado, a la \u00faltima en cuanto a energ\u00eda renovable.<br \/>Contraste entre melanc\u00f3licos seguidores de Mobutu y los colonos belgas asegurando que cualquier tiempo pasado fue mejor y entre personas que conf\u00edan en la democracia, en una juventud comprometida con la innovaci\u00f3n, la defensa de la justicia, la igualdad de g\u00e9nero, el orgullo africano\u2026<br \/>Y contraste entre tradiciones locales e influencias occidentales (sincretismo de brujer\u00eda y cristianismo, por ejemplo).<br \/>Son solo algunos ejemplos de un pa\u00eds que no deja de sorprenderme por poder encontrarlo todo en \u00e9l, de un extremo al otro. Y ese contraste se materializa en una toma de decisiones constante, de continuo posicionamiento.&nbsp;<\/p>\n<p><strong>\u00bfHay algo a lo que te est\u00e9 costando especialmente adaptarte?<\/strong><\/p>\n<p>Pr\u00e1cticamente, lo \u00fanico que me ha hecho tener d\u00edas malos ha sido el miedo a las enfermedades. Como dec\u00eda, la cultura congolesa que estoy conociendo es hospitalaria y espont\u00e1nea, por lo que los peque\u00f1os contratiempos o choques culturales, por el momento, son f\u00e1cilmente solucionables.&nbsp;<\/p>\n<p>Podr\u00eda decir que las condiciones de higiene fuera de la comunidad y la limitada asistencia m\u00e9dica en Kikwit es lo que m\u00e1s me est\u00e1 costando sobrellevar. En cuanto a enfermedades, ya he tenido un par de veces malaria, fiebre tifoidea, infecciones\u2026 Da miedo escucharlo, pero la verdad es que con medicaci\u00f3n y siendo lo suficientemente prudente para ir al m\u00e9dico ante cualquier s\u00edntoma, no he tenido ning\u00fan problema. De hecho, he pasado gripes peores en Espa\u00f1a.&nbsp;<\/p>\n<p>Pero s\u00ed he sentido, sobre todo las primeras veces, bastante aprensi\u00f3n al escuchar el nombre de enfermedades, que a priori dan miedo, y he temido por aquellas que ni siquiera conozco. Sin embargo me siento muy acompa\u00f1ada, tanto el equipo de Kinshasa como el de Espa\u00f1a siempre est\u00e1n pendientes de mi estado de salud y de que todo se desarrolle con normalidad, y poco a poco voy normaliz\u00e1ndolo, as\u00ed como mi cuerpo se va acostumbrando.&nbsp;<\/p>\n<p>Aqu\u00ed es casi obligado preguntar por la salud como parte del saludo. Esto me ayuda a entender lo dif\u00edcil que es realizar proyectos de vida, esforzarse en los estudios o el trabajo, en cuidar de la familia o pensar a largo plazo cuando est\u00e1s continuamente enferma; me ayuda a admirar a personas que nunca se detienen. Aqu\u00ed en general la gente no tiene miedo de la malaria (de hecho se r\u00eden amistosamente de m\u00ed cuando continuamente me echo repelente), conviven con ella y saben c\u00f3mo tratarla. Sin embargo, yo no dejo de pensar en el obst\u00e1culo que supone no tener todas las condiciones, calidades y servicios sanitarios disponibles, sobre todo, para aquellas personas que no viven en Kinshasa.&nbsp;<\/p>\n<p><strong>\u00bfParticipas activamente en alg\u00fan programa relacionado con mujeres en el que est\u00e9 involucrado Entreculturas? \u00bfPodr\u00edas comentarnos c\u00f3mo se desarrolla y de qu\u00e9 va el proyecto?<\/strong><\/p>\n<p>Actualmente asisto a unas reuniones los viernes. Es un grupo de mujeres que lleva m\u00e1s de 10 a\u00f1os preparando el 8M con actividades de sensibilizaci\u00f3n durante todo el mes de marzo. Son mujeres de todas las edades, mujeres inteligentes y fuertes con un discurso interiorizado que comparten alto y claro: \u201cqueremos tener las mismas oportunidades, somos capaces de todo si contamos con los mismos recursos y derechos\u201d. Como ya sabemos, hablamos de feminismos, en este caso afrofeminismo. Las reuniones son en kikongo y sus costumbres y tradiciones no se ven afectadas por sus deseos de igualdad. Nos espera un mes de marzo interesante en el que se prev\u00e9n conciertos, teatro, cine-f\u00f3rum, conferencias\u2026 Todo, en torno a las mujeres.&nbsp;<\/p>\n<p>En Kikwit, al menos, no es Fe y Alegr\u00eda quien organiza el 8M pero s\u00ed colabora con este grupo de mujeres. El a\u00f1o pasado hicieron unas jornadas de \u201clidership femenin\u201d en la que, mujeres exitosas profesionalmente, dieron charlas a j\u00f3venes adolescentes, convirti\u00e9ndose en ejemplos de liderazgo femenino.&nbsp;<\/p>\n<p>En cualquier caso, Foi et Joie RDC apuesta por la educaci\u00f3n de las ni\u00f1as y por visibilizar esta necesidad que verbaliza en sus campa\u00f1as, actos y publicaciones.&nbsp;<\/p>\n<p><strong>\u00bfPodr\u00edas hablarnos desde tu perspectiva y como cooperante voluntaria como ves a la mujer dentro de la sociedad en la que actualmente cumples con tu voluntariado?<\/strong><\/p>\n<p>Estas mujeres, en mi humilde opini\u00f3n, son el gran motor de la RDC. He conocido a algunas mujeres, como Charlotte, que trabaja en casa, es maestra en el colegio y tambi\u00e9n trabaja en el campo, junto con su hija mayor. El campo donde cultivan ma\u00edz, cacahuetes, yuca entre otras cosas, est\u00e1 a 1h andando de su casa.&nbsp;<\/p>\n<p>Como me explic\u00f3 el padre Mate, existen tribus patriarcales y matriarcales, con unas dif\u00edciles normas de funcionamiento, herencia, l\u00edneas sucesorias y de poder. La mujer, como en todo el mundo, vive en una sociedad que le exige m\u00e1s y le permite menos que a los hombres, que sufre violencia en todas sus manifestaciones.&nbsp;<\/p>\n<p>En occidente y desde nuestros feminismos hemos visto la necesidad real de hablar de sororidad, de aparcar esa competencia que materializamos inconscientemente como hijas del sistema. Aqu\u00ed admiro la ausencia de ese discurso, porque no es necesario. Muchos matrimonios surgen de pactos entre familias en las zonas m\u00e1s rurales. Ser madre y esposa es el fin para el que educan a muchas ni\u00f1as, es el objetivo de sus vidas, que en ocasiones no lo desencadena el amor. Y veo que se dan relaciones de cooperaci\u00f3n entre las mujeres, de ayuda mutua, veo la alegr\u00eda que se expresan por compartir espacios juntas, charlar, re\u00edr\u2026 Ya sean familia, amigas o desconocidas. Al menos, es lo poco que he podido leer desde mi perspectiva y sobre todo de las conversaciones que he tenido con mujeres sobre este tema.&nbsp;<\/p>\n<p>Aunque solo me encuentre en un c\u00edrculo que espec\u00edficamente trate el tema de g\u00e9nero, no hay ning\u00fan espacio en el que trabaje en el que no haya mujeres a las que admirar. En los colegios de infantil y primaria, las j\u00f3venes del grupo de voluntariado, las compa\u00f1eras de la oficina de Kinshasa, en las comunidades\u2026: Charlotte, Julienne, Dorcas, Nadine, Fran\u00e7oise, Therese, mama Pauline, Christelle, Ruth, Arvie, Lucie, Shayda, Mayele, Mety\u2026 La juventud femenina pisa fuerte, es competente, sabe lo que quiere y lucha por ello. Siento que no dejo de aprender, que podemos hablar con naturalidad, confianza y encontrar espacios donde compartir nuestras ideas.&nbsp;&nbsp;<\/p>\n<p><strong>\u00bfRecomendar\u00edas VOLPA a otras personas? \u00bfPor qu\u00e9? Anima a las personas a hacerlo.&nbsp;<\/strong><\/p>\n<p>Por supuesto. Hablamos de la \u201cexperiencia de voluntariado\u201d pero, citando a una amiga VOLPA (Luc\u00eda), no es una simple experiencia, es una parte de tu vida. Estando en un contexto tan diferente tienes que dejar tus placeres y exigencias a un lado y aprender por todos los medios a colaborar, a escuchar, a ceder\u2026 Aprendes a descubrir prejuicios y estereotipos de los que te cre\u00edas libre, a ver que los conflictos que parecen lejanos, pasan en un pa\u00eds de personas que ahora son tus vecinas, compa\u00f1eras y amigas. Aprendes valores comunitarios que no sab\u00edas que exist\u00edan en un mundo que parec\u00eda hecho para alimentar tu ego y tus placeres.&nbsp;<\/p>\n<p>Aun me queda medio a\u00f1o, pero a d\u00eda de hoy siento que estoy exactamente donde tengo que estar, con quien tengo que estar, haciendo lo que tengo que hacer. Las transformaciones intrapersonales e interpersonales coexisten y se retroalimentan, no se da la una sin la otra. Y normalmente el fruto de esta transformaci\u00f3n hol\u00edstica, si es aut\u00e9ntica, se traduce en compromiso social, en dejar de resignarse y comenzar a indignarse, en sentirse parte de la gran ciudadan\u00eda global.&nbsp;<\/p>\n<p>Y sin atreverme a adelantar aprendizajes generales que pueden ser y ser\u00e1n tan diferentes dependiendo de la persona y las circunstancias, simplemente est\u00e1s aqu\u00ed, compartiendo de la forma m\u00e1s real, sin distracciones, para convertir el yo en nosotras y el discurso en compromiso activo y coherente.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ella es Beatriz Zapata, tiene 27 a\u00f1os. Trabaja&nbsp;como tutora y maestra de franc\u00e9s, termin\u00f3&nbsp;el M\u00e1ster de Educaci\u00f3n para el Desarrollo el a\u00f1o pasado, en Sevilla. Junto al profesor que le tutoriz\u00f3 el Trabajo de Fin de M\u00e1ster, y siguiendo con esa investigaci\u00f3n, avanzar\u00e1n&nbsp;en un Doctorado en el \u00e1mbito de sociolog\u00eda de la educaci\u00f3n.&nbsp;&nbsp; Como afirma la propia Beatriz, &#8220;no solemos ser tan diferentes al fin y al cabo, como a casi todo el mundo, me gusta compartir mi tiempo, pasarlo con las personas que quiero y conocer a otras nuevas, leer, el cine, dibujar, escribir, hacer deportes de riesgo (escalada, buceo, snowboard&#8230;), viajar (pero no &#8220;hacer turismo&#8221;) y aprender casi cualquier cosa nueva que tenga que ver con las ciencias humanas&#8221;. \u00bfConoc\u00edas el trabajo de Entreculturas? \u00bfC\u00f3mo llegaste a conocer Entreculturas? En 2015 conoc\u00ed, a trav\u00e9s del bolet\u00edn de noticias de mi universidad, el curso \u201cAc\u00e9rcate al Sur\u201d, hoy llamado [&hellip;]<\/p>\n","protected":false},"featured_media":9689,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[191],"country":[],"cause":[],"class_list":["post-9688","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-voluntariado"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Beatriz Zapata - VOLPA en R.D. Congo - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Beatriz Zapata - VOLPA en R.D. Congo\" \/>\n<meta property=\"og:description\" content=\"Ella es Beatriz Zapata, tiene 27 a\u00f1os. Trabaja&nbsp;como tutora y maestra de franc\u00e9s, termin\u00f3&nbsp;el M\u00e1ster de Educaci\u00f3n para el Desarrollo el a\u00f1o pasado, en Sevilla. Junto al profesor que le tutoriz\u00f3 el Trabajo de Fin de M\u00e1ster, y siguiendo con esa investigaci\u00f3n, avanzar\u00e1n&nbsp;en un Doctorado en el \u00e1mbito de sociolog\u00eda de la educaci\u00f3n.&nbsp;&nbsp; Como afirma la propia Beatriz, &#8220;no solemos ser tan diferentes al fin y al cabo, como a casi todo el mundo, me gusta compartir mi tiempo, pasarlo con las personas que quiero y conocer a otras nuevas, leer, el cine, dibujar, escribir, hacer deportes de riesgo (escalada, buceo, snowboard&#8230;), viajar (pero no &#8220;hacer turismo&#8221;) y aprender casi cualquier cosa nueva que tenga que ver con las ciencias humanas&#8221;. \u00bfConoc\u00edas el trabajo de Entreculturas? \u00bfC\u00f3mo llegaste a conocer Entreculturas? En 2015 conoc\u00ed, a trav\u00e9s del bolet\u00edn de noticias de mi universidad, el curso \u201cAc\u00e9rcate al Sur\u201d, hoy llamado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-17T11:34:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2023\/12\/beatriz_zapata_somos_baja.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/beatriz-zapata-volpa-en-rd-congo\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/beatriz-zapata-volpa-en-rd-congo\\\/\",\"name\":\"Beatriz Zapata - VOLPA en R.D. Congo - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/beatriz-zapata-volpa-en-rd-congo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/beatriz-zapata-volpa-en-rd-congo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/beatriz_zapata_somos_baja.jpg\",\"datePublished\":\"2022-04-01T08:04:43+00:00\",\"dateModified\":\"2024-09-17T11:34:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/beatriz-zapata-volpa-en-rd-congo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/beatriz-zapata-volpa-en-rd-congo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/beatriz-zapata-volpa-en-rd-congo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/beatriz_zapata_somos_baja.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/beatriz_zapata_somos_baja.jpg\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/beatriz-zapata-volpa-en-rd-congo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beatriz Zapata &#8211; VOLPA en R.D. Congo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Beatriz Zapata - VOLPA en R.D. Congo - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/","og_locale":"en_US","og_type":"article","og_title":"Beatriz Zapata - VOLPA en R.D. Congo","og_description":"Ella es Beatriz Zapata, tiene 27 a\u00f1os. Trabaja&nbsp;como tutora y maestra de franc\u00e9s, termin\u00f3&nbsp;el M\u00e1ster de Educaci\u00f3n para el Desarrollo el a\u00f1o pasado, en Sevilla. Junto al profesor que le tutoriz\u00f3 el Trabajo de Fin de M\u00e1ster, y siguiendo con esa investigaci\u00f3n, avanzar\u00e1n&nbsp;en un Doctorado en el \u00e1mbito de sociolog\u00eda de la educaci\u00f3n.&nbsp;&nbsp; Como afirma la propia Beatriz, &#8220;no solemos ser tan diferentes al fin y al cabo, como a casi todo el mundo, me gusta compartir mi tiempo, pasarlo con las personas que quiero y conocer a otras nuevas, leer, el cine, dibujar, escribir, hacer deportes de riesgo (escalada, buceo, snowboard&#8230;), viajar (pero no &#8220;hacer turismo&#8221;) y aprender casi cualquier cosa nueva que tenga que ver con las ciencias humanas&#8221;. \u00bfConoc\u00edas el trabajo de Entreculturas? \u00bfC\u00f3mo llegaste a conocer Entreculturas? En 2015 conoc\u00ed, a trav\u00e9s del bolet\u00edn de noticias de mi universidad, el curso \u201cAc\u00e9rcate al Sur\u201d, hoy llamado [&hellip;]","og_url":"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-09-17T11:34:50+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2023\/12\/beatriz_zapata_somos_baja.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/","url":"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/","name":"Beatriz Zapata - VOLPA en R.D. Congo - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2023\/12\/beatriz_zapata_somos_baja.jpg","datePublished":"2022-04-01T08:04:43+00:00","dateModified":"2024-09-17T11:34:50+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2023\/12\/beatriz_zapata_somos_baja.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2023\/12\/beatriz_zapata_somos_baja.jpg","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/beatriz-zapata-volpa-en-rd-congo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/en\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/en\/noticias\/"},{"@type":"ListItem","position":3,"name":"Beatriz Zapata &#8211; VOLPA en R.D. Congo"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/en\/#website","url":"https:\/\/www.entreculturas.org\/en\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/en\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/en\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/noticia\/9688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media\/9689"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media?parent=9688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/categories?post=9688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/tags?post=9688"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/country?post=9688"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/cause?post=9688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}