{"id":6566,"date":"2022-05-26T10:24:41","date_gmt":"2022-05-26T10:24:41","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros"},"modified":"2024-02-19T11:33:12","modified_gmt":"2024-02-19T10:33:12","slug":"organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/","title":{"rendered":"Organizaciones reclaman al gobierno que promueva una Europa sin dobles raseros"},"content":{"rendered":"<p>La adopci\u00f3n de la <strong>Directiva de Protecci\u00f3n Temporal (DPT)<\/strong>, del pasado 3 de marzo de 2022, para otorgar protecci\u00f3n a las personas que huyen del conflicto de Ucrania durante un periodo de entre uno y tres a\u00f1os, supuso un <strong>hito hist\u00f3rico<\/strong>, ya que fue la primera vez que la Uni\u00f3n Europea la activaba desde su aprobaci\u00f3n en 2001.&nbsp;<br \/>&nbsp;<\/p>\n<\/p>\n<p>Sin embargo, tal y como recuerdan las organizaciones de migraci\u00f3n y refugio, <strong>esta medida no se adopt\u00f3 en circunstancias similares para personas de otras nacionalidades<\/strong>, por ejemplo las que hu\u00edan de los conflictos de Siria y Afganist\u00e1n, que han llegado durante los \u00faltimos a\u00f1os a Europa buscando protecci\u00f3n, y que han visto vulnerados sus derechos humanos y sus vidas paralizadas en centros de detenci\u00f3n.<br \/>&nbsp;<br \/>Ante esta situaci\u00f3n, <strong>las organizaciones&nbsp;firmantes nos hemos&nbsp;unido para reclamar al gobierno espa\u00f1ol una vez m\u00e1s el respeto del derecho a solicitar asilo<\/strong> y el compromiso de los Estados de la Uni\u00f3n Europea para garantizar la acogida de todas las personas refugiadas, independientemente de sus pa\u00edses de origen, confiando que en esta ocasi\u00f3n la solidaridad entre Estados sea realmente eficaz para coordinar y facilitar el transporte de las personas con seguridad, respetando sus necesidades y la elecci\u00f3n de d\u00f3nde establecerse.<\/p>\n<p>La adopci\u00f3n de la DPT confirma que<strong> la Uni\u00f3n Europea posee mecanismos de respuesta solidaria<\/strong>, as\u00ed como la capacidad de actuar de forma humanitaria para hacer frente a las necesidades de refugio y acogida de todas las personas, independientemente de su procedencia. Con ella se otorga protecci\u00f3n en caso de afluencia masiva de personas desplazadas procedentes de terceros pa\u00edses durante un periodos de entre uno y tres a\u00f1os, garantizando el acceso y el resto de sus derechos b\u00e1sicos de manera inmediata, como el derecho a la atenci\u00f3n sanitaria, a la educaci\u00f3n o la obtenci\u00f3n de permisos de residencia y trabajo, y se evitan los largos tiempos de espera del proceso de asilo.&nbsp;<\/p>\n<p>No obstante, dicha adopci\u00f3n contrasta con el momento en el que decide adoptarse y por quienes est\u00e1n bajo su protecci\u00f3n. Esta medida incluye \u00fanicamente a las personas ucranianas, ap\u00e1tridas y refugiadas, as\u00ed como sus familias y personas migrantes con un permiso de residencia de larga duraci\u00f3n que resid\u00edan en Ucrania al estallar la guerra. Esto <strong>ha dejado desamparadas a miles de personas en situaci\u00f3n irregular<\/strong>, solicitantes de refugio, estudiantes y poblaci\u00f3n trabajadora temporal residentes en el pa\u00eds, sobre quienes se han reportado diversos casos de trato discriminatorio y racista en el momento de la huida de Ucrania.<br \/>&nbsp;&nbsp;<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sin_dobles_raseros_meme.png\" style=\"width: 800px;height: 450px\"><\/p>\n<p>Por ello, <strong>las organizaciones recordamos que todas las personas que se ven forzadas a desplazarse<\/strong>, independientemente de su procedencia, y bajo las mismas condiciones que cualquier persona desplazada desde Ucrania, <strong>deben tener acceso a un procedimiento de asilo justo, con garant\u00edas, no discriminatorio y r\u00e1pido<\/strong> para que los solicitantes de protecci\u00f3n internacional no deban esperar meses para presentar su solicitud o recibir la resoluci\u00f3n.<br \/>&nbsp;&nbsp;<br \/>Por todo lo expuesto, hemos solicitado al Gobierno espa\u00f1ol que adopte, y a su vez promueva en el marco de la Uni\u00f3n Europea, un dec\u00e1logo por una Europa sin dobles raseros. En dicho dec\u00e1logo se insta a los Estados a que:<br \/>&nbsp;<\/p>\n<ul>\n<li>Acojan a todas las personas sin discriminaci\u00f3n, especialmente a las mujeres, a las ni\u00f1as, los ni\u00f1os y adolescentes y a personas con alg\u00fan factor de vulnerabilidad que buscan protecci\u00f3n, tal y como se estipula en la DPT, en otras normativas de la Uni\u00f3n Europea y en el Derecho Internacional, y que garanticen traslados seguros.<\/li>\n<li>Generen, en el desarrollo de sus pol\u00edticas y actuaciones, orientaciones sobre grupos con vulnerabilidades, tales como personas con discapacidades, personas LGBTQI+, supervivientes de la trata de personas u otras formas de explotaci\u00f3n, y ni\u00f1os y ni\u00f1as que migran solos, teniendo en cuenta las aportaciones de la Fundamental Rights Agency, la European Union Agency for Asylum, ACNUR, OIM y la sociedad civil.<\/li>\n<li>Reasienten a las personas desplazadas teniendo en cuenta sus necesidades y v\u00ednculos, y que esta pr\u00e1ctica se convierta en la norma y no en la excepci\u00f3n.<\/li>\n<li>Establezcan mecanismos de coordinaci\u00f3n entre autoridades nacionales, auton\u00f3micas y locales, y proveedoras de servicios, especialmente en la recepci\u00f3n y el reasentamiento, incluyendo a las organizaciones de la sociedad civil y organizaciones de migrantes y de la di\u00e1spora.<\/li>\n<li>Las agencias europeas de derechos humanos y asilo supervisen y garanticen que las personas tengan acceso al territorio de la UE, puedan acceder plenamente a sus derechos, y los traslados sean seguros.<\/li>\n<li>Adopten enfoques inclusivos, interseccionales y no discriminatorios basados en la protecci\u00f3n y el respeto de los derechos humanos, incluyendo los derechos de las mujeres.<\/li>\n<li>Refuercen los mecanismos de gesti\u00f3n del sistema de protecci\u00f3n internacional, as\u00ed como los de primera acogida e inclusi\u00f3n para evitar su colapso.<\/li>\n<li>Proh\u00edban las expulsiones sumarias y colectivas en las fronteras de la UE. En concreto, que el Estado espa\u00f1ol elimine la disposici\u00f3n adicional de la Ley de Seguridad Ciudadana que pretende dar cobertura legal a estas pr\u00e1cticas contrarias al Convenio Europeo de Derechos Humanos.<\/li>\n<li>Movilicen recursos adicionales para apoyar a las personas que huyen de Ucrania sin que afecte los fondos ya comprometidos para apoyar a personas migrantes, desplazadas o solicitantes de asilo en otros contextos, o en otras crisis humanitarias, y que no computen como Ayuda Oficial al Desarrollo.<\/li>\n<li>Apliquen los mecanismos financieros de solidaridad movilizados tambi\u00e9n para los Estados miembro que reciben la llegada de personas en movimiento.<\/li>\n<\/ul>\n<p>&nbsp;<br \/><strong>Las organizaciones firmantes han trasladado estas recomendaciones al Ministerio de Interior, al Ministerio de Inclusi\u00f3n, Seguridad Social y Migraciones y al Ministerio de Asuntos Exteriores, Uni\u00f3n Europea y Cooperaci\u00f3n, as\u00ed como a las respectivas Comisiones en el Congreso y el Senado.<\/strong><br \/>&nbsp;<br \/>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"450\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sin_dobles_mecanismos.png\" width=\"800\"><\/p>\n<p><span style=\"color:#FF0000\"><strong>Firmamos&nbsp;este comunicado:&nbsp;<\/strong><\/span><\/p>\n<ul>\n<li>Alianza por la Solidaridad &#8211; ActionAid.&nbsp;<\/li>\n<li>Amnist\u00eda Internacional.&nbsp;<\/li>\n<li>Andaluc\u00eda Acoge.&nbsp;<\/li>\n<li>La Coordinadora de Organizaciones para el Desarrollo.&nbsp;<\/li>\n<li>Entreculturas.&nbsp;<\/li>\n<li>M\u00e9dicos del Mundo.&nbsp;<\/li>\n<li>Oxfam Interm\u00f3n.&nbsp;<\/li>\n<li>Red Acoge.&nbsp;<\/li>\n<li>Stop Mare Mortum.&nbsp;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La adopci\u00f3n de la Directiva de Protecci\u00f3n Temporal (DPT), del pasado 3 de marzo de 2022, para otorgar protecci\u00f3n a las personas que huyen del conflicto de Ucrania durante un periodo de entre uno y tres a\u00f1os, supuso un hito hist\u00f3rico, ya que fue la primera vez que la Uni\u00f3n Europea la activaba desde su aprobaci\u00f3n en 2001. Sin embargo, otras nacionalidades en situaciones similares han quedado desprotegidas. Pedimos una Europa #SinDoblesRaseros. <\/p>\n","protected":false},"featured_media":6564,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[10],"country":[120],"cause":[129],"class_list":["post-6566","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-migracion-y-refugio","country-espana","cause-migracion-y-refugio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Organizaciones reclaman al gobierno que promueva una Europa sin dobles raseros - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organizaciones reclaman al gobierno que promueva una Europa sin dobles raseros\" \/>\n<meta property=\"og:description\" content=\"La adopci\u00f3n de la Directiva de Protecci\u00f3n Temporal (DPT), del pasado 3 de marzo de 2022, para otorgar protecci\u00f3n a las personas que huyen del conflicto de Ucrania durante un periodo de entre uno y tres a\u00f1os, supuso un hito hist\u00f3rico, ya que fue la primera vez que la Uni\u00f3n Europea la activaba desde su aprobaci\u00f3n en 2001. Sin embargo, otras nacionalidades en situaciones similares han quedado desprotegidas. Pedimos una Europa #SinDoblesRaseros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T10:33:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sin_dobles_raseros_meme.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\\\/\",\"name\":\"Organizaciones reclaman al gobierno que promueva una Europa sin dobles raseros - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/sin_dobles_raseros_meme.png\",\"datePublished\":\"2022-05-26T10:24:41+00:00\",\"dateModified\":\"2024-02-19T10:33:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/sin_dobles_raseros_meme.png\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/sin_dobles_raseros_meme.png\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Organizaciones reclaman al gobierno que promueva una Europa sin dobles raseros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Organizaciones reclaman al gobierno que promueva una Europa sin dobles raseros - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/","og_locale":"en_US","og_type":"article","og_title":"Organizaciones reclaman al gobierno que promueva una Europa sin dobles raseros","og_description":"La adopci\u00f3n de la Directiva de Protecci\u00f3n Temporal (DPT), del pasado 3 de marzo de 2022, para otorgar protecci\u00f3n a las personas que huyen del conflicto de Ucrania durante un periodo de entre uno y tres a\u00f1os, supuso un hito hist\u00f3rico, ya que fue la primera vez que la Uni\u00f3n Europea la activaba desde su aprobaci\u00f3n en 2001. Sin embargo, otras nacionalidades en situaciones similares han quedado desprotegidas. Pedimos una Europa #SinDoblesRaseros.","og_url":"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-19T10:33:12+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sin_dobles_raseros_meme.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/","url":"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/","name":"Organizaciones reclaman al gobierno que promueva una Europa sin dobles raseros - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sin_dobles_raseros_meme.png","datePublished":"2022-05-26T10:24:41+00:00","dateModified":"2024-02-19T10:33:12+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sin_dobles_raseros_meme.png","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2022\/05\/sin_dobles_raseros_meme.png","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/organizaciones-reclaman-al-gobierno-que-promueva-una-europa-sin-dobles-raseros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/en\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/en\/noticias\/"},{"@type":"ListItem","position":3,"name":"Organizaciones reclaman al gobierno que promueva una Europa sin dobles raseros"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/en\/#website","url":"https:\/\/www.entreculturas.org\/en\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/en\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/en\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/noticia\/6566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media\/6564"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media?parent=6566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/categories?post=6566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/tags?post=6566"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/country?post=6566"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/cause?post=6566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}