{"id":6069,"date":"2021-07-29T09:24:27","date_gmt":"2021-07-29T09:24:27","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=este-verano-la-educacion-no-se-detiene"},"modified":"2024-02-19T17:42:26","modified_gmt":"2024-02-19T16:42:26","slug":"este-verano-la-educacion-no-se-detiene","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/","title":{"rendered":"Este verano la educaci\u00f3n no se detiene"},"content":{"rendered":"<p>Este verano te invitamos a conocer cuatro historias y realidades desde distintos puntos del planeta, personas que siguen apostando por su futuro, y en el que, desde Entreculturas seguimos acompa\u00f1\u00e1ndoles sin descanso.&nbsp;<\/p>\n<p>Desde Brasil con la creaci\u00f3n de una casa de acogida en Boa Vista, hasta la Rep\u00fablica Democr\u00e1tica de Congo reduciendo el analfabetismo;&nbsp;pasando por Uganda para conocer el maravilloso testimonio de esperanza de Catherine, hasta llegar a Espa\u00f1a en un viaje que apenas comienza para Sineyi, una madre venezolana, solicitante de asilo.<\/p>\n<\/p>\n<p><span style=\"color:#FF0000\"><strong>Brasil: acogida y dignidad para las personas migrantes y refugiadas en Boa Vista<\/strong><\/span><br \/>Junto a Fe y Alegr\u00eda Brasil hemos puesto en marcha un proyecto de acci\u00f3n humanitaria y asistencia social y educativa dirigido a la poblaci\u00f3n migrante y refugiada venezolana en Boa Vista. Fruto de esta intervenci\u00f3n ha sido la reciente inauguraci\u00f3n de la Casa de Passagem Pe. Jos\u00e9 Maria V\u00e9laz, SJ, un albergue que no solo ofrece un espacio seguro donde dormir y donde acceder a una alimentaci\u00f3n completa, sino que brinda otros servicios b\u00e1sicos como son internet, transporte local, actividades socioeducativas y de prevenci\u00f3n de riesgos. <a href=\"https:\/\/www.entreculturas.org\/es\/noticias\/brasil-acogida-y-dignidad-para-las-personas-migrantes-y-refugiadas-en-boa-vista\" target=\"_blank\" rel=\"noopener\"><strong>Leer +<\/strong><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/01.jpg\" width=\"800\"><\/p>\n<p><span style=\"color:#FF0000\"><strong>\u2018Kielo ya mazaya\u2019: reduciendo el analfabetismo en R. D. del Congo<\/strong><\/span><br \/>Entreculturas, Alboan y Radio ECCA (instituci\u00f3n radiof\u00f3nica educativa localizada en Canarias) hemos aunado esfuerzos junto a Fe y Alegr\u00eda para iniciar el proyecto de alfabetizaci\u00f3n \u2018Kielo ya mazaya\u2019 (\u2018Puerta al conocimiento\u2019), que tiene como objetivo ofrecer la oportunidad de aprender a escribir, leer y calcular en franc\u00e9s (la lengua del entorno administrativo en el pa\u00eds) a personas analfabetas de la poblaci\u00f3n de Kikwit. En terreno contamos adem\u00e1s con la colaboraci\u00f3n de la emisora comunitaria Radio Tomisa, comprometida con la educaci\u00f3n y los derechos humanos y que cuenta con cobertura en toda la comarca. <a href=\"https:\/\/www.entreculturas.org\/es\/noticias\/kielo-ya-mazaya-reduciendo-el-analfabetismo-en-r-d-del-congo\" target=\"_blank\" rel=\"noopener\"><strong>Leer +<\/strong><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/02.jpg\" width=\"800\"><\/p>\n<p><span style=\"color:#FF0000\"><strong>El viaje de Sineyi<\/strong><\/span><br \/>Sineyi es venezolana, madre y solicitante de asilo. Ahora vive en Valencia, donde desde hace unos meses est\u00e1 construyendo una nueva vida para ella y su hija, Sidney, gracias al acompa\u00f1amiento del Servicio Jesuita a Migrantes (SJM), despu\u00e9s de un camino lleno de dificultades. Su historia de vida la pudimos conocer durante la rueda de prensa de la campa\u00f1a Caminos de Hospitalidad #SumoMiCamino. Una historia tan dura como la de las miles de personas refugiadas y migrantes que se ven obligadas a dejarlo todo atr\u00e1s, empujadas por la guerra, los conflictos o la persecuci\u00f3n. <a href=\"https:\/\/www.entreculturas.org\/es\/noticias\/el-viaje-de-sineyi\" target=\"_blank\" rel=\"noopener\"><strong>Leer +<\/strong><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" height=\"400\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/04.jpg\" width=\"800\"><\/p>\n<p><span style=\"color:#FF0000\"><strong>Uganda: \u201cLa educaci\u00f3n es el arma m\u00e1s poderosa que tenemos para prosperar en el futuro\u201d<\/strong><\/span><br \/>Catherine es una de las participantes del proyecto de JRS que apoyamos desde Entreculturas, y que tiene como objetivo facilitar el acceso a una educaci\u00f3n secundaria de calidad tanto por parte de las personas refugiadas de Sud\u00e1n del Sur como por parte de la comunidad de acogida. Un proyecto que ha becado a 35 estudiantes, entre los que se encuentra Catherine. \u201cMe han ayudado a pagar mis estudios de secundaria y siguen escuch\u00e1ndome y ofreci\u00e9ndome ayuda en estos momentos dif\u00edciles\u201d, nos cuenta Catherine. <a href=\"https:\/\/www.entreculturas.org\/es\/noticias\/la-educacion-es-el-arma-mas-poderosa-que-tenemos-para-prosperar-en-el-futuro\" target=\"_blank\" rel=\"noopener\"><strong>Leer +<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde Brasil con la creaci\u00f3n de una casa de acogida en Boa Vista, hasta la Rep\u00fablica Democr\u00e1tica de Congo reduciendo el analfabetismo, pasando por Uganda para conocer el maravilloso testimonio de esperanza de Catherine, hasta llegar a Espa\u00f1a en un viaje que apenas comienza para Sineyi, una madre venezolana, solicitante de asilo.<\/p>\n","protected":false},"featured_media":6072,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[289],"country":[],"cause":[128],"class_list":["post-6069","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-educacion","cause-educacion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Este verano la educaci\u00f3n no se detiene - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este verano la educaci\u00f3n no se detiene\" \/>\n<meta property=\"og:description\" content=\"Desde Brasil con la creaci\u00f3n de una casa de acogida en Boa Vista, hasta la Rep\u00fablica Democr\u00e1tica de Congo reduciendo el analfabetismo, pasando por Uganda para conocer el maravilloso testimonio de esperanza de Catherine, hasta llegar a Espa\u00f1a en un viaje que apenas comienza para Sineyi, una madre venezolana, solicitante de asilo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T16:42:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/principal_historias_verano_entreculturas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"648\" \/>\n\t<meta property=\"og:image:height\" content=\"257\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/este-verano-la-educacion-no-se-detiene\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/este-verano-la-educacion-no-se-detiene\\\/\",\"name\":\"Este verano la educaci\u00f3n no se detiene - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/este-verano-la-educacion-no-se-detiene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/este-verano-la-educacion-no-se-detiene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/principal_historias_verano_entreculturas.jpg\",\"datePublished\":\"2021-07-29T09:24:27+00:00\",\"dateModified\":\"2024-02-19T16:42:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/este-verano-la-educacion-no-se-detiene\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/este-verano-la-educacion-no-se-detiene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/este-verano-la-educacion-no-se-detiene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/principal_historias_verano_entreculturas.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/principal_historias_verano_entreculturas.jpg\",\"width\":648,\"height\":257,\"caption\":\"principal_historias_verano_entreculturas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/este-verano-la-educacion-no-se-detiene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Este verano la educaci\u00f3n no se detiene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Este verano la educaci\u00f3n no se detiene - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/","og_locale":"en_US","og_type":"article","og_title":"Este verano la educaci\u00f3n no se detiene","og_description":"Desde Brasil con la creaci\u00f3n de una casa de acogida en Boa Vista, hasta la Rep\u00fablica Democr\u00e1tica de Congo reduciendo el analfabetismo, pasando por Uganda para conocer el maravilloso testimonio de esperanza de Catherine, hasta llegar a Espa\u00f1a en un viaje que apenas comienza para Sineyi, una madre venezolana, solicitante de asilo.","og_url":"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-19T16:42:26+00:00","og_image":[{"width":648,"height":257,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/principal_historias_verano_entreculturas.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/","url":"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/","name":"Este verano la educaci\u00f3n no se detiene - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/principal_historias_verano_entreculturas.jpg","datePublished":"2021-07-29T09:24:27+00:00","dateModified":"2024-02-19T16:42:26+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/principal_historias_verano_entreculturas.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/07\/principal_historias_verano_entreculturas.jpg","width":648,"height":257,"caption":"principal_historias_verano_entreculturas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/este-verano-la-educacion-no-se-detiene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/en\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/en\/noticias\/"},{"@type":"ListItem","position":3,"name":"Este verano la educaci\u00f3n no se detiene"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/en\/#website","url":"https:\/\/www.entreculturas.org\/en\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/en\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/en\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/noticia\/6069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media\/6072"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media?parent=6069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/categories?post=6069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/tags?post=6069"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/country?post=6069"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/cause?post=6069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}