{"id":5671,"date":"2021-03-29T07:40:06","date_gmt":"2021-03-29T07:40:06","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento"},"modified":"2024-02-28T18:03:21","modified_gmt":"2024-02-28T17:03:21","slug":"jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/","title":{"rendered":"JRS MENA y Entreculturas demandamos un apoyo renovado para el pueblo sirio y su sufrimiento colectivo en la V Conferencia de Bruselas sobre el apoyo al futuro de Siria y la regi\u00f3n"},"content":{"rendered":"<\/p>\n<p><span style=\"font-size:16px\"><span style=\"color:#FF0000\"><strong>Recomendaciones a las delegaciones que asistan a la Quinta Conferencia de Bruselas sobre el Apoyo al Futuro de Siria y su Regi\u00f3n<\/strong><\/span><\/span><\/p>\n<p>La UE y la ONU ser\u00e1n coanfitriones de la quinta Conferencia Internacional sobre el Apoyo al Futuro de Siria y su regi\u00f3n, el pr\u00f3ximo 30 de marzo de 2021. La conferencia es una oportunidad para que las delegaciones estatales <strong>trabajen para alcanzar una soluci\u00f3n pol\u00edtica en Siria y se comprometan a dar apoyo financiero al pa\u00eds <\/strong>y a los estados de la regi\u00f3n que albergan a un gran n\u00famero de personas refugiadas sirias. Este apoyo se hace m\u00e1s necesario que nunca al celebrarse el d\u00e9cimo a\u00f1o del inicio del conflicto en Siria.<\/p>\n<p>El Servicio Jesuita a Refugiados de la regi\u00f3n (JRS MENA) y Entreculturas apoyan a las personas desplazadas por el conflicto en Siria, as\u00ed como a las comunidades de acogida vulnerables de la regi\u00f3n. A trav\u00e9s de este trabajo, que incluye servicios de educaci\u00f3n, salud mental, medios de vida y programas de protecci\u00f3n, vemos de primera mano la realidad actual en Siria y los pa\u00edses vecinos.<\/p>\n<p>En base a este conocimiento, dirigimos las siguientes recomendaciones a las delegaciones que asistan a la Quinta Conferencia de Bruselas sobre el Apoyo al Futuro de Siria y su Regi\u00f3n:<\/p>\n<p><span style=\"color:#FF0000\"><strong>1. Responder a las necesidades cr\u00edticas mediante el aumento de financiaci\u00f3n y revisar el impacto de las sanciones en la poblaci\u00f3n civil.<\/strong><\/span><\/p>\n<p>Las necesidades de la poblaci\u00f3n siria desplazada y las comunidades de acogida vulnerables no han disminuido con la prolongaci\u00f3n de la crisis. Ahora m\u00e1s que nunca, estas personas no pueden satisfacer sus necesidades b\u00e1sicas y se debe aumentar la asistencia humanitaria, prestando especial atenci\u00f3n a las necesidades de los m\u00e1s vulnerables, incluidos los ni\u00f1os\/as, las mujeres y las personas ancianas. Se estima que <strong>11 millones de personas dentro de Siria necesitan asistencia humanitaria, 4,8 millones de las cuales son ni\u00f1os y ni\u00f1as[i].<\/strong> La econom\u00eda siria ha llegado a un punto de crisis extrema y casi el 60% de la poblaci\u00f3n carece de acceso a alimentos suficientes. Las sanciones impuestas por la comunidad internacional han empeorado la situaci\u00f3n econ\u00f3mica y han perjudicado a la poblaci\u00f3n m\u00e1s vulnerable. En L\u00edbano, el 50% de la poblaci\u00f3n local viven actualmente por debajo del umbral de pobreza, mientras que el 89% de los\/as sirios\/as viven en la pobreza extrema[ii]. En Jordania, un alarmante 65% de la poblaci\u00f3n refugiada siria informa que no tienen c\u00f3mo comprar alimentos suficientes[iii].<\/p>\n<p>A trav\u00e9s de nuestra experiencia en la regi\u00f3n, vemos que tambi\u00e9n existen deficiencias y necesidades cr\u00edticas en salud, salud mental, protecci\u00f3n y educaci\u00f3n. En Siria, multitud de ni\u00f1os y ni\u00f1as se han visto obligados a abandonar la escuela debido a problemas diversos como el desplazamiento forzoso, ataques a escuelas, trabajo infantil, restricciones derivadas del COVID-19, hacinamiento en las escuelas y a la falta de medios de vida. 2,4 millones de ni\u00f1os\/as en Siria est\u00e1n fuera del sistema educativo y se estima que trabajan en aproximadamente el 75% de los hogares. <strong>En L\u00edbano, m\u00e1s de la mitad de los ni\u00f1os\/as en edad escolar no est\u00e1n escolarizados<\/strong> y en Jordania la cifra se sit\u00faa en el 40%. La educaci\u00f3n es un derecho humano, una parte esencial de la respuesta humanitaria y est\u00e1 estrechamente vinculada a la protecci\u00f3n de los ni\u00f1os\/as. Creemos firmemente que lograr una educaci\u00f3n inclusiva y de calidad para todos es uno de las herramientas m\u00e1s poderosas y probadas para alcanzar el desarrollo sostenible y es vital para alcanzar el resto de Objetivos de Desarrollo Sostenible de las Naciones Unidas.<\/p>\n<p>Los participantes de la conferencia deben comprometerse a proveer una financiaci\u00f3n plurianual adecuada para estos sectores que sea flexible a los desaf\u00edos actuales que se presentan en medio de la crisis provocada por el COVID-19. La comunidad internacional deber\u00eda considerar la Conferencia de Bruselas como una oportunidad para revisar el impacto de las sanciones impuestas a la poblaci\u00f3n civil siria.<\/p>\n<p><span style=\"color:#FF0000\"><strong>2. Invertir en la generaci\u00f3n de medios de vida para mejorar la cohesi\u00f3n social y la resiliencia.<\/strong><\/span><\/p>\n<p>La respuesta humanitaria a las necesidades cr\u00edticas debe ir acompa\u00f1ada de un enfoque a m\u00e1s largo plazo que considere la resiliencia. Siria y los pa\u00edses vecinos que acogen a la poblaci\u00f3n refugiada siria se enfrentan actualmente a m\u00faltiples crisis sin precedentes. Por ejemplo, L\u00edbano, el estado con la mayor proporci\u00f3n de refugiados\/as per c\u00e1pita en el mundo ahora se ubica tambi\u00e9n como el segundo pa\u00eds con mayor inflaci\u00f3n. Adem\u00e1s de la pandemia COVID-19, el a\u00f1o pasado el pa\u00eds experiment\u00f3 un colapso econ\u00f3mico, una fuerte inestabilidad pol\u00edtica y una explosi\u00f3n s\u00edsmica en Beirut que acab\u00f3 con la vida de 200 personas, hiri\u00f3 a 7.000 y dej\u00f3 a miles sin hogar. Se deben proporcionar m\u00e1s fondos para ayudar a las comunidades de acogida a trav\u00e9s de <strong>proyectos de desarrollo que busquen construir uniones s\u00f3lidas e innovadoras entre poblaci\u00f3n local y refugiada.<\/strong><\/p>\n<p>La inversi\u00f3n en medios de vida es tambi\u00e9n una parte clave del fomento de la resiliencia. El acceso al empleo es escaso en muchos pa\u00edses de acogida; por ejemplo, en Jordania, el \u00edndice de desempleo se ha incrementado del 19% en 2019 al 23% en 2020[iv], llegando hasta el 65% en la poblaci\u00f3n refugiada siria, gran parte de la cual ha perdido su principal medio de vida en el \u00faltimo a\u00f1o debido al COVID-19[v]. La creaci\u00f3n de empleo ayudar\u00e1 a mantener la cohesi\u00f3n social y reducir\u00e1 las tensiones entre las comunidades de acogida y refugiada, mientras que para la poblaci\u00f3n refugiada puede suponer una fuente de ingresos que les salve la vida. Estos esfuerzos deben ir acompa\u00f1ados de una mejora del acceso a la documentaci\u00f3n legal y al permiso de trabajo, que actualmente est\u00e1 muy restringido en algunos estados como Jordania y L\u00edbano.<\/p>\n<p><span style=\"color:#FF0000\"><strong>3. Los estados regionales e internacionales deben detener por completo la devoluci\u00f3n forzosa de migrantes. Todo regreso debe ser voluntario, seguro, digno y sostenible de acuerdo con los principios humanitarios.<\/strong><\/span><\/p>\n<p>A pesar de los innumerables desaf\u00edos pol\u00edticos, sociales, econ\u00f3micos y de salud a los que se enfrentan los pa\u00edses de acogida, <strong>muchos sirios\/as con los\/as que trabajamos en el L\u00edbano y Jordania no se sienten capaces de regresar a Siria. <\/strong>Entre los gobiernos regionales, ha habido numerosos intentos de devolver a la poblaci\u00f3n refugiada siria a su pa\u00eds. Sirven de ejemplos la conferencia sobre el retorno de refugiados organizada en Damasco en noviembre de 2020 por el gobierno sirio con el apoyo de Rusia o la declaraci\u00f3n de mayo de 2019 del gobierno liban\u00e9s con la que habilitaba a deportar personas de nacionalidad siria que hubieran entrado en L\u00edbano de forma irregular a partir de esa fecha. Los estados europeos han mantenido un consenso general de que la situaci\u00f3n en Siria a\u00fan no es segura para los retornos[vi], sin embargo, Dinamarca ha declarado recientemente que partes del pa\u00eds s\u00ed son seguras y es la primera naci\u00f3n de la UE que dictamina que los refugiados pueden regresar[vii]. Esto podr\u00eda convertirse en una tendencia preocupante si otros pa\u00edses de asilo siguen el ejemplo dan\u00e9s. Alentamos a las delegaciones de la conferencia a reiterar su apoyo a los principios y normas internacionales para el retorno y a reconocer que a\u00fan no se cumplen las condiciones para el regreso a Siria.<\/p>\n<p><span style=\"color:#FF0000\"><strong>4. Compartir la responsabilidad a trav\u00e9s de la provisi\u00f3n de oportunidades de asilo, reasentamiento y v\u00edas complementarias.<\/strong><\/span><\/p>\n<p>Una gran mayor\u00eda de sirios\/as desplazados vive en pa\u00edses vecinos de Siria. Estos pa\u00edses est\u00e1n experimentando algunos de los cambios y desaf\u00edos m\u00e1s importantes de su historia reciente. Con personas que luchan por sobrevivir, el reasentamiento seguro en otro pa\u00eds puede suponer un salvavidas para estas personas. La comunidad internacional puede y debe compartir la responsabilidad y debe apoyar a m\u00e1s personas comprometi\u00e9ndose a aumentar los lugares de reasentamiento, las v\u00edas complementarias para el asentamiento y manteniendo abiertos los procesos de asilo para la poblaci\u00f3n de origen sirio.<br \/><strong>JRS MENA y Entreculturas continuar\u00e1n trabajando junto a aquellos que se han visto afectados por el conflicto sirio, <\/strong>tanto dentro de Siria como en toda la regi\u00f3n. Contar\u00e1n con nuestro apoyo mientras trazan su camino a seguir. Instamos a la comunidad global a unirse en este esfuerzo y priorizar sus necesidades.<br \/>&nbsp;<\/p>\n<p><span style=\"font-size:12px\">[i] UNICEF, Syrian Arab Republic Appeal, <a href=\"https:\/\/www.unicef.org\/appeals\/syria\">https:\/\/www.unicef.org\/appeals\/syria<\/a><br \/>[ii]WFP, 2020, Nine out of ten Syrian refugee families in Lebanon are now living in extreme poverty, UN study says, <a href=\"https:\/\/www.wfp.org\/news\/nine-out-ten-syrian-refugee-families-lebanon-are-now-living-extreme-poverty-un-study-says#:~:text=One%20of%20the%20most%20concerning,cent%20only%20a%20year%20before.\">https:\/\/www.wfp.org\/news\/nine-out-ten-syrian-refugee-families-lebanon-are-now-living-extreme-poverty-un-study-says#:~:text=One%20of%20the%20most%20concerning,cent%20only%20a%20year%20before.<\/a><br \/>[iii] Jordan INGO Forum, 2021, Walk the Talk<br \/>[iv] Badarin, 2020, Jordan\u2019s economic, security and political challenges under Covid-19, <a href=\"https:\/\/www.tandfonline.com\/doi\/full\/10.1080\/13629395.2020.1850624\">https:\/\/www.tandfonline.com\/doi\/full\/10.1080\/13629395.2020.1850624<\/a><br \/>[v] Jordan INGO Forum, 2021, Walk the Talk<br \/>[vi] European Parliament press release, 2021, MEPs \u2018remind all EU member states that Syria is not a safe country to return to and believe any return should be safe, voluntary, dignified and informed\u2019, <a href=\"https:\/\/www.europarl.europa.eu\/news\/en\/press-room\/20210304IPR99218\/syria-needs-a-greater-financial-and-political-response-from-the-eu\">https:\/\/www.europarl.europa.eu\/news\/en\/press-room\/20210304IPR99218\/syria-needs-a-greater-financial-and-political-response-from-the-eu<\/a><br \/>[vii] InfoMigrants, 2021, Denmark declares parts of Syria safe, pressuring refugees to return, <a href=\"https:\/\/www.infomigrants.net\/en\/post\/30650\/denmark-declares-parts-of-syria-safe-pressuring-refugees-to-return#:~:text=Denmark%20declares%20parts%20of%20Syria%20safe%2C%20pressuring%20refugees%20to%20return,-Published%20on%20%3A%202021&amp;text=Denmark%20has%20stripped%2094%20Syrian,be%20sent%20back%20to%20Syria.\">https:\/\/www.infomigrants.net\/en\/post\/30650\/denmark-declares-parts-of-syria-safe-pressuring-refugees-to-return#:~:text=Denmark%20declares%20parts%20of%20Syria%20safe%2C%20pressuring%20refugees%20to%20return,-Published%20on%20%3A%202021&amp;text=Denmark%20has%20stripped%2094%20Syrian,be%20sent%20back%20to%20Syria.<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Quinta Conferencia de Bruselas sobre el Apoyo al Futuro de Siria y su Regi\u00f3n es una oportunidad para que las delegaciones estatales trabajen para alcanzar una soluci\u00f3n pol\u00edtica en Siria y se comprometan a dar apoyo financiero al pa\u00eds y a los estados de la regi\u00f3n que albergan a un gran n\u00famero de personas refugiadas sirias.<\/p>\n","protected":false},"featured_media":5672,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[10],"country":[460],"cause":[129],"class_list":["post-5671","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-migracion-y-refugio","country-siria","cause-migracion-y-refugio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>JRS MENA y Entreculturas demandamos un apoyo renovado para el pueblo sirio y su sufrimiento colectivo en la V Conferencia de Bruselas sobre el apoyo al futuro de Siria y la regi\u00f3n - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JRS MENA y Entreculturas demandamos un apoyo renovado para el pueblo sirio y su sufrimiento colectivo en la V Conferencia de Bruselas sobre el apoyo al futuro de Siria y la regi\u00f3n\" \/>\n<meta property=\"og:description\" content=\"La Quinta Conferencia de Bruselas sobre el Apoyo al Futuro de Siria y su Regi\u00f3n es una oportunidad para que las delegaciones estatales trabajen para alcanzar una soluci\u00f3n pol\u00edtica en Siria y se comprometan a dar apoyo financiero al pa\u00eds y a los estados de la regi\u00f3n que albergan a un gran n\u00famero de personas refugiadas sirias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T17:03:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/03\/makeshift_home_in_a_camp_in_the_bekaa_valley_2016dec.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\\\/\",\"name\":\"JRS MENA y Entreculturas demandamos un apoyo renovado para el pueblo sirio y su sufrimiento colectivo en la V Conferencia de Bruselas sobre el apoyo al futuro de Siria y la regi\u00f3n - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/makeshift_home_in_a_camp_in_the_bekaa_valley_2016dec.jpg\",\"datePublished\":\"2021-03-29T07:40:06+00:00\",\"dateModified\":\"2024-02-28T17:03:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/makeshift_home_in_a_camp_in_the_bekaa_valley_2016dec.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/makeshift_home_in_a_camp_in_the_bekaa_valley_2016dec.jpg\",\"width\":1080,\"height\":720,\"caption\":\"makeshift_home_in_a_camp_in_the_bekaa_valley_2016dec\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JRS MENA y Entreculturas demandamos un apoyo renovado para el pueblo sirio y su sufrimiento colectivo en la V Conferencia de Bruselas sobre el apoyo al futuro de Siria y la regi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"JRS MENA y Entreculturas demandamos un apoyo renovado para el pueblo sirio y su sufrimiento colectivo en la V Conferencia de Bruselas sobre el apoyo al futuro de Siria y la regi\u00f3n - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/","og_locale":"en_US","og_type":"article","og_title":"JRS MENA y Entreculturas demandamos un apoyo renovado para el pueblo sirio y su sufrimiento colectivo en la V Conferencia de Bruselas sobre el apoyo al futuro de Siria y la regi\u00f3n","og_description":"La Quinta Conferencia de Bruselas sobre el Apoyo al Futuro de Siria y su Regi\u00f3n es una oportunidad para que las delegaciones estatales trabajen para alcanzar una soluci\u00f3n pol\u00edtica en Siria y se comprometan a dar apoyo financiero al pa\u00eds y a los estados de la regi\u00f3n que albergan a un gran n\u00famero de personas refugiadas sirias.","og_url":"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-02-28T17:03:21+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/03\/makeshift_home_in_a_camp_in_the_bekaa_valley_2016dec.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/","url":"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/","name":"JRS MENA y Entreculturas demandamos un apoyo renovado para el pueblo sirio y su sufrimiento colectivo en la V Conferencia de Bruselas sobre el apoyo al futuro de Siria y la regi\u00f3n - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/03\/makeshift_home_in_a_camp_in_the_bekaa_valley_2016dec.jpg","datePublished":"2021-03-29T07:40:06+00:00","dateModified":"2024-02-28T17:03:21+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/03\/makeshift_home_in_a_camp_in_the_bekaa_valley_2016dec.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2021\/03\/makeshift_home_in_a_camp_in_the_bekaa_valley_2016dec.jpg","width":1080,"height":720,"caption":"makeshift_home_in_a_camp_in_the_bekaa_valley_2016dec"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/jrs-mena-y-entreculturas-demandamos-un-apoyo-renovado-para-el-pueblo-sirio-y-su-sufrimiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/en\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/en\/noticias\/"},{"@type":"ListItem","position":3,"name":"JRS MENA y Entreculturas demandamos un apoyo renovado para el pueblo sirio y su sufrimiento colectivo en la V Conferencia de Bruselas sobre el apoyo al futuro de Siria y la regi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/en\/#website","url":"https:\/\/www.entreculturas.org\/en\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/en\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/en\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/noticia\/5671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media\/5672"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media?parent=5671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/categories?post=5671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/tags?post=5671"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/country?post=5671"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/cause?post=5671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}