{"id":5100,"date":"2020-09-07T07:26:23","date_gmt":"2020-09-07T07:26:23","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la"},"modified":"2024-03-06T17:57:34","modified_gmt":"2024-03-06T16:57:34","slug":"entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/","title":{"rendered":"Entreculturas y Alboan ponen en valor el voluntariado internacional como agente clave de la cooperaci\u00f3n espa\u00f1ola"},"content":{"rendered":"<p>El d\u00eda 8 de septiembre es el D\u00eda del Cooperante, una fecha para reconocer la labor de los y las cooperantes espa\u00f1oles que trabajan en las zonas menos favorecidas de nuestro planeta y para sensibilizar a la sociedad respecto a la labor que desempe\u00f1an. Este d\u00eda <strong>celebramos el d\u00eda de la cooperaci\u00f3n internacional y de las personas que la hacen posible<\/strong>, entre ellas el voluntariado internacional por el aporte que ha hecho y sigue haciendo a la cooperaci\u00f3n espa\u00f1ola.<\/p>\n<p>En este 8 de septiembre desde Entreculturas y Alboan queremos,&nbsp;por una parte, \u201cvisibilizar y poner en valor el voluntariado internacional como agente clave de la cooperaci\u00f3n espa\u00f1ola, y, por otra,&nbsp;manifestar, que si bien se ha avanzado con la inclusi\u00f3n del voluntariado internacional en la Ley de Voluntariado de 2015, el cumplimiento de los derechos de este colectivo es parcial y limitado a lo que puedan hacer las organizaciones de cooperaci\u00f3n.<strong> &#8220;Los derechos de las personas voluntarias pasan a ser deberes de las organizaciones, sin contar con el respaldo de las administraciones\u201d<\/strong>, afirma David Alonso, Director de Personas y Organizaci\u00f3n de Entreculturas, direcci\u00f3n a la que se adscribe este voluntariado internacional.&nbsp;<\/p>\n<\/p>\n<p>Queremos reconocer la labor del voluntariado internacional en la <strong>promoci\u00f3n de los objetivos de la cooperaci\u00f3n y su contribuci\u00f3n en el alcance de la Agenda 2030.<\/strong> En los m\u00e1s de 29 a\u00f1os de experiencia con programas de voluntariado internacional de larga duraci\u00f3n como VOLPA, que ofrecemos&nbsp;Entreculturas y Alboan, en el que desde sus inicios en 1991 <strong>m\u00e1s de 1000 personas han participado como voluntarias<\/strong> en proyectos de cooperaci\u00f3n al desarrollo con las instituciones socias de ambas ONGD espa\u00f1olas en contextos de alta vulnerabilidad.&nbsp;Desde Entreculturas y Alboan&nbsp;podemos decir con seguridad que el voluntariado internacional:<\/p>\n<ul>\n<li>Transforma la vida de las personas, ya que cambia prioridades, valores y maneras de relacionarse.\u2028<\/li>\n<li>Permite entender las din\u00e1micas globales y profundizar en las causas de la desigualdad. \u2028<\/li>\n<li>Vincula a personas de distintos&nbsp; lugares, realidades y culturas. Elimina prejuicios y ayuda a descubrir la riqueza de la diversidad. \u2028<\/li>\n<li>Permite compartir habilidades, conocimientos e instrumentos en los lugares y organizaciones que acogen al voluntariado desde la cercan\u00eda y la confianza mutua.\u2028<\/li>\n<li>Convierte a la persona en un agente transformador para toda la vida.\u2028<br \/>&nbsp;<\/li>\n<\/ul>\n<p>Desde este aporte claro del voluntariado internacional a la agenda de desarrollo \u201cqueremos manifestar esta realidad invisible, o mejor dicho, invisibilizada y poco reconocida y&nbsp; apoyada por las Administraciones P\u00fablicas del voluntariado internacional e invitar a la sociedad civil organizada y especialmente a las administraciones p\u00fablicas a visibilizar y fomentar programas de voluntariado internacional realizados con calidad y calidez\u201d, se\u00f1ala David Alonso.&nbsp;<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/fernando_brasil_4.jpg\" style=\"width: 800px;height: 450px\"><\/p>\n<p>Desde Entreculturas y Alboan&nbsp;creemos&nbsp;que para que esto se d\u00e9 es necesario que el voluntariado internacional:<\/p>\n<ul>\n<li>Tenga una <strong>regulaci\u00f3n espec\u00edfica<\/strong> dentro del marco de la cooperaci\u00f3n para el desarrollo reconociendo esta realidad propia y que permita salir del limbo legal y la invisibilidad en la que se encuentra.&nbsp; \u2028<\/li>\n<li>Un papel clave en esto lo tiene la Agencia Espa\u00f1ola de Cooperaci\u00f3n (AECID) y las agencias auton\u00f3micas. Es fundamental que <strong>reconozcan este voluntariado como instrumento de la cooperaci\u00f3n<\/strong> que realizan. Esto implica hacerse cargo del mismo con una atenci\u00f3n expl\u00edcita en sus estrategias, planificaciones, modalidades, medidas de fomento, etc. pero tambi\u00e9n que apuesten por un modelo de acreditaci\u00f3n de las organizaciones que aseguren la calidad de las propuestas y procesos y eviten malas pr\u00e1cticas que convierten al voluntariado internacional en \u201cvolunturismo\u201d o en pr\u00e1cticas a\u00fan m\u00e1s negativas.\u2028<\/li>\n<li>Proponemos que la AECID pueda concertar un <strong>seguro colectivo<\/strong> en favor de las personas voluntarias de cooperaci\u00f3n al desarrollo, al que pueden adherirse las organizaciones, asumiendo \u00e9stas una parte del coste pero no su totalidad. Un formato al menos similar al que aparece en el Estatuto del cooperante, m\u00e1s teniendo en cuenta que el voluntariado internacional no cuenta con fuentes frecuentes de financiaci\u00f3n v\u00eda proyectos.&nbsp; \u2028<\/li>\n<li>Cuente con un<strong> convenio especial <\/strong>para las personas voluntarias al servicio de la cooperaci\u00f3n internacional de larga duraci\u00f3n. Que este convenio especial garantice no solamente prestaciones contributivas de jubilaci\u00f3n, incapacidad permanente, muerte o supervivencia, sino tambi\u00e9n las prestaciones de incapacidad temporal, maternidad y desempleo.\u2028<\/li>\n<li>Un <strong>registro de las personas<\/strong> que realizan el voluntariado internacional por parte de la AECID, en coordinaci\u00f3n con las agencias auton\u00f3micas, que pueda conocer en cada momento que ciudadan\u00eda espa\u00f1ola est\u00e1 en esta modalidad aportando en las claves mencionadas en pa\u00edses de intervenci\u00f3n de la cooperaci\u00f3n espa\u00f1ola. Esto permitir\u00e1, adem\u00e1s de atender las posibles emergencias con mayor consciencia, realizar informes peri\u00f3dicos que puedan recoger el impacto y el cambio social que este voluntariado realiza y visibilizarlo como otras cooperaciones europeas realizan. \u2028<br \/>&nbsp;<\/li>\n<\/ul>\n<p>&nbsp;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 8 de septiembre es el D\u00eda del Cooperante, una fecha para reconocer la labor de los y las cooperantes espa\u00f1oles que trabajan en las zonas menos favorecidas de nuestro planeta y para sensibilizar a la sociedad respecto a la labor que desempe\u00f1an. Este d\u00eda celebramos el d\u00eda de la cooperaci\u00f3n internacional y de las personas que la hacen posible, entre ellas el voluntariado internacional por el aporte que ha hecho y sigue haciendo a la cooperaci\u00f3n espa\u00f1ola.<\/p>\n","protected":false},"featured_media":5097,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[8],"country":[],"cause":[132],"class_list":["post-5100","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-participacion-y-ciudadania-global","cause-participacion-y-ciudadania-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Entreculturas y Alboan ponen en valor el voluntariado internacional como agente clave de la cooperaci\u00f3n espa\u00f1ola - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entreculturas y Alboan ponen en valor el voluntariado internacional como agente clave de la cooperaci\u00f3n espa\u00f1ola\" \/>\n<meta property=\"og:description\" content=\"El d\u00eda 8 de septiembre es el D\u00eda del Cooperante, una fecha para reconocer la labor de los y las cooperantes espa\u00f1oles que trabajan en las zonas menos favorecidas de nuestro planeta y para sensibilizar a la sociedad respecto a la labor que desempe\u00f1an. Este d\u00eda celebramos el d\u00eda de la cooperaci\u00f3n internacional y de las personas que la hacen posible, entre ellas el voluntariado internacional por el aporte que ha hecho y sigue haciendo a la cooperaci\u00f3n espa\u00f1ola.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T16:57:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/mg_7991.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\\\/\",\"name\":\"Entreculturas y Alboan ponen en valor el voluntariado internacional como agente clave de la cooperaci\u00f3n espa\u00f1ola - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/mg_7991.jpg\",\"datePublished\":\"2020-09-07T07:26:23+00:00\",\"dateModified\":\"2024-03-06T16:57:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/mg_7991.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/mg_7991.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticia\\\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Entreculturas y Alboan ponen en valor el voluntariado internacional como agente clave de la cooperaci\u00f3n espa\u00f1ola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Entreculturas y Alboan ponen en valor el voluntariado internacional como agente clave de la cooperaci\u00f3n espa\u00f1ola - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/","og_locale":"en_US","og_type":"article","og_title":"Entreculturas y Alboan ponen en valor el voluntariado internacional como agente clave de la cooperaci\u00f3n espa\u00f1ola","og_description":"El d\u00eda 8 de septiembre es el D\u00eda del Cooperante, una fecha para reconocer la labor de los y las cooperantes espa\u00f1oles que trabajan en las zonas menos favorecidas de nuestro planeta y para sensibilizar a la sociedad respecto a la labor que desempe\u00f1an. Este d\u00eda celebramos el d\u00eda de la cooperaci\u00f3n internacional y de las personas que la hacen posible, entre ellas el voluntariado internacional por el aporte que ha hecho y sigue haciendo a la cooperaci\u00f3n espa\u00f1ola.","og_url":"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-03-06T16:57:34+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/mg_7991.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/","url":"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/","name":"Entreculturas y Alboan ponen en valor el voluntariado internacional como agente clave de la cooperaci\u00f3n espa\u00f1ola - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/mg_7991.jpg","datePublished":"2020-09-07T07:26:23+00:00","dateModified":"2024-03-06T16:57:34+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/mg_7991.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/09\/mg_7991.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/en\/noticia\/entreculturas-y-alboan-ponen-en-valor-el-voluntariado-internacional-como-agente-clave-de-la\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/en\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/en\/noticias\/"},{"@type":"ListItem","position":3,"name":"Entreculturas y Alboan ponen en valor el voluntariado internacional como agente clave de la cooperaci\u00f3n espa\u00f1ola"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/en\/#website","url":"https:\/\/www.entreculturas.org\/en\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/en\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/en\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/noticia\/5100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media\/5097"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/media?parent=5100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/categories?post=5100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/tags?post=5100"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/country?post=5100"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/en\/wp-json\/wp\/v2\/cause?post=5100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}