{"id":46729,"date":"2026-03-05T08:39:00","date_gmt":"2026-03-05T07:39:00","guid":{"rendered":"https:\/\/www.entreculturas.org\/?post_type=podcast&#038;p=46729"},"modified":"2026-03-05T12:56:39","modified_gmt":"2026-03-05T11:56:39","slug":"julia-navarro-podcast-ong-centroamerica","status":"publish","type":"podcast","link":"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/","title":{"rendered":"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez: &#8220;Encuentro la esperanza sobre todo entre las personas pobres, no entre los poderosos&#8221;"},"content":{"rendered":"\n<p>Esta semana en el podcast de <a href=\"https:\/\/www.entreculturas.org\/podcast\/\">Voces por una Causa<\/a>, la escritora <strong>Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson, salvadore\u00f1o, antrop\u00f3logo, cronista y escritor. <\/strong>Autor de obras como Ver, o\u00edr y callar, El ni\u00f1o de Hollywood y El que tenga miedo a morir que no nazca, su trabajo combina investigaci\u00f3n rigurosa y mirada literaria. Junto a \u00e9l, Julia Navarro nos acerca a un tema complejo y urgente: las nuevas violencias en Centroam\u00e9rica y el Caribe.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-de-que-hablan-julia-navarro-y-juan-jose-martinez\"><strong>\u00bfDe qu\u00e9 hablan Julia Navarro y Juan Jos\u00e9 Mart\u00ednez?<\/strong><\/h2>\n\n\n\n<p>En este episodio, Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson nos habla de las ra\u00edces hist\u00f3ricas y estructurales que explican la persistencia de la violencia en la regi\u00f3n. Tal y como se\u00f1ala, Centroam\u00e9rica y el Caribe es \u201cuna regi\u00f3n complicada, como <strong>casi todas las regiones con una historia reciente de mucha violencia y<\/strong> con una multiplicidad de actores violentos que incluyen tambi\u00e9n al Estado, que no han permitido, en muchas ocasiones, que se inicien procesos de paz\u201d.<\/p>\n\n\n\n<p>Adem\u00e1s, Juan Jos\u00e9 tambi\u00e9n habla sobre c\u00f3mo Centroam\u00e9rica est\u00e1 ante un cambio de ciclo con el <strong>\u201cfin del monopolio de las maras\u201d<\/strong>. En sus propias palabras, \u201cel narcotr\u00e1fico ha terminado metiendo animales m\u00e1s grandes que han terminado pisoteando a las pandillas\u201d, un hecho que ha sucedido en pa\u00edses como El Salvador, Honduras o Guatemala, donde han emergido nuevas organizaciones de poder, desde estructuras vinculadas al narcotr\u00e1fico hasta lo que denomina \u201cmafia de Estado\u201d.<\/p>\n\n\n\n<p>En medio de relatos duros sobre el impacto personal que ha tenido el investigar estas realidades, Juan Jos\u00e9 tambi\u00e9n comparte gestos de humanidad que sostienen la esperanza. Recuerda que la esperanza no est\u00e1 en los poderosos, sino en las sociedades organizadas: <strong>\u201cLa esperanza la encuentro, sobre todo, entre los pobres, no entre los poderosos\u201d<\/strong>. Y por \u00faltimo, junto a Julia Navarro, profundiza en la necesidad de analizar las violencias desde sus causas estructurales \u2014hist\u00f3ricas, pol\u00edticas y econ\u00f3micas\u2014 y no como fen\u00f3menos aislados o inevitables.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-que-es-voces-por-una-causa-con-julia-navarro\"><strong>\u00bfQu\u00e9 es \u2018Voces por una Causa\u2019 con Julia Navarro?<\/strong><\/h2>\n\n\n\n<p>Presentado por la escritora y periodista Julia Navarro, <a href=\"https:\/\/www.entreculturas.org\/podcast\/\"><strong>\u2018Voces por una causa\u2019<\/strong><\/a><strong> es el podcast semanal de la ONG Entreculturas<\/strong> que explora cuestiones sociales, medioambientales y culturales a trav\u00e9s de testimonios en primera persona. Los programas se emiten todos los jueves en nuestro canal de <a href=\"https:\/\/www.youtube.com\/c\/EntreculturasOrg915902672\">Youtube<\/a>, en <a href=\"https:\/\/open.spotify.com\/show\/6dS5JsqnsWrnHL1gwead1A\">Spotify<\/a>, en <a href=\"https:\/\/www.ivoox.com\/perfil-entreculturas_a8_listener_28185270_1.html\">Ivoox<\/a>, y en <a href=\"https:\/\/podcasts.apple.com\/us\/podcast\/entreculturas-voces-por-una-causa\/id1621485462\">Apple Podcast<\/a>.<\/p>\n\n\n\n<iframe data-testid=\"embed-iframe\" style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed\/episode\/0UOSPDO8asieVZhPeBknmD?utm_source=generator\" width=\"100%\" height=\"352\" frameBorder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\"><\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>Esta semana en el podcast de Voces por una Causa, la escritora Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson, salvadore\u00f1o, antrop\u00f3logo, cronista y escritor. Autor de obras como Ver, o\u00edr y callar, El ni\u00f1o de Hollywood y El que tenga miedo a morir que no nazca, su trabajo combina investigaci\u00f3n rigurosa y mirada literaria. Junto a \u00e9l, Julia Navarro nos acerca a un tema complejo y urgente: las nuevas violencias en Centroam\u00e9rica y el Caribe. \u00bfDe qu\u00e9 hablan Julia Navarro y Juan Jos\u00e9 Mart\u00ednez? En este episodio, Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson nos habla de las ra\u00edces hist\u00f3ricas y estructurales que explican la persistencia de la violencia en la regi\u00f3n. Tal y como se\u00f1ala, Centroam\u00e9rica y el Caribe es \u201cuna regi\u00f3n complicada, como casi todas las regiones con una historia reciente de mucha violencia y con una multiplicidad de actores violentos que incluyen tambi\u00e9n al Estado, que no han permitido, [&hellip;]<\/p>\n","protected":false},"featured_media":46731,"template":"","meta":{"_acf_changed":true},"categories":[],"tags":[],"class_list":["post-46729","podcast","type-podcast","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Julia Navarro habla sobre Centroam\u00e9rica con Juan Jos\u00e9 Mart\u00ednez<\/title>\n<meta name=\"description\" content=\"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson sobre las nuevas violencias en Centroam\u00e9rica y el Caribe.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez: &quot;Encuentro la esperanza sobre todo entre las personas pobres, no entre los poderosos&quot;\" \/>\n<meta property=\"og:description\" content=\"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson sobre las nuevas violencias en Centroam\u00e9rica y el Caribe.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T11:56:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/03\/Somos-e1772635189804.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/podcast\\\/julia-navarro-podcast-ong-centroamerica\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/podcast\\\/julia-navarro-podcast-ong-centroamerica\\\/\",\"name\":\"Julia Navarro habla sobre Centroam\u00e9rica con Juan Jos\u00e9 Mart\u00ednez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/podcast\\\/julia-navarro-podcast-ong-centroamerica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/podcast\\\/julia-navarro-podcast-ong-centroamerica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Somos-e1772635189804.jpg\",\"datePublished\":\"2026-03-05T07:39:00+00:00\",\"dateModified\":\"2026-03-05T11:56:39+00:00\",\"description\":\"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson sobre las nuevas violencias en Centroam\u00e9rica y el Caribe.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/podcast\\\/julia-navarro-podcast-ong-centroamerica\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/podcast\\\/julia-navarro-podcast-ong-centroamerica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/podcast\\\/julia-navarro-podcast-ong-centroamerica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Somos-e1772635189804.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Somos-e1772635189804.jpg\",\"width\":800,\"height\":457,\"caption\":\"Julia Navarro y Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/podcast\\\/julia-navarro-podcast-ong-centroamerica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast Julia Navarro\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/podcasts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez: &#8220;Encuentro la esperanza sobre todo entre las personas pobres, no entre los poderosos&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Julia Navarro habla sobre Centroam\u00e9rica con Juan Jos\u00e9 Mart\u00ednez","description":"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson sobre las nuevas violencias en Centroam\u00e9rica y el Caribe.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/","og_locale":"ca_ES","og_type":"article","og_title":"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez: \"Encuentro la esperanza sobre todo entre las personas pobres, no entre los poderosos\"","og_description":"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson sobre las nuevas violencias en Centroam\u00e9rica y el Caribe.","og_url":"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2026-03-05T11:56:39+00:00","og_image":[{"width":800,"height":457,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/03\/Somos-e1772635189804.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/","url":"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/","name":"Julia Navarro habla sobre Centroam\u00e9rica con Juan Jos\u00e9 Mart\u00ednez","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/03\/Somos-e1772635189804.jpg","datePublished":"2026-03-05T07:39:00+00:00","dateModified":"2026-03-05T11:56:39+00:00","description":"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson sobre las nuevas violencias en Centroam\u00e9rica y el Caribe.","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/03\/Somos-e1772635189804.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2026\/03\/Somos-e1772635189804.jpg","width":800,"height":457,"caption":"Julia Navarro y Juan Jos\u00e9 Mart\u00ednez d\u2019Aubuisson"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/ca\/podcast\/julia-navarro-podcast-ong-centroamerica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Podcast Julia Navarro","item":"https:\/\/www.entreculturas.org\/ca\/podcasts\/"},{"@type":"ListItem","position":3,"name":"Julia Navarro conversa con Juan Jos\u00e9 Mart\u00ednez: &#8220;Encuentro la esperanza sobre todo entre las personas pobres, no entre los poderosos&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/ca\/#website","url":"https:\/\/www.entreculturas.org\/ca\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/ca\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/ca\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.entreculturas.org\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/podcast\/46729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/types\/podcast"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/media\/46731"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/media?parent=46729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/categories?post=46729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/tags?post=46729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}