{"id":5368,"date":"2020-12-11T10:26:27","date_gmt":"2020-12-11T10:26:27","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes"},"modified":"2024-03-20T11:17:05","modified_gmt":"2024-03-20T10:17:05","slug":"participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/","title":{"rendered":"Participa en un Kahoot interescolar por el D\u00eda internacional de las personas migrantes"},"content":{"rendered":"<p>El pr\u00f3ximo 18 de diciembre te invitamos a participar junto a tu grupo a alguna de las&nbsp;diferentes sesiones de un kahoot interescolar con motivo del <strong>D\u00eda Internacional de las Personas Migrantes<\/strong>. Con ella, nos gustar\u00eda acercar la realidad de estas personas a las aulas a trav\u00e9s de este evento y a la vez ofrecer una actividad especial para cerrar el trimestre.<\/p>\n<p><strong>\u00bfTe animas a participar con tu clase?<\/strong><br \/>Podr\u00e1s elegir la franja horaria del d\u00eda 18 (pr\u00f3ximo viernes) y el idioma que te vayan mejor. Haremos sesiones de 30 minutos en castellano, euskera o ingl\u00e9s.<\/p>\n<p>En <strong>Castellano<\/strong> de 12.00 a 12.30h o de 13.30 a 14.00h.<\/p>\n<p>En<strong> Ingl\u00e9s <\/strong>de 9.30 a 10.00h o de 11.15 a 11.45h.<\/p>\n<p>En <strong>Euskera<\/strong> de 8.45 a 9.15h&nbsp;de 10.30 a 11.00h, de 12.45 a 13.15h o de 14.15 a 14.45h.<\/p>\n<p>Para inscribirte solo tienes que <strong><a href=\"https:\/\/www.jrschange.org\/es\/teachers-registration\/\">hacer click en este enlace y rellenar un breve formulario<\/a><\/strong>. Una vez finalizada la inscripci\u00f3n recibir\u00e1s un correo electr\u00f3nico con la informaci\u00f3n pr\u00e1ctica para conectarte el d\u00eda 18 y un enlace para elegir la franja horaria que m\u00e1s te convenga, el idioma, etc.<\/p>\n<p>Para realizar esta actividad <strong>nos conectaremos a trav\u00e9s de la plataforma zoom<\/strong> y desde los equipos de <a href=\"https:\/\/www.loiolaetxea.com\/\">Loiolaetxea<\/a>, el<a href=\"https:\/\/jrseurope.org\/en\/home\/\"> JRS Europa<\/a>, <a href=\"https:\/\/www.entreculturas.org\/es\/home\">Entreculturas <\/a>y <a href=\"https:\/\/www.alboan.org\/es\">Alboan<\/a> nos encargaremos de la dinamizaci\u00f3n.<\/p>\n<p>Esta propuesta se enmarca dentro del proyecto europeo <a href=\"https:\/\/www.jrschange.org\/es\/\">CHANGE<\/a> que quiere potenciar el <strong>pensamiento cr\u00edtico, la empat\u00eda y la participaci\u00f3n<\/strong> del alumnado en relaci\u00f3n a las tem\u00e1ticas de las migraciones, el refugio y la acogida. Por este motivo te queremos ofrecer la oportunidad de ampliar el trabajo sobre esta tem\u00e1tica con alguna actividad complementaria al kahoot. Recibir\u00e1s esta informaci\u00f3n tambi\u00e9n una vez realizada la inscripci\u00f3n.<\/p>\n<p>Si tienes dudas o necesit\u00e1s&nbsp;m\u00e1s informaci\u00f3n, contacta en&nbsp;y.lopez@entreculturas.org<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo 18 de diciembre te invitamos a participar junto a tu grupo a alguna de las&nbsp;diferentes sesiones de un kahoot interescolar con motivo del D\u00eda Internacional de las Personas Migrantes. Con ella, nos gustar\u00eda acercar la realidad de estas personas a las aulas a trav\u00e9s de este evento y a la vez ofrecer una actividad especial para cerrar el trimestre. \u00bfTe animas a participar con tu clase?Podr\u00e1s elegir la franja horaria del d\u00eda 18 (pr\u00f3ximo viernes) y el idioma que te vayan mejor. Haremos sesiones de 30 minutos en castellano, euskera o ingl\u00e9s. En Castellano de 12.00 a 12.30h o de 13.30 a 14.00h. En Ingl\u00e9s de 9.30 a 10.00h o de 11.15 a 11.45h. En Euskera de 8.45 a 9.15h&nbsp;de 10.30 a 11.00h, de 12.45 a 13.15h o de 14.15 a 14.45h. Para inscribirte solo tienes que hacer click en este enlace y rellenar un breve formulario. Una [&hellip;]<\/p>\n","protected":false},"featured_media":5367,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[10],"country":[],"cause":[129],"class_list":["post-5368","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-migracion-y-refugio","cause-migracion-y-refugio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Participa en un Kahoot interescolar por el D\u00eda internacional de las personas migrantes - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Participa en un Kahoot interescolar por el D\u00eda internacional de las personas migrantes\" \/>\n<meta property=\"og:description\" content=\"El pr\u00f3ximo 18 de diciembre te invitamos a participar junto a tu grupo a alguna de las&nbsp;diferentes sesiones de un kahoot interescolar con motivo del D\u00eda Internacional de las Personas Migrantes. Con ella, nos gustar\u00eda acercar la realidad de estas personas a las aulas a trav\u00e9s de este evento y a la vez ofrecer una actividad especial para cerrar el trimestre. \u00bfTe animas a participar con tu clase?Podr\u00e1s elegir la franja horaria del d\u00eda 18 (pr\u00f3ximo viernes) y el idioma que te vayan mejor. Haremos sesiones de 30 minutos en castellano, euskera o ingl\u00e9s. En Castellano de 12.00 a 12.30h o de 13.30 a 14.00h. En Ingl\u00e9s de 9.30 a 10.00h o de 11.15 a 11.45h. En Euskera de 8.45 a 9.15h&nbsp;de 10.30 a 11.00h, de 12.45 a 13.15h o de 14.15 a 14.45h. Para inscribirte solo tienes que hacer click en este enlace y rellenar un breve formulario. Una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T10:17:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/12\/cabecera_es_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\\\/\",\"name\":\"Participa en un Kahoot interescolar por el D\u00eda internacional de las personas migrantes - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/cabecera_es_2.jpg\",\"datePublished\":\"2020-12-11T10:26:27+00:00\",\"dateModified\":\"2024-03-20T10:17:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/cabecera_es_2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/cabecera_es_2.jpg\",\"width\":650,\"height\":335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Participa en un Kahoot interescolar por el D\u00eda internacional de las personas migrantes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Participa en un Kahoot interescolar por el D\u00eda internacional de las personas migrantes - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/","og_locale":"ca_ES","og_type":"article","og_title":"Participa en un Kahoot interescolar por el D\u00eda internacional de las personas migrantes","og_description":"El pr\u00f3ximo 18 de diciembre te invitamos a participar junto a tu grupo a alguna de las&nbsp;diferentes sesiones de un kahoot interescolar con motivo del D\u00eda Internacional de las Personas Migrantes. Con ella, nos gustar\u00eda acercar la realidad de estas personas a las aulas a trav\u00e9s de este evento y a la vez ofrecer una actividad especial para cerrar el trimestre. \u00bfTe animas a participar con tu clase?Podr\u00e1s elegir la franja horaria del d\u00eda 18 (pr\u00f3ximo viernes) y el idioma que te vayan mejor. Haremos sesiones de 30 minutos en castellano, euskera o ingl\u00e9s. En Castellano de 12.00 a 12.30h o de 13.30 a 14.00h. En Ingl\u00e9s de 9.30 a 10.00h o de 11.15 a 11.45h. En Euskera de 8.45 a 9.15h&nbsp;de 10.30 a 11.00h, de 12.45 a 13.15h o de 14.15 a 14.45h. Para inscribirte solo tienes que hacer click en este enlace y rellenar un breve formulario. Una [&hellip;]","og_url":"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-03-20T10:17:05+00:00","og_image":[{"width":650,"height":335,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/12\/cabecera_es_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/","url":"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/","name":"Participa en un Kahoot interescolar por el D\u00eda internacional de las personas migrantes - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/12\/cabecera_es_2.jpg","datePublished":"2020-12-11T10:26:27+00:00","dateModified":"2024-03-20T10:17:05+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/12\/cabecera_es_2.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/12\/cabecera_es_2.jpg","width":650,"height":335},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/participa-en-un-kahoot-interescolar-por-el-dia-internacional-de-las-personas-migrantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/ca\/noticias\/"},{"@type":"ListItem","position":3,"name":"Participa en un Kahoot interescolar por el D\u00eda internacional de las personas migrantes"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/ca\/#website","url":"https:\/\/www.entreculturas.org\/ca\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/ca\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/ca\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.entreculturas.org\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/noticia\/5368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/media\/5367"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/media?parent=5368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/categories?post=5368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/tags?post=5368"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/country?post=5368"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/cause?post=5368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}