{"id":4739,"date":"2020-06-01T09:41:57","date_gmt":"2020-06-01T09:41:57","guid":{"rendered":"https:\/\/entreculturasi.wpenginepowered.com\/?noticias=tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de"},"modified":"2024-03-06T18:25:11","modified_gmt":"2024-03-06T17:25:11","slug":"tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de","status":"publish","type":"noticia","link":"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/","title":{"rendered":"Tranquilidad, confianza y agradecimiento: encuentro VOLPA para sobrellevar estos tiempos de incertidumbre"},"content":{"rendered":"<p>Unas 50 personas entre VOLPA en formaci\u00f3n, formadores\/as VOLPA y coordinaciones del programa tanto de ALBOAN como de Entreculturas participamos el pasado s\u00e1bado en un encuentro virtual que, a pesar del car\u00e1cter fr\u00edo de lo online, <strong>ayud\u00f3 a mantener viva la esencia de VOLPA en estos tiempos de incertidumbre.<\/strong><\/p>\n<p>Durante el encuentro pudimos <strong>conversar sobre el estado de \u00e1nimo<\/strong> tanto personal como en su proceso VOLPA. La mayor\u00eda de los voluntarios\/as en formaci\u00f3n mantienen las ganas y la ilusi\u00f3n aunque tambi\u00e9n aparecen los miedos y las dudas al no saber qu\u00e9&nbsp;va a pasar con su proceso debido a la crisis sanitaria y social que vivimos en todo el mundo.<\/p>\n<\/p>\n<p>Los testimonios ayudaron a poner un punto de realidad y de ilusi\u00f3n para seguir caminando. Sara Diego, VOLPA de ALBOAN que tras dos meses en Leticia (Colombia), regres\u00f3 por la situaci\u00f3n de crisis transmiti\u00f3 la importancia de <strong>confiar en la instituci\u00f3n y en el proceso<\/strong>. Y Marco y Mam\u00e9n, post VOLPA tras un a\u00f1o en Ocongate (Per\u00fa) nos transmitieron la <strong>experiencia y el aprendizaje<\/strong> que el encuentro con personas de otras culturas ha supuesto para ellos.<\/p>\n<p>Adem\u00e1s dado el contexto de incertidumbre que influye de manera directa en el proceso de los VOLPA que se est\u00e1n formando en este curso 2019-2020 desde las coordinaciones del programa VOLPA de ALBOAN y Entreculturas se transmiti\u00f3 una serie de mensajes y claves para vivir este tiempo en el que todo queda abierto por ahora.<\/p>\n<p>Al final hubo un tiempo de<strong> trabajo en grupo<\/strong> para compartir las luces y las sombras que a cada persona le est\u00e1 trayendo este tiempo y un<strong> turno de preguntas <\/strong>para que pudieran expresar las dudas, miedos, interrogantes que tuvieran y as\u00ed entre todos y todas poder ayudar con las pocas certezas que se tienen a vivir este tiempo con m\u00e1s tranquilidad.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"\" src=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/volpa_valoracion_0.jpg\" width=\"680\" height=\"362\"><\/p>\n<p>La sesi\u00f3n cerr\u00f3 con una evaluaci\u00f3n en la que tantos los VOLPA en formaci\u00f3n como los formadores\/as que les acompa\u00f1an pudieron decir <strong>con qu\u00e9&nbsp;palabra o sentimiento se quedaban tras el encuentro<\/strong>. Tranquilidad, confianza, agradecimiento fueron las palabras m\u00e1s repetidas y es que nuestros voluntarios\/as vienen trabajando con sus acompa\u00f1antes desde hace meses como incorporar en su vida hoy claves que se trabajan en VOLPA para cuando est\u00e9n en su tiempo en terreno como incertidumbre o vivir desde la vulnerabilidad. Todo un aprendizaje para la vida que est\u00e1n viviendo con consciencia.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unas 50 personas entre VOLPA en formaci\u00f3n, formadores\/as VOLPA y coordinaciones del programa tanto de ALBOAN como de Entreculturas participamos el pasado s\u00e1bado en un encuentro virtual que a pesar del car\u00e1cter fr\u00edo de lo online ayud\u00f3 a mantener viva la esencia de VOLPA en estos tiempos de incertidumbre.<\/p>\n","protected":false},"featured_media":4742,"template":"single-noticia","meta":{"_acf_changed":false},"categories":[7],"tags":[8],"country":[],"cause":[132],"class_list":["post-4739","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","category-noticia","tag-participacion-y-ciudadania-global","cause-participacion-y-ciudadania-global"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tranquilidad, confianza y agradecimiento: encuentro VOLPA para sobrellevar estos tiempos de incertidumbre - Entreculturas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tranquilidad, confianza y agradecimiento: encuentro VOLPA para sobrellevar estos tiempos de incertidumbre\" \/>\n<meta property=\"og:description\" content=\"Unas 50 personas entre VOLPA en formaci\u00f3n, formadores\/as VOLPA y coordinaciones del programa tanto de ALBOAN como de Entreculturas participamos el pasado s\u00e1bado en un encuentro virtual que a pesar del car\u00e1cter fr\u00edo de lo online ayud\u00f3 a mantener viva la esencia de VOLPA en estos tiempos de incertidumbre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T17:25:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/volpa_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\\\/\",\"name\":\"Tranquilidad, confianza y agradecimiento: encuentro VOLPA para sobrellevar estos tiempos de incertidumbre - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/volpa_3.jpg\",\"datePublished\":\"2020-06-01T09:41:57+00:00\",\"dateModified\":\"2024-03-06T17:25:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/volpa_3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/volpa_3.jpg\",\"width\":800,\"height\":472,\"caption\":\"volpa_3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticia\\\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noticias\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tranquilidad, confianza y agradecimiento: encuentro VOLPA para sobrellevar estos tiempos de incertidumbre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tranquilidad, confianza y agradecimiento: encuentro VOLPA para sobrellevar estos tiempos de incertidumbre - Entreculturas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/","og_locale":"ca_ES","og_type":"article","og_title":"Tranquilidad, confianza y agradecimiento: encuentro VOLPA para sobrellevar estos tiempos de incertidumbre","og_description":"Unas 50 personas entre VOLPA en formaci\u00f3n, formadores\/as VOLPA y coordinaciones del programa tanto de ALBOAN como de Entreculturas participamos el pasado s\u00e1bado en un encuentro virtual que a pesar del car\u00e1cter fr\u00edo de lo online ayud\u00f3 a mantener viva la esencia de VOLPA en estos tiempos de incertidumbre.","og_url":"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-03-06T17:25:11+00:00","og_image":[{"width":800,"height":472,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/volpa_3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/","url":"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/","name":"Tranquilidad, confianza y agradecimiento: encuentro VOLPA para sobrellevar estos tiempos de incertidumbre - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/volpa_3.jpg","datePublished":"2020-06-01T09:41:57+00:00","dateModified":"2024-03-06T17:25:11+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/volpa_3.jpg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2020\/06\/volpa_3.jpg","width":800,"height":472,"caption":"volpa_3"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/ca\/noticia\/tranquilidad-confianza-y-agradecimiento-encuentro-volpa-para-sobrellevar-estos-tiempos-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Noticias","item":"https:\/\/www.entreculturas.org\/ca\/noticias\/"},{"@type":"ListItem","position":3,"name":"Tranquilidad, confianza y agradecimiento: encuentro VOLPA para sobrellevar estos tiempos de incertidumbre"}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/ca\/#website","url":"https:\/\/www.entreculturas.org\/ca\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/ca\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/ca\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.entreculturas.org\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/noticia\/4739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/types\/noticia"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/media\/4742"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/media?parent=4739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/categories?post=4739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/tags?post=4739"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/country?post=4739"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/cause?post=4739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}