{"id":30316,"date":"2023-08-06T11:45:46","date_gmt":"2023-08-06T09:45:46","guid":{"rendered":"https:\/\/www.entreculturas.org\/?post_type=ficha&#038;p=30316"},"modified":"2024-08-06T12:24:27","modified_gmt":"2024-08-06T10:24:27","slug":"favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo","status":"publish","type":"ficha","link":"https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/","title":{"rendered":"Favorecer la continuidad educativa y la capacidad de respuesta de la comunidad ante los nuevos retos del sistema educativo."},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Mejorar la empleabilidad y capacidades de emprendimiento de poblaciones vulnerables, especialmente mujeres, de cuatro departamentos de Bolivia, mediante la<br>implementaci\u00f3n articulada de las diversas modalidades de Educaci\u00f3n T\u00e9cnica Productiva (en adelante ETP) en el marco de un enfoque territorial.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Garantizar que 4.950 estudiantes, habitantes de 6 comunidades, ejerzan su<br \/>\nderecho a una educaci\u00f3n de calidad, adaptada a tiempos de crisis.<\/p>\n","protected":false},"featured_media":20552,"template":"","country":[322],"cause":[],"link-pdf":[625],"anio":[413],"class_list":["post-30316","ficha","type-ficha","status-publish","has-post-thumbnail","hentry","country-el-salvador","link-pdf-https-www-entreculturas-org-wp-content-uploads-2024-08-ficha-eval-20-sv-143-pdf","anio-413"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Favorecer la continuidad educativa y la capacidad de respuesta de la comunidad ante los nuevos retos del sistema educativo. - Entreculturas<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Favorecer la continuidad educativa y la capacidad de respuesta de la comunidad ante los nuevos retos del sistema educativo.\" \/>\n<meta property=\"og:description\" content=\"Garantizar que 4.950 estudiantes, habitantes de 6 comunidades, ejerzan su derecho a una educaci\u00f3n de calidad, adaptada a tiempos de crisis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/\" \/>\n<meta property=\"og:site_name\" content=\"Entreculturas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/entreculturas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-06T10:24:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png\" \/>\n\t<meta property=\"og:image:width\" content=\"585\" \/>\n\t<meta property=\"og:image:height\" content=\"699\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Entreculturas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/ficha\\\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/ficha\\\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\\\/\",\"name\":\"Favorecer la continuidad educativa y la capacidad de respuesta de la comunidad ante los nuevos retos del sistema educativo. - Entreculturas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/ficha\\\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/ficha\\\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/placeholder04.png\",\"datePublished\":\"2023-08-06T09:45:46+00:00\",\"dateModified\":\"2024-08-06T10:24:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/ficha\\\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/ficha\\\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/ficha\\\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/placeholder04.png\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/placeholder04.png\",\"width\":585,\"height\":699,\"caption\":\"corazon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/ficha\\\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Favorecer la continuidad educativa y la capacidad de respuesta de la comunidad ante los nuevos retos del sistema educativo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\",\"name\":\"Entreculturas\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#organization\"},\"alternateName\":\"Entreculturas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#organization\",\"name\":\"Entreculturas\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"contentUrl\":\"https:\\\/\\\/www.entreculturas.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/ESP.svg\",\"caption\":\"Entreculturas\"},\"image\":{\"@id\":\"https:\\\/\\\/www.entreculturas.org\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/entreculturas\",\"https:\\\/\\\/x.com\\\/Entreculturas\",\"https:\\\/\\\/www.instagram.com\\\/entreculturas\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/entreculturasvideo\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundacion-entreculturas-ngdo\\\/\",\"https:\\\/\\\/www.flickr.com\\\/photos\\\/98455522@N04\\\/albums\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Favorecer la continuidad educativa y la capacidad de respuesta de la comunidad ante los nuevos retos del sistema educativo. - Entreculturas","robots":{"index":"noindex","follow":"follow"},"og_locale":"ca_ES","og_type":"article","og_title":"Favorecer la continuidad educativa y la capacidad de respuesta de la comunidad ante los nuevos retos del sistema educativo.","og_description":"Garantizar que 4.950 estudiantes, habitantes de 6 comunidades, ejerzan su derecho a una educaci\u00f3n de calidad, adaptada a tiempos de crisis.","og_url":"https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/","og_site_name":"Entreculturas","article_publisher":"https:\/\/www.facebook.com\/entreculturas","article_modified_time":"2024-08-06T10:24:27+00:00","og_image":[{"width":585,"height":699,"url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Entreculturas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/","url":"https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/","name":"Favorecer la continuidad educativa y la capacidad de respuesta de la comunidad ante los nuevos retos del sistema educativo. - Entreculturas","isPartOf":{"@id":"https:\/\/www.entreculturas.org\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/#primaryimage"},"image":{"@id":"https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","datePublished":"2023-08-06T09:45:46+00:00","dateModified":"2024-08-06T10:24:27+00:00","breadcrumb":{"@id":"https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/#primaryimage","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2024\/02\/placeholder04.png","width":585,"height":699,"caption":"corazon"},{"@type":"BreadcrumbList","@id":"https:\/\/www.entreculturas.org\/ca\/ficha\/favorecer-la-continuidad-educativa-y-la-capacidad-de-respuesta-de-la-comunidad-ante-los-nuevos-retos-del-sistema-educativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.entreculturas.org\/ca\/"},{"@type":"ListItem","position":2,"name":"Favorecer la continuidad educativa y la capacidad de respuesta de la comunidad ante los nuevos retos del sistema educativo."}]},{"@type":"WebSite","@id":"https:\/\/www.entreculturas.org\/ca\/#website","url":"https:\/\/www.entreculturas.org\/ca\/","name":"Entreculturas","description":"","publisher":{"@id":"https:\/\/www.entreculturas.org\/ca\/#organization"},"alternateName":"Entreculturas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.entreculturas.org\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.entreculturas.org\/ca\/#organization","name":"Entreculturas","url":"https:\/\/www.entreculturas.org\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.entreculturas.org\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","contentUrl":"https:\/\/www.entreculturas.org\/wp-content\/uploads\/2025\/10\/ESP.svg","caption":"Entreculturas"},"image":{"@id":"https:\/\/www.entreculturas.org\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/entreculturas","https:\/\/x.com\/Entreculturas","https:\/\/www.instagram.com\/entreculturas\/","https:\/\/www.youtube.com\/user\/entreculturasvideo","https:\/\/www.linkedin.com\/company\/fundacion-entreculturas-ngdo\/","https:\/\/www.flickr.com\/photos\/98455522@N04\/albums\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/ficha\/30316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/ficha"}],"about":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/types\/ficha"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/media\/20552"}],"wp:attachment":[{"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/media?parent=30316"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/country?post=30316"},{"taxonomy":"cause","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/cause?post=30316"},{"taxonomy":"link-pdf","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/link-pdf?post=30316"},{"taxonomy":"anio","embeddable":true,"href":"https:\/\/www.entreculturas.org\/ca\/wp-json\/wp\/v2\/anio?post=30316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}